{"id":7996,"date":"2026-03-11T19:50:05","date_gmt":"2026-03-12T00:50:05","guid":{"rendered":"https:\/\/devocionario.net\/?p=7996"},"modified":"2026-03-11T19:50:09","modified_gmt":"2026-03-12T00:50:09","slug":"jueves-tercera-semana-de-cuaresma-12-de-marzo-de-2026-ciclo-a","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2026\/03\/11\/jueves-tercera-semana-de-cuaresma-12-de-marzo-de-2026-ciclo-a\/","title":{"rendered":"JUEVES, Tercera Semana de Cuaresma, 12 de marzo de 2026 (Ciclo a)"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2026\/03\/19661338-women-5963963_1920-1024x683.jpg\" alt=\"\" class=\"wp-image-7997\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2026\/03\/19661338-women-5963963_1920-1024x683.jpg 1024w, https:\/\/devocionario.net\/wp-content\/uploads\/2026\/03\/19661338-women-5963963_1920-300x200.jpg 300w, https:\/\/devocionario.net\/wp-content\/uploads\/2026\/03\/19661338-women-5963963_1920-768x512.jpg 768w, https:\/\/devocionario.net\/wp-content\/uploads\/2026\/03\/19661338-women-5963963_1920-1536x1024.jpg 1536w, https:\/\/devocionario.net\/wp-content\/uploads\/2026\/03\/19661338-women-5963963_1920.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-ast-global-color-2-color has-cyan-bluish-gray-background-color has-text-color has-background has-link-color wp-elements-25ee312c0bed3752ec28d8d519b718ac\"><strong>SAN lUIGI ORIONE (1872-1940)<\/strong><\/p>\n\n\n\n<p>San Luis Orione naci\u00f3 en Pontecurone (di\u00f3cesis de Tortona), cuando era muy joven ingres\u00f3 al convento franciscano de Voghera (Pav\u00eda), pero a\u00f1os m\u00e1s tarde abandon\u00f3 el convento por quebrantos de salud, fue alumno de San Juan Bosco en el Oratorio de Valdocco (Tur\u00edn). Tiempo despu\u00e9s entro en el seminario de Tortona, estando all\u00ed abri\u00f3 un Oratorio para cuidar la educaci\u00f3n cristiana de los j\u00f3venes, as\u00ed como tambi\u00e9n abri\u00f3 un colegio para chicos pobres en el barrio San Bernardino, despu\u00e9s de ordenado sacerdote abre nuevas casas en Mornico Losana (Pav\u00eda), en Noto (Sicilia), en Sanremo, en Roma. Con el Santo crecieron cl\u00e9rigos y sacerdotes que formaron el primer n\u00facleo de la Peque\u00f1a Obra de la Divina Providencia, inici\u00f3 la rama de los ermita\u00f1os de la Divina Providencia y el Obispo de Tortona, reconoci\u00f3 can\u00f3nicamente a los Hijos de la Divina Providencia, dedicada a \u00abcolaborar para llevar a los peque\u00f1os, los pobres y el pueblo a la Iglesia y al Papa, mediante las obras de caridad\u00bb, los fines de la nueva Congregaci\u00f3n aparece el de trabajar \u00abpara alcanzar la uni\u00f3n de las Iglesias separadas\u00bb. Ayud\u00f3 a los damnificadas por los terremotos de Reggio y de Messina y por el de la Marsica. Inicio a la Congregaci\u00f3n de las Peque\u00f1as Hermanas Misioneras de la Caridad, y las Hermanas adoratrices Sacramentinas invidentes, a las que se a\u00f1adir\u00e1n despu\u00e9s las Contemplativas de Jes\u00fas Crucificado. Organiz\u00f3 a los laicos como \u00abDamas de la Divina Providencia\u00bb, los \u00abEx Alumnos\u00bb y los \u00abAmigos\u00bb, a\u00f1os m\u00e1s tarde tomo el nombre de el Instituto Secular Orionino y el Movimiento Laical Orionino y as\u00ed y otras obras m\u00e1s realiz\u00f3 el santo, adem\u00e1s fue un gran confesor, el Papa confiaba asuntos dif\u00edciles de solucionar, sus problemas de coraz\u00f3n y pulmones no le permitieron vivir m\u00e1s muere rodeado de quienes tanto hab\u00eda servido.<br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Lucas 11,14-23<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, estaba Jes\u00fas echando un demonio que era mudo.<\/p>\n\n\n\n<p>Sucedi\u00f3 que, apenas sali\u00f3 el demonio, empez\u00f3 a hablar el mudo. La multitud se qued\u00f3 admirada, pero algunos de ellos dijeron:<br>\u00abPor arte de Belzeb\u00fa, el pr\u00edncipe de los demonios, echa los demonios\u00bb.<\/p>\n\n\n\n<p>Otros, para ponerlo a prueba, le ped\u00edan un signo del cielo. \u00c9l, conociendo sus pensamientos, les dijo:<br>\u00abTodo reino dividido contra s\u00ed mismo va a la ruina y cae casa sobre casa. Si, pues, tambi\u00e9n Satan\u00e1s se ha dividido contra s\u00ed mismo, \u00bfc\u00f3mo se mantendr\u00e1 su reino? Pues vosotros dec\u00eds que yo echo los demonios con el poder de Belzeb\u00fa. Pero, si yo echo los demonios con el poder de Belzeb\u00fa, vuestros hijos, \u00bfpor arte de qui\u00e9n los echan? Por eso, ellos mismos ser\u00e1n vuestros jueces. Pero, si yo echo los demonios con el dedo de Dios, entonces es que el reino de Dios ha llegado a vosotros.<\/p>\n\n\n\n<p>Cuando un hombre fuerte y bien armado guarda su palacio, sus bienes est\u00e1n seguros, pero, cuando otro m\u00e1s fuerte lo asalta y lo vence, le quita las armas de que se fiaba y reparte su bot\u00edn.<\/p>\n\n\n\n<p>El que no est\u00e1 conmigo est\u00e1 contra m\u00ed; el que no recoge conmigo desparrama\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-ast-global-color-5-color has-vivid-purple-background-color has-text-color has-background has-link-color wp-elements-eb11d1f165d5a98c162aac55a541ffb7\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00bfCrees en el poder de Jesucristo para vencer el mal? en ocasiones dudamos del poder mesi\u00e1nico del Maestro, vivimos con pensamientos malintencionados y dejamos a un lado la fe en qui\u00e9n es due\u00f1o de la vida y quien es capaz de librarnos del mal, pues \u00c9l conociendo las artima\u00f1as del adversario tiene tambi\u00e9n la fuerza de combatirlo, el maligno puede suscitar en nosotros desconfianza y hasta incredulidad para hacernos caer en el error.<\/li>\n\n\n\n<li>En la actualidad muchos suelen creer que no existe el demonio, que es una leyenda, una fantas\u00eda, incluso muchos caen en la desfachatez de ir a combatir el mal a base de magia negra, de lectura de cartas, de adivinaci\u00f3n, enga\u00f1\u00e1ndose de que el enemigo combatir\u00e1 contra el mismo, y como Jes\u00fas no lo dice en el evangelio como puede un reino estar dividido contra si mismo.<\/li>\n\n\n\n<li>Adem\u00e1s Jesucristo nos hace una advertencia, de no ser presumidos, debemos estar alertas en no dejarnos arrastrar por el mal, o creernos inmunes a \u00e9l, ya satan\u00e1s esta derrotado y Cristo venci\u00f3 con su muerte, pero no debemos confiarnos, m\u00e1s bien debemos contribuir a expandir el reino de Dios que ha llegado a nosotros para quedarse hasta el fin de los tiempos. \u00a1vence el mal con el bien!<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cuando reces el Padre Nuestro ten fe cuando digas: &#8220;y LIBRANOS DEL MAL&#8221;<\/li>\n\n\n\n<li>San Luigi Orione nos ense\u00f1a que los pilares fundamentales de la verdad son la caridad u la misericordia con los m\u00e1s necesitados.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN lUIGI ORIONE (1872-1940) San Luis Orione naci\u00f3 en Pontecurone (di\u00f3cesis de Tortona), cuando era muy joven ingres\u00f3 al convento franciscano de Voghera (Pav\u00eda), pero a\u00f1os m\u00e1s tarde abandon\u00f3 el convento por quebrantos de salud, fue alumno de San Juan Bosco en el Oratorio de Valdocco (Tur\u00edn). Tiempo despu\u00e9s entro en el &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2026\/03\/11\/jueves-tercera-semana-de-cuaresma-12-de-marzo-de-2026-ciclo-a\/\"> <span class=\"screen-reader-text\">JUEVES, Tercera Semana de Cuaresma, 12 de marzo de 2026 (Ciclo a)<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":7997,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-7996","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tiempo-cuaresma"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2026\/03\/19661338-women-5963963_1920.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/03\/19661338-women-5963963_1920.jpg",1920,1280,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/03\/19661338-women-5963963_1920-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/03\/19661338-women-5963963_1920-300x200.jpg",300,200,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/03\/19661338-women-5963963_1920-768x512.jpg",768,512,true],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/03\/19661338-women-5963963_1920-1024x683.jpg",1024,683,true],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/03\/19661338-women-5963963_1920-1536x1024.jpg",1536,1024,true],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/03\/19661338-women-5963963_1920.jpg",1920,1280,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SAN lUIGI ORIONE (1872-1940) San Luis Orione naci\u00f3 en Pontecurone (di\u00f3cesis de Tortona), cuando era muy joven ingres\u00f3 al convento franciscano de Voghera (Pav\u00eda), pero a\u00f1os m\u00e1s tarde abandon\u00f3 el convento por quebrantos de salud, fue alumno de San Juan Bosco en el Oratorio de Valdocco (Tur\u00edn). Tiempo despu\u00e9s entro en el&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/7996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=7996"}],"version-history":[{"count":2,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/7996\/revisions"}],"predecessor-version":[{"id":7999,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/7996\/revisions\/7999"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/7997"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=7996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=7996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=7996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}