{"id":7951,"date":"2026-03-01T19:44:22","date_gmt":"2026-03-02T00:44:22","guid":{"rendered":"https:\/\/devocionario.net\/?p=7951"},"modified":"2026-03-01T19:44:25","modified_gmt":"2026-03-02T00:44:25","slug":"lunes-segunda-semana-de-cuaresma-02-de-marzo-de-2026-ciclo-a","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2026\/03\/01\/lunes-segunda-semana-de-cuaresma-02-de-marzo-de-2026-ciclo-a\/","title":{"rendered":"LUNES, Segunda Semana de Cuaresma, 02 de marzo de 2026 (Ciclo a)"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"480\" height=\"640\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2026\/03\/2-de-marzo.jpg\" alt=\"\" class=\"wp-image-7954\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2026\/03\/2-de-marzo.jpg 480w, https:\/\/devocionario.net\/wp-content\/uploads\/2026\/03\/2-de-marzo-225x300.jpg 225w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-ast-global-color-2-color has-cyan-bluish-gray-background-color has-text-color has-background has-link-color wp-elements-89e06e88fc6ecc0d422c9444f6120fc2\"><strong>SAN SIMPLICIO (+483)<\/strong><\/p>\n\n\n\n<p>San Simplicio fue hijo de un ciudadano de T\u00edvoli llamado Castino; sucede al Papa Hilario su pontificado dur\u00f3 quince a\u00f1os y en \u00e9l el imperio de Occidente lleg\u00f3 a su fin estando \u00e9l como Papa, defendi\u00f3 la Iglesia del cesaropapismo (t\u00e9rmino referido a las relaciones entre Iglesia y Estado, que identifica o supone la unificaci\u00f3n en una sola persona, normalmente el emperador, \u200b\u200b con el poder pol\u00edtico y poder religioso) de los gobernantes bizantinos. Public\u00f3 decisiones sobre cuestiones eclesi\u00e1sticas, nombr\u00f3 al obispo Zen\u00f3n de Sevilla vicario papal en Espa\u00f1a, de forma que las prerrogativas de la sede papal pudieran ejercerse en el propio pa\u00eds para beneficio de la administraci\u00f3n eclesi\u00e1stica. Simplicio fund\u00f3 cuatro iglesias nuevas en la propia Roma.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Lucas 6, 36-38<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, dijo Jes\u00fas a sus disc\u00edpulos: \u00abSed misericordiosos como vuestro Padre es misericordioso; no juzgu\u00e9is, y no ser\u00e9is juzgados; no conden\u00e9is, y no ser\u00e9is condenados; perdonad, y ser\u00e9is perdonados; dad, y se os dar\u00e1: os verter\u00e1n una medida generosa, colmada, remecida, rebosante, pues con la medida con que midiereis se os medir\u00e1 a vosotros\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-ast-global-color-5-color has-vivid-purple-background-color has-text-color has-background has-link-color wp-elements-eb11d1f165d5a98c162aac55a541ffb7\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00bfAlguna vez has recibido una segunda oportunidad de parte de Dios?, creer\u00eda que todos, en alg\u00fan momento de nuestra existencia hemos sentido la misericordia y compasi\u00f3n de Dios, que se manifiesta incluso si hemos pecado, pero el Evangelio hoy nos invita no solo a recibir esta misericordia, sino que nos llama a ponerla en pr\u00e1ctica con aquellos que est\u00e1n en una situaci\u00f3n de vulnerabilidad. Este acto nos ense\u00f1a a mirar el mundo con el coraz\u00f3n, a mirar las miserias con compasi\u00f3n, a entender que debemos perdonar siempre a cualquier persona, pues est\u00e1 puede llevar una carga que solo Dios ve.<\/li>\n\n\n\n<li>Debemos conocer el peligro al que nos exponemos cuando juzgamos, cuando condenamos, pues no podemos hacer juicios a nadie, pues tambi\u00e9n tenemos pecados que ser\u00e1n juzgados por Dios, nuestra actitud con quien falla es de compasi\u00f3n y empat\u00eda, sabiendo que todos en alguna circunstancia podemos caer.<\/li>\n\n\n\n<li>De alguna manera cada gesto que tengamos con nuestros hermanos vendr\u00e1 a nosotros como un principio reciproco, todo lo que haga con los dem\u00e1s vendr\u00e1 a mi en diferentes formas, es por eso que medir a alguien a nuestro antojo, no es cristiano, debemos tener cuidado todo absolutamente todo se devuelve, y m\u00e1s si act\u00faas con maldad.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dejar a un lado la murmuraci\u00f3n de vidas ajenas, evadir el tema a quien quiera desviarme de la misericordia y el amor que Dios me profesa.<\/li>\n\n\n\n<li>San Simplicio hizo grandes obras y desarrollo espiritual a nuestra Iglesia Cat\u00f3lica, como \u00e9l dejemos huellas pero sin pisar a nadie.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN SIMPLICIO (+483) San Simplicio fue hijo de un ciudadano de T\u00edvoli llamado Castino; sucede al Papa Hilario su pontificado dur\u00f3 quince a\u00f1os y en \u00e9l el imperio de Occidente lleg\u00f3 a su fin estando \u00e9l como Papa, defendi\u00f3 la Iglesia del cesaropapismo (t\u00e9rmino referido a las relaciones entre Iglesia y Estado, &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2026\/03\/01\/lunes-segunda-semana-de-cuaresma-02-de-marzo-de-2026-ciclo-a\/\"> <span class=\"screen-reader-text\">LUNES, Segunda Semana de Cuaresma, 02 de marzo de 2026 (Ciclo a)<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":7954,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-7951","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tiempo-cuaresma"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2026\/03\/2-de-marzo.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/03\/2-de-marzo.jpg",480,640,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/03\/2-de-marzo-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/03\/2-de-marzo-225x300.jpg",225,300,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/03\/2-de-marzo.jpg",480,640,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/03\/2-de-marzo.jpg",480,640,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/03\/2-de-marzo.jpg",480,640,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/03\/2-de-marzo.jpg",480,640,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SAN SIMPLICIO (+483) San Simplicio fue hijo de un ciudadano de T\u00edvoli llamado Castino; sucede al Papa Hilario su pontificado dur\u00f3 quince a\u00f1os y en \u00e9l el imperio de Occidente lleg\u00f3 a su fin estando \u00e9l como Papa, defendi\u00f3 la Iglesia del cesaropapismo (t\u00e9rmino referido a las relaciones entre Iglesia y Estado,&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/7951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=7951"}],"version-history":[{"count":2,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/7951\/revisions"}],"predecessor-version":[{"id":7955,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/7951\/revisions\/7955"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/7954"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=7951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=7951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=7951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}