{"id":7786,"date":"2026-02-03T21:36:08","date_gmt":"2026-02-04T02:36:08","guid":{"rendered":"https:\/\/devocionario.net\/?p=7786"},"modified":"2026-02-03T21:36:11","modified_gmt":"2026-02-04T02:36:11","slug":"miercoles-cuarta-semana-del-tiempo-ordinario-04-de-febrero-de-2026-ciclo-a","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2026\/02\/03\/miercoles-cuarta-semana-del-tiempo-ordinario-04-de-febrero-de-2026-ciclo-a\/","title":{"rendered":"MIERCOLES, Cuarta Semana del Tiempo Ordinario, 04 de febrero de 2026 (Ciclo a)"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"685\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2026\/02\/dormeur74-carpenter-4015109_1920-1024x685.jpg\" alt=\"\" class=\"wp-image-7787\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2026\/02\/dormeur74-carpenter-4015109_1920-1024x685.jpg 1024w, https:\/\/devocionario.net\/wp-content\/uploads\/2026\/02\/dormeur74-carpenter-4015109_1920-300x201.jpg 300w, https:\/\/devocionario.net\/wp-content\/uploads\/2026\/02\/dormeur74-carpenter-4015109_1920-768x514.jpg 768w, https:\/\/devocionario.net\/wp-content\/uploads\/2026\/02\/dormeur74-carpenter-4015109_1920-1536x1028.jpg 1536w, https:\/\/devocionario.net\/wp-content\/uploads\/2026\/02\/dormeur74-carpenter-4015109_1920.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-ast-global-color-2-color has-cyan-bluish-gray-background-color has-text-color has-background has-link-color wp-elements-4fe00e9999a3acba9918a4abda355af1\"><strong>SAN JOSE DE LEONESSA (1556-1612)<\/strong><\/p>\n\n\n\n<p>San Jos\u00e9 naci\u00f3 en Leonessa (Umbr\u00eda, Italia), fue un fraile capuchino muy amable, humilde, se mortificaba, y com\u00eda pan y agua por tres d\u00edas seguidos, siempre se le ve\u00eda predicar con un crucifijo en la mano, fue enviado como misionero a Turqu\u00eda, ah\u00ed animaba a los esclavos ense\u00f1\u00e1ndoles el amor a Jesucristo, por ese entonces se presentaba una peste en aquel lugar, fue contagiado pero recobro pronto la salud, tambi\u00e9n convirti\u00f3 muchos herejes y predic\u00f3 a los musulmanes exponi\u00e9ndose a la ley de Turqu\u00eda, dos veces fue preso, y luego condenado a muerte por anunciar la fe en Jes\u00fas, fue torturado por horas y puesto en una horca, fue desterrado, se dirige a Venecia, y entonces decide regresar a Leonessa, para retomar sus labores pastorales, pero un tumor le da mucho sufrimiento, lo operan dos veces pero a la tercera no soport\u00f3 y muere de cincuenta y ocho a\u00f1os felizmente habiendo cumplido su misi\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Marcos 6, 1-6<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, Jes\u00fas se dirigi\u00f3 a su ciudad y lo segu\u00edan sus disc\u00edpulos.<\/p>\n\n\n\n<p>Cuando lleg\u00f3 el s\u00e1bado, empez\u00f3 a ense\u00f1ar en la sinagoga; la multitud que lo o\u00eda se preguntaba asombrada:<br>\u00ab\u00bfDe d\u00f3nde saca todo eso? \u00bfQu\u00e9 sabidur\u00eda es esa que le ha sido dada? \u00bfY esos milagros que realizan sus manos? \u00bfNo es este el carpintero, el hijo de Mar\u00eda, hermano de Santiago y Jos\u00e9 y Judas y Sim\u00f3n? Y sus hermanas \u00bfno viven con nosotros aqu\u00ed?\u00bb.<\/p>\n\n\n\n<p>Y se escandalizaban a cuenta de \u00e9l.<\/p>\n\n\n\n<p>Les dec\u00eda:<br>\u00abNo desprecian a un profeta m\u00e1s que en su tierra, entre sus parientes y en su casa\u00bb.<\/p>\n\n\n\n<p>No pudo hacer all\u00ed ning\u00fan milagro, solo cur\u00f3 algunos enfermos imponi\u00e9ndoles las manos. Y se admiraba de su falta de fe.<\/p>\n\n\n\n<p>Y recorr\u00eda los pueblos de alrededor ense\u00f1ando.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-ast-global-color-2-color has-vivid-green-cyan-background-color has-text-color has-background has-link-color wp-elements-0c192cd5e76cac3988c4c9fb3045ec50\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Muchos misioneros pasan por la situaci\u00f3n de Jes\u00fas en el anunci\u00f3 de la Buena Nueva, cada d\u00eda son m\u00e1s las personas que ignoran que Dios escoja hombres y mujeres comunes, los mismos que se desarrollan en nuestro mismo ambiente para anunciar su mensaje salv\u00edfico, dudamos de las capacidades que el otro tiene, y rechazamos oportunidades de cambio para nuestra vida. La vida del hombre a lo largo de los a\u00f1os a utilizado su lenguaje para denigrar , para despellejar la reputaci\u00f3n de quienes quieren ayudar, mejorar, avanzar, y solo porque ve sus debilidades en ellos. Quienes han dedicado su vida a la evangelizaci\u00f3n est\u00e1n expuestos y condenados a ser odiados por el mundo,<em> &#8220;si el mundo los odia, recuerden que a m\u00ed me odi\u00f3 primero&#8221; <strong>Juan 15, 18.<\/strong><\/em><\/li>\n\n\n\n<li>Jes\u00fas nos invita a anunciarle con nuestro testimonio de vida, pues quienes quieran entrar en el camino de la luz reconocer\u00e1n que somos de Cristo y nuestra forma de vivir define quien habita en nuestro interior, el mismo Dios. Muchas veces nos proponemos encajar en una sociedad que solo desobedece a Jesucristo, para caerle bien a todos los de mi circulo social cometemos pecados que van en contra de los mandatos de Dios, recordemos que si seguimos los pasos de Jes\u00fas nuestra vida estar\u00e1 llena de criticas, burlas, se\u00f1alamientos, etc, que nos desanimar\u00e1n pero teniendo nuestra fe firme, ser\u00e1 imposible desfallecer.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Orar por los misioneros de mi comunidad, alentarlos y motivarlos a seguir anunciand<strong>o a Jesucristo.<\/strong><\/li>\n\n\n\n<li>San Jos\u00e9 de Leonessa nos pide perseverar en Dios.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN JOSE DE LEONESSA (1556-1612) San Jos\u00e9 naci\u00f3 en Leonessa (Umbr\u00eda, Italia), fue un fraile capuchino muy amable, humilde, se mortificaba, y com\u00eda pan y agua por tres d\u00edas seguidos, siempre se le ve\u00eda predicar con un crucifijo en la mano, fue enviado como misionero a Turqu\u00eda, ah\u00ed animaba a los esclavos &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2026\/02\/03\/miercoles-cuarta-semana-del-tiempo-ordinario-04-de-febrero-de-2026-ciclo-a\/\"> <span class=\"screen-reader-text\">MIERCOLES, Cuarta Semana del Tiempo Ordinario, 04 de febrero de 2026 (Ciclo a)<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":7787,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-7786","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tiempo-ordinario"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2026\/02\/dormeur74-carpenter-4015109_1920.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/02\/dormeur74-carpenter-4015109_1920.jpg",1920,1285,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/02\/dormeur74-carpenter-4015109_1920-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/02\/dormeur74-carpenter-4015109_1920-300x201.jpg",300,201,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/02\/dormeur74-carpenter-4015109_1920-768x514.jpg",768,514,true],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/02\/dormeur74-carpenter-4015109_1920-1024x685.jpg",1024,685,true],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/02\/dormeur74-carpenter-4015109_1920-1536x1028.jpg",1536,1028,true],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/02\/dormeur74-carpenter-4015109_1920.jpg",1920,1285,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SAN JOSE DE LEONESSA (1556-1612) San Jos\u00e9 naci\u00f3 en Leonessa (Umbr\u00eda, Italia), fue un fraile capuchino muy amable, humilde, se mortificaba, y com\u00eda pan y agua por tres d\u00edas seguidos, siempre se le ve\u00eda predicar con un crucifijo en la mano, fue enviado como misionero a Turqu\u00eda, ah\u00ed animaba a los esclavos&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/7786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=7786"}],"version-history":[{"count":2,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/7786\/revisions"}],"predecessor-version":[{"id":7789,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/7786\/revisions\/7789"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/7787"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=7786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=7786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=7786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}