{"id":7594,"date":"2026-01-02T14:34:56","date_gmt":"2026-01-02T19:34:56","guid":{"rendered":"https:\/\/devocionario.net\/?p=7594"},"modified":"2026-01-02T14:34:59","modified_gmt":"2026-01-02T19:34:59","slug":"sabado-octava-de-navidad-03-de-enero-ciclo-a","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2026\/01\/02\/sabado-octava-de-navidad-03-de-enero-ciclo-a\/","title":{"rendered":"SABADO ,OCTAVA DE NAVIDAD, 03 de Enero (ciclo A)"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2026\/01\/lamb-292512_1920-1024x683.jpg\" alt=\"\" class=\"wp-image-7595\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2026\/01\/lamb-292512_1920-1024x683.jpg 1024w, https:\/\/devocionario.net\/wp-content\/uploads\/2026\/01\/lamb-292512_1920-300x200.jpg 300w, https:\/\/devocionario.net\/wp-content\/uploads\/2026\/01\/lamb-292512_1920-768x512.jpg 768w, https:\/\/devocionario.net\/wp-content\/uploads\/2026\/01\/lamb-292512_1920-1536x1024.jpg 1536w, https:\/\/devocionario.net\/wp-content\/uploads\/2026\/01\/lamb-292512_1920.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-ast-global-color-2-color has-text-color has-link-color wp-elements-bad2cde9e057d6e92a0470e04bd1a9c3\"><strong>SANTISIMO NOMBRE DE JES\u00daS (Siglo XIV)<\/strong><\/p>\n\n\n\n<p>Hoy en la Iglesia cat\u00f3lica se celebra el sant\u00edsimo Nombre del Se\u00f1or, San Bernardino de Siena y San Juan Capistrano, fueron dos santos que patrocinaron esta celebraci\u00f3n, en sus misiones llevaron una copia del monograma del Sant\u00edsimo Nombre que comprend\u00eda de las dos iniciales del nombre de Jes\u00fas pintado en una madera de donde sal\u00edan rayos , lo trajeron a las ciudades de Italia para bendecir a las gentes especialmente a los enfermos, en sus sermones ped\u00edan a todos arrodillarse ante este emblema y tenerlo en las puertas de sus casas, tiempo despu\u00e9s San Bernardino fue acusado por promulgar esta devoci\u00f3n, pero San Capistrano fue testigo del santo para que le dejar\u00e1n salir, con esta piadosa devoci\u00f3n muchos Papas concedieron indulgencias para los fieles que pronunciar\u00e1n el nombre del Se\u00f1or.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Juan 1, 29-34<\/strong><\/p>\n\n\n\n<p>Al d\u00eda siguiente, al ver Juan a Jes\u00fas que ven\u00eda hacia \u00e9l, exclam\u00f3:<br>\u00abEste es el Cordero de Dios, que quita el pecado del mundo. Este es aquel de quien yo dijo: \u201cTras de m\u00ed viene un hombre que est\u00e1 por delante de m\u00ed, porque exist\u00eda antes que yo\u201d. Yo no lo conoc\u00eda, pero he salido a bautizar con agua, para que sea manifestado a Israel\u00bb.<\/p>\n\n\n\n<p>Y Juan dio testimonio diciendo:<br>\u00abHe contemplado al Esp\u00edritu que bajaba del cielo como una paloma, y se pos\u00f3 sobre \u00e9l. Yo no lo conoc\u00eda, pero el que me envi\u00f3 a bautizar con agua me dijo: \u201cAquel sobre quien veas bajar el Esp\u00edritu y posarse sobre \u00e9l, ese es el que bautiza con Esp\u00edritu Santo\u201d.<\/p>\n\n\n\n<p>Y yo lo he visto y he dado testimonio de que este es el Hijo de Dios\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-ast-global-color-5-color has-ast-global-color-0-background-color has-text-color has-background has-link-color wp-elements-1fe700d43fe5008d1b891f44ab770442\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00bfReconocemos a Jes\u00fas que nos quiere salvar?, cuando comenzamos a ser testigos de la luz que es Cristo difundimos su mensaje de amor y somos participes de su sacrificio perfecto, estamos permitiendo la presencia del Cordero de Dios que quita toda mancha de pecado, como Juan debemos decir en cada celebraci\u00f3n es Jes\u00fas el Cordero de Dios que tiene piedad de nosotros y nos da la paz, debemos estar convencidos de que el plan divino trazado por Dios tambi\u00e9n nos alcanza a nosotros y de generaci\u00f3n en generaci\u00f3n.<\/li>\n\n\n\n<li>Juan no se cansaba de hablar de Jes\u00fas, como \u00e9l busquemos que Jes\u00fas Nuestro Se\u00f1or sea el centro de nuestras vidas, que toda nuestra atenci\u00f3n vaya hacia \u00e9l, no busquemos ser nosotros protagonistas, dejemos que sea Jesucristo el rey de tu vida y de la m\u00eda, seamos mansos como el Cordero de Dios que se don\u00f3 por amor, siendo Dios y teniendo poder permiti\u00f3 que Juan le bautizar\u00e1, siendo Dios se anonado y se sacrifico por nuestra salvaci\u00f3n. \u00bf Todo lo que hacemos en nuestra vida tiene como referencia a Jes\u00fas?<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Elaborar en una tabla de madera donde vaya escrito el nombre de Jes\u00fas y colocarlo en la puerta de tu casa como recuerdo de la piedad impartida por San Bernardino y San Capistrano.<\/li>\n\n\n\n<li>Jes\u00fas significa: &#8220;Dios salva&#8221;, pronunciemos este nombre del Se\u00f1or en lo m\u00e1s profundo de nuestro ser y permitamos que se materialice en nuestras vidas.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SANTISIMO NOMBRE DE JES\u00daS (Siglo XIV) Hoy en la Iglesia cat\u00f3lica se celebra el sant\u00edsimo Nombre del Se\u00f1or, San Bernardino de Siena y San Juan Capistrano, fueron dos santos que patrocinaron esta celebraci\u00f3n, en sus misiones llevaron una copia del monograma del Sant\u00edsimo Nombre que comprend\u00eda de las dos iniciales del nombre &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2026\/01\/02\/sabado-octava-de-navidad-03-de-enero-ciclo-a\/\"> <span class=\"screen-reader-text\">SABADO ,OCTAVA DE NAVIDAD, 03 de Enero (ciclo A)<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":7595,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-7594","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-octava-de-navidad"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2026\/01\/lamb-292512_1920.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/01\/lamb-292512_1920.jpg",1920,1280,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/01\/lamb-292512_1920-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/01\/lamb-292512_1920-300x200.jpg",300,200,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/01\/lamb-292512_1920-768x512.jpg",768,512,true],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/01\/lamb-292512_1920-1024x683.jpg",1024,683,true],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/01\/lamb-292512_1920-1536x1024.jpg",1536,1024,true],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2026\/01\/lamb-292512_1920.jpg",1920,1280,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SANTISIMO NOMBRE DE JES\u00daS (Siglo XIV) Hoy en la Iglesia cat\u00f3lica se celebra el sant\u00edsimo Nombre del Se\u00f1or, San Bernardino de Siena y San Juan Capistrano, fueron dos santos que patrocinaron esta celebraci\u00f3n, en sus misiones llevaron una copia del monograma del Sant\u00edsimo Nombre que comprend\u00eda de las dos iniciales del nombre&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/7594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=7594"}],"version-history":[{"count":2,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/7594\/revisions"}],"predecessor-version":[{"id":7597,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/7594\/revisions\/7597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/7595"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=7594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=7594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=7594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}