{"id":7476,"date":"2025-12-11T15:23:00","date_gmt":"2025-12-11T20:23:00","guid":{"rendered":"https:\/\/devocionario.net\/?p=7476"},"modified":"2025-12-11T15:23:04","modified_gmt":"2025-12-11T20:23:04","slug":"viernes-segunda-semana-de-adviento-12-de-diciembre-ciclo-c","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2025\/12\/11\/viernes-segunda-semana-de-adviento-12-de-diciembre-ciclo-c\/","title":{"rendered":"VIERNES, Segunda Semana de Adviento, 12 de Diciembre (ciclo c)"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"427\" height=\"640\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/12\/12-de-diciembre.jpg\" alt=\"\" class=\"wp-image-7479\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/12\/12-de-diciembre.jpg 427w, https:\/\/devocionario.net\/wp-content\/uploads\/2025\/12\/12-de-diciembre-200x300.jpg 200w\" sizes=\"(max-width: 427px) 100vw, 427px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-0bcfa5069ac4ad08ab24c2581e70ec41\"><strong>NUESTRA SE\u00d1ORA DE GUADALUPE (1531)<\/strong><\/p>\n\n\n\n<p>En el Valle de M\u00e9xico habitaban los Indios Aztecas hace muchos a\u00f1os, y no conoc\u00edan de Jes\u00fas, as\u00ed que algunos sacerdotes Espa\u00f1oles viajaron hasta M\u00e9xico y evangelizaron a los Indios entre ellos San Juan Diego que se hizo bautizar junto con su Esposa, un s\u00e1bado cuando este Indio pas\u00f3 por el Cerro de Tepeyac para llegar a Tlatelolco, escuch\u00f3 una dulce voz de una Se\u00f1ora, que le preguntaba a donde iva, y le hizo una petici\u00f3n al Indio para que se le construyera un templo y poder prestar su auxilio a los pecadores, y tambi\u00e9n le orden\u00f3 fuera donde el Obispo, pero Juan Diego al contarle al Obispo no le crey\u00f3, as\u00ed que al aparec\u00e9rsele nuevamente la Virgen Mar\u00eda le dijo que enviar\u00e1 alguien m\u00e1s importante que \u00e9l, entonces La Sant\u00edsima Madre de Jes\u00fas le dijo que se dirigiera a la punto del cerro y all\u00ed cortar\u00e1 unas flores y se las llevar\u00e1 al obispo como prueba de su aparici\u00f3n y petici\u00f3n de la construcci\u00f3n de un templo, Juan Diego hizo lo mandado, al soltar su ayate las rosas cayeron al suelo y apareci\u00f3 dibujada en la tela la preciosa imagen de la Virgen de Guadalupe, desde ese momento el Obispo Fray de Zum\u00e1rraga crey\u00f3 y conserv\u00f3 el ayate y luego lo traslado a la ermita construida en el Cerro de Tepeyac.<br>San P\u00edo X elev\u00f3 el santuario de M\u00e9xico a la categor\u00eda de Bas\u00edlica y proclam\u00f3 a la Virgen de Guadalupe, Patrona de toda Am\u00e9rica Latina.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Mateo 11, 16-19<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, dijo Jes\u00fas al gent\u00edo:<br>\u00ab\u00bfA qui\u00e9n comparar\u00e9 esta generaci\u00f3n?<\/p>\n\n\n\n<p>Se asemeja a unos ni\u00f1os sentados en la plaza, que gritan diciendo:<br>\u201cHemos tocado la flauta, y no hab\u00e9is bailado; hemos entonado lamentaciones, y no hab\u00e9is llorado\u201d.<\/p>\n\n\n\n<p>Porque vino Juan, que ni com\u00eda ni beb\u00eda, y dicen: \u201cTiene un demonio\u201d. Vino el Hijo del hombre, que come y bebe, y dicen: \u201cAh\u00ed ten\u00e9is a un comil\u00f3n y borracho, amigo de publicanos y pecadores\u201d.<\/p>\n\n\n\n<p>Pero la sabidur\u00eda se ha acreditado por sus obras\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-ast-global-color-4-color has-vivid-purple-background-color has-text-color has-background has-link-color wp-elements-0f928d32f44a7a3cc8313935039da608\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Esta generaci\u00f3n de hoy es igual a la que el Evangelio nos describe, muchos de nosotros estamos acostumbrados a llevar una religi\u00f3n a la carta, \u00bfno es, verdad?, queremos salvarnos pero a nuestro modo, somos indiferentes a la f\u00f3rmula que el Se\u00f1or nos plantea, queremos acomodarnos a nuestras propias creencias, como , yo oro en casa porque Dios tambi\u00e9n esta ah\u00ed, de que me sirve ir a misa si me critican y juzgan, la caridad hay que saber hacerla, para que me confieso con hombres pecadores, para que rezar el rosario, as\u00ed y muchas m\u00e1s formas de pensar nos han hecho inconformes con la predicaci\u00f3n que Jesucristo me plantea, cuando se trata de convertirnos.<\/li>\n\n\n\n<li>Para qui\u00e9n no quiere cambiar de vida, ni o\u00edr la Palabra de Dios ninguna predicaci\u00f3n ser\u00e1 convincente, como en aquel tiempo ni a Juan ni a Jesucristo escucharon, igual estamos nosotros ahora en este tiempo, &#8220;<em>Es impactante que Dios nos hable a trav\u00e9s de hombres con limitaciones, hombres pecadores: \u00a1es impactante!&nbsp;&#8221; <strong>Pap\u00e1 Francisco<\/strong><\/em><\/li>\n\n\n\n<li>\u00bfT\u00fa como creyente que actitud tienes?, la predicaci\u00f3n de muchos puede sonarnos escandalosa, claro sino se acomoda a mis intereses, ah\u00ed nace mi inconformidad espiritual, hoy el Se\u00f1or nos invita abrir nuestro coraz\u00f3n a la acci\u00f3n salvadora del Espiritu Santo a trav\u00e9s de quien anuncia la Palabra de Dios.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Escuchar m\u00e1s y hablar menos..<\/li>\n\n\n\n<li>Nuestra Se\u00f1ora de Guadalupe intercede por nosotros.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA NUESTRA SE\u00d1ORA DE GUADALUPE (1531) En el Valle de M\u00e9xico habitaban los Indios Aztecas hace muchos a\u00f1os, y no conoc\u00edan de Jes\u00fas, as\u00ed que algunos sacerdotes Espa\u00f1oles viajaron hasta M\u00e9xico y evangelizaron a los Indios entre ellos San Juan Diego que se hizo bautizar junto con su Esposa, un s\u00e1bado cuando este &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2025\/12\/11\/viernes-segunda-semana-de-adviento-12-de-diciembre-ciclo-c\/\"> <span class=\"screen-reader-text\">VIERNES, Segunda Semana de Adviento, 12 de Diciembre (ciclo c)<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":7479,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-7476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tiempo-adviento"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/12\/12-de-diciembre.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/12\/12-de-diciembre.jpg",427,640,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/12\/12-de-diciembre-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/12\/12-de-diciembre-200x300.jpg",200,300,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/12\/12-de-diciembre.jpg",427,640,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/12\/12-de-diciembre.jpg",427,640,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/12\/12-de-diciembre.jpg",427,640,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/12\/12-de-diciembre.jpg",427,640,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":1,"uagb_excerpt":"SANTO DEL D\u00cdA NUESTRA SE\u00d1ORA DE GUADALUPE (1531) En el Valle de M\u00e9xico habitaban los Indios Aztecas hace muchos a\u00f1os, y no conoc\u00edan de Jes\u00fas, as\u00ed que algunos sacerdotes Espa\u00f1oles viajaron hasta M\u00e9xico y evangelizaron a los Indios entre ellos San Juan Diego que se hizo bautizar junto con su Esposa, un s\u00e1bado cuando este&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/7476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=7476"}],"version-history":[{"count":4,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/7476\/revisions"}],"predecessor-version":[{"id":7481,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/7476\/revisions\/7481"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/7479"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=7476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=7476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=7476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}