{"id":7403,"date":"2025-12-02T12:45:36","date_gmt":"2025-12-02T17:45:36","guid":{"rendered":"https:\/\/devocionario.net\/?p=7403"},"modified":"2025-12-02T12:45:39","modified_gmt":"2025-12-02T17:45:39","slug":"domingo-primera-semana-de-adviento-30-de-noviembre-ciclo-c","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2025\/12\/02\/domingo-primera-semana-de-adviento-30-de-noviembre-ciclo-c\/","title":{"rendered":"DOMINGO, Primera Semana de Adviento, 30 de Noviembre (ciclo c)"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/12\/30-de-noviembre.jpg\" alt=\"\" class=\"wp-image-7407\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/12\/30-de-noviembre.jpg 640w, https:\/\/devocionario.net\/wp-content\/uploads\/2025\/12\/30-de-noviembre-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color has-link-color wp-elements-407b8c50e53165b188f54200c7c2f11d\"><strong>SAN ANDR\u00c9S APOSTOL (+60 d.c)<\/strong><\/p>\n\n\n\n<p>San Andr\u00e9s nacido en Betsaida (Galilea) fue un humilde pescador igual que su hermano Sim\u00f3n Pedro, ambos desempe\u00f1aban este oficio en Cafarna\u00fam, San Andr\u00e9s fue llamado por Jes\u00fas en el lago de Tiber\u00edades junto con Juan. Desde antes el ap\u00f3stol ya ten\u00eda la iniciativa de seguir al Mes\u00edas, gracias a la predicaci\u00f3n de San Juan Bautista, fue \u00e9l quien motivo a su hermano Pedro para que siguiera a Jes\u00fas llev\u00e1ndolo hasta el Maestro, en los evangelios se habla unas tres veces de Andr\u00e9s, en la multiplicaci\u00f3n de los panes, como intermediario de los forasteros, y la pregunta que le hace a Jes\u00fas para que profetice sobre la destrucci\u00f3n de Jerusal\u00e9n, despu\u00e9s de la Ascenci\u00f3n de Jesucristo anuncia la buena noticia en regiones b\u00e1rbaras como la Scitia, en la Rusia meridional, como refiere el historiador Eusebio, no se tiene certeza como muri\u00f3. El primero en recordar su memoria fue San Gregorio Nacianceno.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Mateo 24, 37-44<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, dijo Jes\u00fas a sus disc\u00edpulos:<br>\u00abCuando venga el Hijo del hombre, pasar\u00e1 como en tiempo de No\u00e9.<\/p>\n\n\n\n<p>En los d\u00edas antes del diluvio, la gente com\u00eda y beb\u00eda, se casaban los hombres y las mujeres tomaban esposo, hasta el d\u00eda en que No\u00e9 entr\u00f3 en el arca; y cuando menos lo esperaban lleg\u00f3 el diluvio y se los llev\u00f3 a todos; lo mismo suceder\u00e1 cuando venga el Hijo del hombre: dos hombres estar\u00e1n en el campo, a uno se lo llevar\u00e1n y a otro lo dejar\u00e1n; dos mujeres estar\u00e1n moliendo, a una se la llevar\u00e1n y a otra la dejar\u00e1n.<\/p>\n\n\n\n<p>Por tanto, estad en vela, porque no sab\u00e9is qu\u00e9 d\u00eda vendr\u00e1 vuestro Se\u00f1or.<\/p>\n\n\n\n<p>Comprended que si supiera el due\u00f1o de casa a qu\u00e9 hora de la noche viene el ladr\u00f3n, estar\u00eda en vela y no dejar\u00eda que abrieran un boquete en su casa.<\/p>\n\n\n\n<p>Por eso, estad tambi\u00e9n vosotros preparados, porque a la hora que menos pens\u00e9is viene el Hijo del hombre\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-ast-global-color-4-color has-vivid-purple-background-color has-text-color has-background has-link-color wp-elements-0f928d32f44a7a3cc8313935039da608\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El Evangelio de este domingo nos hace una invitaci\u00f3n a permanecer firmes en la fe, a no permitir que los vicios, las preocupaciones, el consumismo, y las distracciones ef\u00edmeras nos aparten del verdadero camino de la fe, pues la esperanza nos permite caminar con vigilancia ante los acontecimientos presentes con la mirada puesta en el cielo. A menudo se nos escapan por el agujero negro muchas cosas en el universo de nuestra vida, cosas que edifican nuestro esp\u00edritu, hoy se nos exhorta a permanecer vigilantes, alertas, y despiertos los ojos del alma .<\/li>\n\n\n\n<li>En la actualidad al estar en medio de tanta tribulaci\u00f3n y destrucci\u00f3n, debemos estar consientes de que la redenci\u00f3n y la vida eterna est\u00e1n por delante, los peri\u00f3dicos, noticias de Tv, redes sociales, nos est\u00e1n siempre mostrando malas noticias, ya podemos ver los signos de los tiempos que nos hablan no para temer sino para animarnos en la fe, la muerte tarde que temprano nos llegar\u00e1 a todos, es una realidad de la que no podemos escapar, as\u00ed que no debemos centrar nuestra mirada en lo temporal, sino en lo que vendr\u00e1 para quienes siguen a Jesucristo.<\/li>\n\n\n\n<li>\u00bfTe desesperas con este relato apocal\u00edptico?\u00bfEn qui\u00e9n est\u00e1s colocando tu esperanza?, este Evangelio de hoy nos inquieta a interpelarnos de lo que estamos haciendo, y de lo bueno que hemos dejado hacer, a estar preparados ya sea para el fin de los tiempos o para la muerte, pero debemos vivir con esperanza de que Jes\u00fas vendr\u00e1,&#8221; levantaos, alzad la cabeza; se acerca vuestra liberaci\u00f3n&#8221;, esta hermosa frase nos impulsa a seguir sin desfallecer, que hacer la voluntad de Dios no es vano, deber\u00edas hacerte estas preguntas \u00bfC\u00f3mo me encuentro en este momento de mi vida, si Jes\u00fas me llamara?\u00bfC\u00f3mo ser\u00e1 mi final?, Los signos de los tiempos me indican que todo pasa pero Jes\u00fas no pasar\u00e1, \u00bfQue debo mejorar y que debo potencializar en mi camino de fe?.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Prepararnos a tiempo y a destiempo.<\/li>\n\n\n\n<li>san Andr\u00e9s Ap\u00f3stol nos ense\u00f1a que seguir a Jesucristo debe hacerse con valentia.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN ANDR\u00c9S APOSTOL (+60 d.c) San Andr\u00e9s nacido en Betsaida (Galilea) fue un humilde pescador igual que su hermano Sim\u00f3n Pedro, ambos desempe\u00f1aban este oficio en Cafarna\u00fam, San Andr\u00e9s fue llamado por Jes\u00fas en el lago de Tiber\u00edades junto con Juan. Desde antes el ap\u00f3stol ya ten\u00eda la iniciativa de seguir al &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2025\/12\/02\/domingo-primera-semana-de-adviento-30-de-noviembre-ciclo-c\/\"> <span class=\"screen-reader-text\">DOMINGO, Primera Semana de Adviento, 30 de Noviembre (ciclo c)<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":7407,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/12\/30-de-noviembre.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/12\/30-de-noviembre.jpg",640,427,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/12\/30-de-noviembre-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/12\/30-de-noviembre-300x200.jpg",300,200,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/12\/30-de-noviembre.jpg",640,427,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/12\/30-de-noviembre.jpg",640,427,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/12\/30-de-noviembre.jpg",640,427,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/12\/30-de-noviembre.jpg",640,427,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SAN ANDR\u00c9S APOSTOL (+60 d.c) San Andr\u00e9s nacido en Betsaida (Galilea) fue un humilde pescador igual que su hermano Sim\u00f3n Pedro, ambos desempe\u00f1aban este oficio en Cafarna\u00fam, San Andr\u00e9s fue llamado por Jes\u00fas en el lago de Tiber\u00edades junto con Juan. Desde antes el ap\u00f3stol ya ten\u00eda la iniciativa de seguir al&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/7403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=7403"}],"version-history":[{"count":4,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/7403\/revisions"}],"predecessor-version":[{"id":7409,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/7403\/revisions\/7409"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/7407"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=7403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=7403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=7403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}