{"id":7347,"date":"2025-11-20T20:02:06","date_gmt":"2025-11-21T01:02:06","guid":{"rendered":"https:\/\/devocionario.net\/?p=7347"},"modified":"2025-11-20T20:02:09","modified_gmt":"2025-11-21T01:02:09","slug":"jueves-trigesimo-tercera-semana-del-tiempo-ordinario-20-de-noviembre-ciclo-c","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2025\/11\/20\/jueves-trigesimo-tercera-semana-del-tiempo-ordinario-20-de-noviembre-ciclo-c\/","title":{"rendered":"JUEVES, Trig\u00e9simo tercera Semana del Tiempo Ordinario, 20 de Noviembre (ciclo c)"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"427\" height=\"640\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/11\/20-DE-NOVIEMBRE.jpg\" alt=\"\" class=\"wp-image-7348\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/11\/20-DE-NOVIEMBRE.jpg 427w, https:\/\/devocionario.net\/wp-content\/uploads\/2025\/11\/20-DE-NOVIEMBRE-200x300.jpg 200w\" sizes=\"(max-width: 427px) 100vw, 427px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color has-link-color wp-elements-cbdc7ab7da197141429cb9253ef4fdc0\"><strong>SAN EDMUNDO (841-870)<\/strong><\/p>\n\n\n\n<p>San Edmundo fue coronado rey de Estanglia (Inglaterra) con tan solo catorce a\u00f1os de edad, fue un gran modelo de los buenos pr\u00edncipes, busca siempre la paz para su pueblo, es recto y neutral ante los temas de justicia, ayuda a los hu\u00e9rfanos, viudas y necesitados, resalta los valores de quienes son marginados, a la llegada de los piratas daneses capitaneados por los hermanos Hingaro y Hubba generan en el pueblo miedo y destruyen todo a su paso, estos adversarios reflejaban el odio por los cristianos, as\u00ed que comienzan a saquear templos, monasterios, y a asesinar a todos los que profesan la fe cristiana, una muestra fue en el monasterio de Coldinghan, donde la abadesa santa Ebba fue degollada con todas sus monjas, San Edmundo organiza un peque\u00f1o ejercito para combatir a los enemigos de la fe, pero decide esconderse para no dar muerte aquellos y provocar su condenaci\u00f3n, una vez encontrado por los piratas lo obligan a renegar de su fe y atentar contra su pueblo, rechaza tal propuesta entonces es azotado, y decapitado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Lucas 19, 41-44<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, al acercarse Jes\u00fas a Jerusal\u00e9n y ver la ciudad, llor\u00f3 sobre ella, mientras dec\u00eda:<br>\u00abSi reconocieras t\u00fa tambi\u00e9n en este d\u00eda lo que conduce a la paz! Pero ahora est\u00e1 escondido a tus ojos.<\/p>\n\n\n\n<p>Pues vendr\u00e1n d\u00edas sobre ti en que tus enemigos te rodear\u00e1n de trincheras, te sitiar\u00e1n, apretar\u00e1n el cerco de todos lados, te arrasar\u00e1n con tus hijos dentro, y no dejar\u00e1n piedra sobre piedra. Porque no reconociste el tiempo de tu visita\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-ast-global-color-2-color has-vivid-green-cyan-background-color has-text-color has-background has-link-color wp-elements-0c192cd5e76cac3988c4c9fb3045ec50\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00bfQu\u00e9 sucesos de la vida te hacen llorar?, \u00bfHas experimentado la tristeza? Creer\u00eda que si!!, todos hemos pasado por situaciones de dolor, tristeza, que nos hacen llorar, en esta pasaje b\u00edblico encontramos aun Jes\u00fas triste, por la incredulidad del pueblo de Jerusal\u00e9n que hab\u00eda presenciado sus prodigios pero no cre\u00edan en sus palabras.<\/li>\n\n\n\n<li>Jesucristo llora ante tantas injusticias, y se lamenta por todos los adversarios que impiden anunciar su mensaje salvador, su coraz\u00f3n siente dolor desde que comienza su vida p\u00fablica al ver tantos que conoc\u00edan a Dios a trav\u00e9s de su ley pero eran incoherentes ante la pr\u00e1ctica real del amor hacia los hermanos, muchos pensaron que El Se\u00f1or era un profeta, les pareci\u00f3 muy normal quien les predicaba la verdad, no reconocieron los signos de los tiempos no vieron al salvador.<\/li>\n\n\n\n<li>Jesucristo en la actualidad continua derramando l\u00e1grimas por la humanidad, por su falta de fe, y por su falta de amor , nunca se ha cansado de esperar, anhela que la raza humana vuelva su mirada a \u00e9l, que entienda las se\u00f1ales que anuncian su venida, vivimos en este mundo crucificando a Jes\u00fas una y otra vez, pero \u00e9l en su infinita misericordia nos muestra compasi\u00f3n, y lamenta d\u00eda y noche por nuestra desobediencia. Aprovechemos su presencia en la Sagrada eucarist\u00eda, en \u00e9l que sufre, en \u00e9l necesitado, aprendamos a conmovernos por el sufrimiento de los dem\u00e1s, a orar siempre por quienes rechazan el mensaje de Jes\u00fas y no lo ponen en pr\u00e1ctica.<\/li>\n\n\n\n<li>Debemos hacer un alto en el camino y reflexionar de los actos que cometemos y que hacen llorar y entristecer el coraz\u00f3n de Jes\u00fas, ya no podemos estar en el mundo y en las cosas de Dios, nuestra vida debe agradarle s\u00f3lo a \u00e9l ,\u00bf te conduces a caminos de paz?<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Orar por quienes rechazan el mensaje de Jesucristo.<\/li>\n\n\n\n<li>San Edmundo nos dice: &#8220;La vida es vida y sigue la ley de la existencia: el progreso&#8221;<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN EDMUNDO (841-870) San Edmundo fue coronado rey de Estanglia (Inglaterra) con tan solo catorce a\u00f1os de edad, fue un gran modelo de los buenos pr\u00edncipes, busca siempre la paz para su pueblo, es recto y neutral ante los temas de justicia, ayuda a los hu\u00e9rfanos, viudas y necesitados, resalta los valores &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2025\/11\/20\/jueves-trigesimo-tercera-semana-del-tiempo-ordinario-20-de-noviembre-ciclo-c\/\"> <span class=\"screen-reader-text\">JUEVES, Trig\u00e9simo tercera Semana del Tiempo Ordinario, 20 de Noviembre (ciclo c)<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":7348,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-7347","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tiempo-ordinario"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/11\/20-DE-NOVIEMBRE.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/11\/20-DE-NOVIEMBRE.jpg",427,640,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/11\/20-DE-NOVIEMBRE-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/11\/20-DE-NOVIEMBRE-200x300.jpg",200,300,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/11\/20-DE-NOVIEMBRE.jpg",427,640,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/11\/20-DE-NOVIEMBRE.jpg",427,640,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/11\/20-DE-NOVIEMBRE.jpg",427,640,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/11\/20-DE-NOVIEMBRE.jpg",427,640,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SAN EDMUNDO (841-870) San Edmundo fue coronado rey de Estanglia (Inglaterra) con tan solo catorce a\u00f1os de edad, fue un gran modelo de los buenos pr\u00edncipes, busca siempre la paz para su pueblo, es recto y neutral ante los temas de justicia, ayuda a los hu\u00e9rfanos, viudas y necesitados, resalta los valores&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/7347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=7347"}],"version-history":[{"count":2,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/7347\/revisions"}],"predecessor-version":[{"id":7350,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/7347\/revisions\/7350"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/7348"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=7347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=7347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=7347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}