{"id":7198,"date":"2025-10-25T19:55:58","date_gmt":"2025-10-26T00:55:58","guid":{"rendered":"https:\/\/devocionario.net\/?p=7198"},"modified":"2025-10-25T19:56:01","modified_gmt":"2025-10-26T00:56:01","slug":"viernes-vigesimo-novena-semana-del-tiempo-ordinario-24-de-octubre-ciclo-c","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2025\/10\/25\/viernes-vigesimo-novena-semana-del-tiempo-ordinario-24-de-octubre-ciclo-c\/","title":{"rendered":"VIERNES, Vig\u00e9simo Novena Semana del Tiempo Ordinario, 24 de octubre (ciclo c)"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"612\" height=\"408\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/10\/24-de-octubre.jpg\" alt=\"\" class=\"wp-image-7201\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/10\/24-de-octubre.jpg 612w, https:\/\/devocionario.net\/wp-content\/uploads\/2025\/10\/24-de-octubre-300x200.jpg 300w\" sizes=\"(max-width: 612px) 100vw, 612px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-ast-global-color-2-color has-text-color has-link-color wp-elements-63e82164b402bf460c057c2f6a3552b3\"><strong>SAN ANTONIO MARIA CLARET(1807-1870)<\/strong><\/p>\n\n\n\n<p>San Antonio naci\u00f3 en Sallent (Espa\u00f1a), desde sus doce a\u00f1os comenz\u00f3 a trabajar en el telar de su familia, viaj\u00f3 a Barcelona para perfeccionarse en este arte, pasado alg\u00fan tiempo escucha el llamado de Dios que resuena en su cabeza, en su conciencia, recibi\u00f3 muchas ofertas para tener su propio negocio, pero al final decidi\u00f3 ser cartujo(monje del monasterio de dicha orden) y no complacer a su Padre, entonces ingresa al seminario de Vic, siente desanimo y hasta casi cae en tentaci\u00f3n pero se mantuvo firme, el Se\u00f1or lo quer\u00eda como misionero evangelizador as\u00ed entendi\u00f3 San Antonio. Una vez ordenado sacerdote lo env\u00edan a su Parroquia natal para servir en esa comunidad, pero entiende que Dios lo quer\u00eda como evangelizador, luego hizo un viaje a Roma, y se sinti\u00f3 movido en ingresar a la Compa\u00f1\u00eda de Jes\u00fas (Jesuitas), pero un dolor en una pierna le hicieron regresar a Espa\u00f1a, tiempo despu\u00e9s solicita a Propaganda Fide el t\u00edtulo de &#8220;Misionero Apost\u00f3lico&#8221;, \u00e9l mismo reforz\u00f3 este nombre con dedicaci\u00f3n espiritual y apostolado, y le eximieron de toda responsabilidad de la Parroquia donde se encontraba para que pudiera evangelizar de pueblo en pueblo, recorri\u00f3 toda Catalu\u00f1a, y se neg\u00f3 a recibir cosas materiales, tambi\u00e9n se dedic\u00f3 a publicar devocionarios, peque\u00f1os tratados literarios cortos dirigidos a sacerdotes, religiosas, ni\u00f1os, j\u00f3venes, casadas, padres de familia, fund\u00f3 una Librer\u00eda Religiosa, fund\u00f3 tambi\u00e9n Cofrad\u00edas como la Hermandad del sant\u00edsimo e inmaculado Coraz\u00f3n de Mar\u00eda, as\u00ed como el Instituto Secular Filiaci\u00f3n Cordimariana, a\u00f1os despu\u00e9s el obispo lo envi\u00f3 a las Islas Canarias, al regresar a Catalu\u00f1a funda la Congregaci\u00f3n de los Misioneros Hijos del Inmaculado Coraz\u00f3n de Mar\u00eda, y luego es nombrado Arzobispo de Cuba, trabaja arduamente durante mucho tiempo en contra de la esclavitud, recibe un atentado en Holgu\u00edn, casi le cuesta la vida, la Reina Isabel II lo elige para ser su confesor, aprovecha su estad\u00eda en Palacio para evangelizar. A\u00f1os m\u00e1s tarde sinti\u00e9ndose delicado de salud, huye de sus perseguidores al monasterio cisterciense de Fontfroide donde pasa sus \u00faltimos d\u00edas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Lucas 12,54-59<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, dec\u00eda Jes\u00fas a la gente:<br>\u00abCuando veis subir una nube por el poniente, dec\u00eds enseguida: \u201cVa a caer un aguacero\u201d, y as\u00ed sucede. Cuando sopla el sur dec\u00eds: \u201cVa a hacer bochorno\u201d, y sucede.<\/p>\n\n\n\n<p>Hip\u00f3critas: sab\u00e9is interpretar el aspecto de la tierra y del cielo, pues \u00bfc\u00f3mo no sab\u00e9is interpretar el tiempo presente? \u00bfC\u00f3mo no sab\u00e9is juzgar vosotros mismos lo que es justo?<\/p>\n\n\n\n<p>Por ello, mientras vas con tu adversario al magistrado, haz lo posible en el camino por llegar a un acuerdo con \u00e9l, no sea que te lleve a la fuerza ante el juez y el juez te entregue al guardia y el guardia te meta en la c\u00e1rcel.<\/p>\n\n\n\n<p>Te digo que no saldr\u00e1s de all\u00ed hasta que no pagues la \u00faltima monedilla\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-ast-global-color-2-color has-vivid-green-cyan-background-color has-text-color has-background has-link-color wp-elements-0c192cd5e76cac3988c4c9fb3045ec50\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00bfC\u00f3mo respondes a las se\u00f1ales que Dios te env\u00eda a trav\u00e9s de lo que te rodea?, muchas veces pasamos desapercibidas algunas situaciones en las que deber\u00edamos aplicar la justicia, como servir, como amar, pues estamos cegados pero para las cosas de Dios, en la actualidad la ciencia ha avanzado, hemos descubierto cosas de la naturaleza que nos hacen comprender porque suceden, pero hemos dejado aun lado la Palabra de Dios que nos permite trascender y entender lo inimaginable, porque existimos y para donde vamos.<\/li>\n\n\n\n<li>El tiempo presente es Jesucristo, \u00bfnos hemos fijado de su presencia entre nosotros?, \u00bfhemos hecho notar su poder ante los dem\u00e1s?, es por eso que vivimos sin esperanza, sin prop\u00f3sitos, pues nuestra b\u00fasqueda es material y superflua, debemos aprender a discernir la acci\u00f3n de Dios en nosotros, saber que es lo importante y que lo complementa, sin olvidar la primera. Como dice San Pablo exam\u00ednenlo todo y qu\u00e9dense con lo bueno.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Estar consiente de la presencia de Dios.<\/li>\n\n\n\n<li>San Antonio Mar\u00eda Claret nos dice:&#8221;\u201cDebes mirar e imitar continuamente la humildad y la mansedumbre de Jes\u00fas; la humildad es el fundamento de todas las virtudes; y como se cae un edificio alto sin cimientos, as\u00ed tambi\u00e9n vosotros si no sois humildes\u201d.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN ANTONIO MARIA CLARET(1807-1870) San Antonio naci\u00f3 en Sallent (Espa\u00f1a), desde sus doce a\u00f1os comenz\u00f3 a trabajar en el telar de su familia, viaj\u00f3 a Barcelona para perfeccionarse en este arte, pasado alg\u00fan tiempo escucha el llamado de Dios que resuena en su cabeza, en su conciencia, recibi\u00f3 muchas ofertas para tener &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2025\/10\/25\/viernes-vigesimo-novena-semana-del-tiempo-ordinario-24-de-octubre-ciclo-c\/\"> <span class=\"screen-reader-text\">VIERNES, Vig\u00e9simo Novena Semana del Tiempo Ordinario, 24 de octubre (ciclo c)<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":7201,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/10\/24-de-octubre.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/10\/24-de-octubre.jpg",612,408,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/10\/24-de-octubre-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/10\/24-de-octubre-300x200.jpg",300,200,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/10\/24-de-octubre.jpg",612,408,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/10\/24-de-octubre.jpg",612,408,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/10\/24-de-octubre.jpg",612,408,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/10\/24-de-octubre.jpg",612,408,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":1,"uagb_excerpt":"SANTO DEL D\u00cdA SAN ANTONIO MARIA CLARET(1807-1870) San Antonio naci\u00f3 en Sallent (Espa\u00f1a), desde sus doce a\u00f1os comenz\u00f3 a trabajar en el telar de su familia, viaj\u00f3 a Barcelona para perfeccionarse en este arte, pasado alg\u00fan tiempo escucha el llamado de Dios que resuena en su cabeza, en su conciencia, recibi\u00f3 muchas ofertas para tener&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/7198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=7198"}],"version-history":[{"count":3,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/7198\/revisions"}],"predecessor-version":[{"id":7202,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/7198\/revisions\/7202"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/7201"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=7198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=7198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=7198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}