{"id":6582,"date":"2025-07-21T17:52:25","date_gmt":"2025-07-21T22:52:25","guid":{"rendered":"https:\/\/devocionario.net\/?p=6582"},"modified":"2025-07-21T17:52:27","modified_gmt":"2025-07-21T22:52:27","slug":"martes-decimosexta-semana-del-tiempo-ordinario22-de-juliociclo-c","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2025\/07\/21\/martes-decimosexta-semana-del-tiempo-ordinario22-de-juliociclo-c\/","title":{"rendered":"MARTES, Decimosexta Semana del Tiempo Ordinario,22 de julio,(Ciclo c)"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"612\" height=\"408\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/07\/22-DE-JULIO.jpg\" alt=\"\" class=\"wp-image-6583\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/07\/22-DE-JULIO.jpg 612w, https:\/\/devocionario.net\/wp-content\/uploads\/2025\/07\/22-DE-JULIO-300x200.jpg 300w\" sizes=\"(max-width: 612px) 100vw, 612px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-ast-global-color-2-color has-text-color has-link-color wp-elements-aaf23b4ddd3036f2387cde681a3b944b\"><strong>SSANTA MARIA MAGDALENA (SIGLO I)<\/strong><\/p>\n\n\n\n<p>Santa Mar\u00eda Magdalena, nacida en Magdala fue una mujer muy importante en la vida p\u00fablica de Jes\u00fas, aparece junto al Maestro como seguidora fiel hasta su resurrecci\u00f3n y ascensi\u00f3n, los evangelios relatan que Jesucristo expuls\u00f3 siete demonios de ella, y desde ese momento camino con Jes\u00fas y los ap\u00f3stoles en las misiones a distintos lugares que la Biblia menciona, tambi\u00e9n dice la tradici\u00f3n de la Iglesia Cat\u00f3lica que esta mujer fue la que Jes\u00fas perdono en el momento que iva a ser apedreada, y aquella que sec\u00f3 sus lagrimas y ungi\u00f3 con aceite los pies de Jesucristo. Mar\u00eda Magdalena fue la primera mujer que presenci\u00f3 la resurrecci\u00f3n de Jes\u00fas, y tiempo despu\u00e9s estuvo en la fiesta de pentecost\u00e9s donde acompa\u00f1o a la Madre de Jes\u00fas y a los disc\u00edpulos.<br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Juan 20, 1-2. 11-18<\/strong><\/p>\n\n\n\n<p>El primer d\u00eda de la semana, Mar\u00eda la Magdalena fue al sepulcro al amanecer, cuando a\u00fan estaba oscuro, y vio la losa quitada del sepulcro.<\/p>\n\n\n\n<p>Ech\u00f3 a correr y fue donde estaban Sim\u00f3n Pedro y el otro disc\u00edpulo, a quien Jes\u00fas amaba, y les dijo:<br>\u00abSe han llevado del sepulcro al se\u00f1or y no sabemos d\u00f3nde lo han puesto\u00bb.<\/p>\n\n\n\n<p>Estaba Mar\u00eda fuera, junto al sepulcro, llorando. Mientras lloraba, se asom\u00f3 al sepulcro y vio dos \u00e1ngeles vestidos de blanco, sentados, uno a la cabecera y otro a los pies, donde hab\u00eda estado el cuerpo de Jes\u00fas.<\/p>\n\n\n\n<p>Ellos le preguntan:<br>\u00abMujer, \u00bfpor qu\u00e9 lloras?\u00bb.<\/p>\n\n\n\n<p>Ella les contesta:<br>\u00abPorque se han llevado a mi Se\u00f1or y no s\u00e9 d\u00f3nde lo han puesto\u00bb.<\/p>\n\n\n\n<p>Dicho esto, se vuelve y ve a Jes\u00fas, de pie, pero no sab\u00eda que era Jes\u00fas.<\/p>\n\n\n\n<p>Jes\u00fas le dice:<br>\u00abMujer, \u00bfpor qu\u00e9 lloras?, \u00bfa qui\u00e9n buscas?\u00bb.<\/p>\n\n\n\n<p>Ella, tom\u00e1ndolo por el hortelano, le contesta:<br>\u00abSe\u00f1or, si t\u00fa te lo has llevado, dime d\u00f3nde lo has puesto y yo lo recoger\u00e9\u00bb.<\/p>\n\n\n\n<p>Jes\u00fas le dice:<br>\u00ab\u00a1Mar\u00eda!\u00bb.<\/p>\n\n\n\n<p>Ella se vuelve y le dice:<br>\u00ab\u00a1Rabboni!\u00bb, que significa: \u00ab\u00a1Maestro!\u00bb.<\/p>\n\n\n\n<p>Jes\u00fas le dice:<br>\u00abNo me retengas, que todav\u00eda no he subido al Padre. Pero anda, ve a mis hermanos y diles: \u201cSubo al Padre m\u00edo y Padre vuestro, al Dios m\u00edo y Dios vuestro\u201d\u00bb.<\/p>\n\n\n\n<p>Mar\u00eda la Magdalena fue y anunci\u00f3 a los disc\u00edpulos:<br>\u00abHe visto al Se\u00f1or y ha dicho esto\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-ast-global-color-2-color has-vivid-green-cyan-background-color has-text-color has-background has-link-color wp-elements-0c192cd5e76cac3988c4c9fb3045ec50\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Jes\u00fas se revela a los m\u00e1s sencillos, a los vulnerables, a los marginados, el dolor del hombre inquieta su amante coraz\u00f3n, cuando enceguecidos estamos por las aflicciones de esta humanidad enferma, Jes\u00fas nos encuentra, y siente compasi\u00f3n, cuando nuestro coraz\u00f3n esta abrumado, \u00c9l nos llama por nuestro nombre con su voz dulce y paciente, y nos brinda una esperanza que nos motiva a anunciarlo con nuestro testimonio de vida.<\/li>\n\n\n\n<li>Jes\u00fas quiere en esta actualidad disc\u00edpulos arriesgados, que motivados por su amor, sean capaces de hacer hasta lo que se cree imposible , sin importar si muchos no van a creer s\u00f3lo pide que nos dejemos transformar y  har\u00e1 de nosotros hombres y mujeres misioneros fieles a su amor. Jes\u00fas una vez m\u00e1s nos da valor a las mujeres y nos da nuestro lugar, haci\u00e9ndonos participes de su plan de salvaci\u00f3n, y es que para Dios no hay distinci\u00f3n, la mujer da vida, y promueve la vida y es portadora de vida, es por eso que decidi\u00f3 presentarse a Mar\u00eda Magdalena como Jes\u00fas vivo, para manifestar que la vida triunfa sobre la muerte. En este tiempo las mujeres son desvalorizadas, maltratadas, es Jes\u00fas a trav\u00e9s de este pasaje b\u00edblico que hace a la mujer digna de ser una pieza clave en la evangelizaci\u00f3n de su Reino.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Hoy elevaremos una oraci\u00f3n por las mujeres que son excluidas de la sociedad, por las prostitutas, madres solteras, y por aquellas maltratadas en su mismo hogar.<\/li>\n\n\n\n<li>Santa Mar\u00eda Magdalena nos ense\u00f1a que amar incondicionalmente a Cristo nos permite ver milagros asombrosos en nuestra vida, como la santa sigamos a Jes\u00fas hasta el final de nuestros d\u00edas, y siendo sus disc\u00edpulos lo anunciemos incluso a quienes no puedan creernos.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SSANTA MARIA MAGDALENA (SIGLO I) Santa Mar\u00eda Magdalena, nacida en Magdala fue una mujer muy importante en la vida p\u00fablica de Jes\u00fas, aparece junto al Maestro como seguidora fiel hasta su resurrecci\u00f3n y ascensi\u00f3n, los evangelios relatan que Jesucristo expuls\u00f3 siete demonios de ella, y desde ese momento camino con Jes\u00fas y &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2025\/07\/21\/martes-decimosexta-semana-del-tiempo-ordinario22-de-juliociclo-c\/\"> <span class=\"screen-reader-text\">MARTES, Decimosexta Semana del Tiempo Ordinario,22 de julio,(Ciclo c)<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":6583,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-6582","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tiempo-ordinario"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/07\/22-DE-JULIO.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/07\/22-DE-JULIO.jpg",612,408,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/07\/22-DE-JULIO-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/07\/22-DE-JULIO-300x200.jpg",300,200,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/07\/22-DE-JULIO.jpg",612,408,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/07\/22-DE-JULIO.jpg",612,408,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/07\/22-DE-JULIO.jpg",612,408,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/07\/22-DE-JULIO.jpg",612,408,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SSANTA MARIA MAGDALENA (SIGLO I) Santa Mar\u00eda Magdalena, nacida en Magdala fue una mujer muy importante en la vida p\u00fablica de Jes\u00fas, aparece junto al Maestro como seguidora fiel hasta su resurrecci\u00f3n y ascensi\u00f3n, los evangelios relatan que Jesucristo expuls\u00f3 siete demonios de ella, y desde ese momento camino con Jes\u00fas y&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/6582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=6582"}],"version-history":[{"count":3,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/6582\/revisions"}],"predecessor-version":[{"id":6587,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/6582\/revisions\/6587"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/6583"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=6582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=6582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=6582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}