{"id":6566,"date":"2025-07-20T07:10:54","date_gmt":"2025-07-20T12:10:54","guid":{"rendered":"https:\/\/devocionario.net\/?p=6566"},"modified":"2025-07-20T07:10:57","modified_gmt":"2025-07-20T12:10:57","slug":"domingo-decimosexta-semana-del-tiempo-ordinario20-de-juliociclo-c","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2025\/07\/20\/domingo-decimosexta-semana-del-tiempo-ordinario20-de-juliociclo-c\/","title":{"rendered":"DOMINGO, Decimosexta Semana del Tiempo Ordinario,20 de julio,(Ciclo c)"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/07\/20-de-julio-1024x683.jpg\" alt=\"\" class=\"wp-image-6568\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/07\/20-de-julio-1024x683.jpg 1024w, https:\/\/devocionario.net\/wp-content\/uploads\/2025\/07\/20-de-julio-300x200.jpg 300w, https:\/\/devocionario.net\/wp-content\/uploads\/2025\/07\/20-de-julio-768x512.jpg 768w, https:\/\/devocionario.net\/wp-content\/uploads\/2025\/07\/20-de-julio.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color has-link-color wp-elements-6709d6107d4705b14e8abfaa3a4f7a77\"><strong>SAN APOLINAR (310-390)<\/strong><\/p>\n\n\n\n<p>San Apolinar nacido en Antioquia (Turqu\u00eda), seg\u00fan la tradici\u00f3n de la iglesia, San Apolinar acompa\u00f1o a San Pedro en la fundaci\u00f3n de la Iglesia en Roma despu\u00e9s de la resurrecci\u00f3n de Cristo, gobernando Claudio, san Apolinar fue enviado a Italia para evangelizar y convertir personas al cristianismo, fue el primer obispo de R\u00e1vena, realiza milagros durante casi 20 a\u00f1os trabajando arduamente en la proclamaci\u00f3n de la Buena Nueva de Jesucristo, al ser ascendido Vespasiano al trono imperial, inici\u00f3 las m\u00e1s crueles persecuciones de su tiempo en contra de los cristianos, San Apolinar huy\u00f3 a Dalmacia, se dice que all\u00ed hizo calmar la hambruna y predico el Evangelio de Jesucristo, luego a\u00f1os m\u00e1s tarde muere, por tortura, convirti\u00e9ndose en m\u00e1rtir en los primeros inicios de la iglesia.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"396\" height=\"214\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/07\/image-1.png\" alt=\"\" class=\"wp-image-4257\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/07\/image-1.png 396w, https:\/\/devocionario.net\/wp-content\/uploads\/2024\/07\/image-1-300x162.png 300w\" sizes=\"(max-width: 396px) 100vw, 396px\" \/><\/figure>\n\n\n\n<p>Hoy conmemoramos  la festividad del divino ni\u00f1o en Colombia, gracias al Padre Salesiano Juan del Rizzo en 1935 se propago esta advocaci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Lucas 10, 38-42<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, entr\u00f3 Jes\u00fas en una aldea, y una mujer llamada Marta lo recibi\u00f3 en su casa.<\/p>\n\n\n\n<p>Esta ten\u00eda una hermana llamada Mar\u00eda, que, sentada junto a los pies del Se\u00f1or, escuchaba su palabra.<\/p>\n\n\n\n<p>Marta, en cambio, andaba muy afanada con los muchos servicios; hasta que, acerc\u00e1ndose, dijo:<br>\u00abSe\u00f1or, \u00bfno te importa que mi hermana me haya dejado sola para servir? Dile que me eche una mano\u00bb.<\/p>\n\n\n\n<p>Respondiendo, le dijo el Se\u00f1or:<br>\u00abMarta, Marta, andas inquieta y preocupada con muchas cosas; solo una es necesaria. Mar\u00eda, pues, ha escogido la parte mejor, y no le ser\u00e1 quitada\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-ast-global-color-2-color has-vivid-green-cyan-background-color has-text-color has-background has-link-color wp-elements-0c192cd5e76cac3988c4c9fb3045ec50\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Hoy en d\u00eda se ha invertido el orden de prioridades en nuestras vidas, al levantarnos damos importancia a nuestras responsabilidades cotidianas, y escuchar y meditar en la Palabra de Dios, o contemplar la presencia de Jesucristo en nuestras vidas esta en \u00faltimo lugar, est\u00e1 ultima se da si no terminas agotado(a), iniciamos el d\u00eda preocupados, atareados, acelerados y hasta ansiosos de querer hacer todo al tiempo, pero estas cosas nos est\u00e1n robando la oportunidad de tener una relaci\u00f3n estrecha con el Se\u00f1or.<\/li>\n\n\n\n<li>Marta y Mar\u00eda son un vivo reflejo de la sociedad de estos tiempos, pero debemos ver que la actitud de Marta es de servicio, pero un servicio no cimentado en el Maestro, mientras que la actitud de Mar\u00eda es contemplativa al estar en la presencia de Jes\u00fas, ambas actitudes son buenas pero se deben complementar, es decir, orar y trabajar, ser activos y contemplativos, es una realidad que debemos tener una vida activa para sustentarnos, en el caso de Marta serv\u00eda para brindar a Jesucristo algo de comer, pero termino por perderse la mejor parte, que har\u00eda que sus tareas fueran m\u00e1s productivas al darle a Jes\u00fas el primer lugar.<\/li>\n\n\n\n<li>\u00bfC\u00f3mo es tu d\u00eda a d\u00eda? , \u00bfJesucristo se convierte en el centro de tu vida o est\u00e1 como una opci\u00f3n para ti?, acoger la Palabra de Dios me permite que mi servicio vaya dirigido por el Se\u00f1or, debemos mantener un equilibrio entre la oraci\u00f3n y el trabajo, no busquemos esto como pretexto para dejar de ser diligentes, sino que teniendo como fundamento la contemplaci\u00f3n en lo divino podremos avanzar en el servicio seg\u00fan la voluntad de Dios en los espacios, ambientes ,lugares donde me desarrollo personalmente.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Buscar un espacio del d\u00eda y encomendar a Dios mis tareas cotidianas. Tener un oratorio en mi hogar.<\/li>\n\n\n\n<li>San Apolinar nos ense\u00f1a que los Evangelios nos ense\u00f1an a vivir conforme a la voluntad de Dios.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN APOLINAR (310-390) San Apolinar nacido en Antioquia (Turqu\u00eda), seg\u00fan la tradici\u00f3n de la iglesia, San Apolinar acompa\u00f1o a San Pedro en la fundaci\u00f3n de la Iglesia en Roma despu\u00e9s de la resurrecci\u00f3n de Cristo, gobernando Claudio, san Apolinar fue enviado a Italia para evangelizar y convertir personas al cristianismo, fue el &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2025\/07\/20\/domingo-decimosexta-semana-del-tiempo-ordinario20-de-juliociclo-c\/\"> <span class=\"screen-reader-text\">DOMINGO, Decimosexta Semana del Tiempo Ordinario,20 de julio,(Ciclo c)<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":6568,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6566","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/07\/20-de-julio.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/07\/20-de-julio.jpg",1280,854,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/07\/20-de-julio-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/07\/20-de-julio-300x200.jpg",300,200,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/07\/20-de-julio-768x512.jpg",768,512,true],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/07\/20-de-julio-1024x683.jpg",1024,683,true],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/07\/20-de-julio.jpg",1280,854,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/07\/20-de-julio.jpg",1280,854,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SAN APOLINAR (310-390) San Apolinar nacido en Antioquia (Turqu\u00eda), seg\u00fan la tradici\u00f3n de la iglesia, San Apolinar acompa\u00f1o a San Pedro en la fundaci\u00f3n de la Iglesia en Roma despu\u00e9s de la resurrecci\u00f3n de Cristo, gobernando Claudio, san Apolinar fue enviado a Italia para evangelizar y convertir personas al cristianismo, fue el&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/6566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=6566"}],"version-history":[{"count":4,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/6566\/revisions"}],"predecessor-version":[{"id":6572,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/6566\/revisions\/6572"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/6568"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=6566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=6566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=6566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}