{"id":6245,"date":"2025-05-31T17:29:36","date_gmt":"2025-05-31T22:29:36","guid":{"rendered":"https:\/\/devocionario.net\/?p=6245"},"modified":"2025-05-31T17:29:40","modified_gmt":"2025-05-31T22:29:40","slug":"domingo-septima-semana-de-pascua-01-de-junio-ciclo-c","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2025\/05\/31\/domingo-septima-semana-de-pascua-01-de-junio-ciclo-c\/","title":{"rendered":"DOMINGO, S\u00e9ptima Semana de Pascua, 01 de junio, (Ciclo C)"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"427\" height=\"640\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/05\/01-DE-JUNIO.jpg\" alt=\"\" class=\"wp-image-6247\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/05\/01-DE-JUNIO.jpg 427w, https:\/\/devocionario.net\/wp-content\/uploads\/2025\/05\/01-DE-JUNIO-200x300.jpg 200w\" sizes=\"(max-width: 427px) 100vw, 427px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color has-link-color wp-elements-86eddde2ced6e22d1beb09c4b6cf6d56\"><strong>SOLEMNIDAD DE LA ASCENSION DEL SE\u00d1OR<\/strong><\/p>\n\n\n\n<p><strong> <\/strong>Hoy la Iglesia Cat\u00f3lica celebra la solemnidad de la Ascensi\u00f3n del Se\u00f1or, cuarenta d\u00edas despu\u00e9s de la Resurrecci\u00f3n, fue elevado al Cielo delante de sus disc\u00edpulos, para sentarse a la derecha del Padre, hasta que venga en su gloria para juzgar a vivos y muertos, esta fiesta se comenz\u00f3 a celebrar en el siglo V.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San \u00a0Lucas 24, 46-53<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, dijo Jes\u00fas a sus disc\u00edpulos:<br>\u00abAs\u00ed est\u00e1 escrito: el Mes\u00edas padecer\u00e1, resucitar\u00e1 de entre los muertos al tercer d\u00eda y en su nombre se proclamar\u00e1 la conversi\u00f3n para el perd\u00f3n de los pecados a todos los pueblos, comenzando por Jerusal\u00e9n.<\/p>\n\n\n\n<p>Vosotros sois testigos de esto. Mirad, yo voy a enviar sobre vosotros la promesa de mi Padre; vosotros, por vuestra parte, quedaos en la ciudad hasta que os revist\u00e1is de la fuerza que viene de lo alto\u00bb.<\/p>\n\n\n\n<p>Y los sac\u00f3 hasta cerca de Betania y, levantando sus manos, los bendijo.<\/p>\n\n\n\n<p>Y mientras los bendec\u00eda, se separ\u00f3 de ellos, y fue llevado hacia el cielo.<\/p>\n\n\n\n<p>Ellos se postraron ante \u00e9l y se volvieron a Jerusal\u00e9n con gran alegr\u00eda; y estaban siempre en el templo bendiciendo a Dios.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-ast-global-color-4-color has-ast-global-color-0-background-color has-text-color has-background has-link-color wp-elements-7c483f14a3fda3793a543136fe826bc7\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El Evangelio de hoy nos narra la sorprendente fiesta de la Ascensi\u00f3n del Se\u00f1or, Jes\u00fas comparte este \u00faltimo momento con sus disc\u00edpulos de manera visible, para permanecer por siempre de manera espiritual, este acontecimiento no se convierte en una partida dolorosa para sus seguidores, sino en el comienzo de una misi\u00f3n gozosa como testigos, teniendo una relaci\u00f3n m\u00e1s intima y profunda con el Maestro, verdaderamente esta partida se convierte en bendici\u00f3n, no solo para sus ap\u00f3stoles sino para nosotros en el d\u00eda de hoy, porque no estamos solos, la presencia del Espiritu Santo esta en cada uno de aquellos que quieran dar a conocer a Jesucristo, esta fue la promesa del Padre Dios hecha a quienes quieran permanecer en \u00c9l.<\/li>\n\n\n\n<li>La Ascensi\u00f3n del Se\u00f1or no solo nos motiva a recordarla como fiesta en nuestra Iglesia, sino como aquella gran tarea que tenemos de anunciar al Salvador del mundo, a ser fieles, y a cultivar el Reino de Dios en la tierra, la Ascensi\u00f3n del Se\u00f1or es un signo de esperanza, que nos mantiene firmes en la meta, el cielo, Jes\u00fas nos anima a trabajar en la Evangelizaci\u00f3n, adoptando sus ense\u00f1anzas, cumpli\u00e9ndolas, y d\u00e1ndolas a conocer a los dem\u00e1s. La bendici\u00f3n que Jesucristo da a sus ap\u00f3stoles, es la que debemos tambi\u00e9n dar los cristianos a la humanidad, desear el bien es una caracter\u00edstica de un verdadero seguidor de Cristo.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Comenzar por bendecir a todas las personas que te rodean, as\u00ed comienzas tu Evangelizaci\u00f3n.<\/li>\n\n\n\n<li>\u00bfC\u00f3mo vives la Ascensi\u00f3n?\u00bf Como iniciar\u00e1s tu propia Evangelizaci\u00f3n como verdadero Cristiano?, Es hora de iniciar tu propia misi\u00f3n.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SOLEMNIDAD DE LA ASCENSION DEL SE\u00d1OR Hoy la Iglesia Cat\u00f3lica celebra la solemnidad de la Ascensi\u00f3n del Se\u00f1or, cuarenta d\u00edas despu\u00e9s de la Resurrecci\u00f3n, fue elevado al Cielo delante de sus disc\u00edpulos, para sentarse a la derecha del Padre, hasta que venga en su gloria para juzgar a vivos y muertos, esta &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2025\/05\/31\/domingo-septima-semana-de-pascua-01-de-junio-ciclo-c\/\"> <span class=\"screen-reader-text\">DOMINGO, S\u00e9ptima Semana de Pascua, 01 de junio, (Ciclo C)<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":6247,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[29],"tags":[],"class_list":["post-6245","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pascua"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/05\/01-DE-JUNIO.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/05\/01-DE-JUNIO.jpg",427,640,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/05\/01-DE-JUNIO-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/05\/01-DE-JUNIO-200x300.jpg",200,300,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/05\/01-DE-JUNIO.jpg",427,640,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/05\/01-DE-JUNIO.jpg",427,640,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/05\/01-DE-JUNIO.jpg",427,640,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/05\/01-DE-JUNIO.jpg",427,640,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":1,"uagb_excerpt":"SANTO DEL D\u00cdA SOLEMNIDAD DE LA ASCENSION DEL SE\u00d1OR Hoy la Iglesia Cat\u00f3lica celebra la solemnidad de la Ascensi\u00f3n del Se\u00f1or, cuarenta d\u00edas despu\u00e9s de la Resurrecci\u00f3n, fue elevado al Cielo delante de sus disc\u00edpulos, para sentarse a la derecha del Padre, hasta que venga en su gloria para juzgar a vivos y muertos, esta&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/6245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=6245"}],"version-history":[{"count":4,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/6245\/revisions"}],"predecessor-version":[{"id":6254,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/6245\/revisions\/6254"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/6247"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=6245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=6245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=6245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}