{"id":6148,"date":"2025-05-15T19:55:50","date_gmt":"2025-05-16T00:55:50","guid":{"rendered":"https:\/\/devocionario.net\/?p=6148"},"modified":"2025-05-15T19:55:52","modified_gmt":"2025-05-16T00:55:52","slug":"viernes-cuarta-semana-de-pascua16-de-mayo-ciclo-c","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2025\/05\/15\/viernes-cuarta-semana-de-pascua16-de-mayo-ciclo-c\/","title":{"rendered":"VIERNES, Cuarta Semana De Pascua,16 de Mayo- (ciclo c)"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/05\/16-de-mayo.jpg\" alt=\"\" class=\"wp-image-6151\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/05\/16-de-mayo.jpg 640w, https:\/\/devocionario.net\/wp-content\/uploads\/2025\/05\/16-de-mayo-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color has-link-color wp-elements-681bbd87e5af220fa16c0a2134ef8c4d\"><strong>SAN JUAN NEPOMUCENO (1350-1393)<\/strong><\/p>\n\n\n\n<p>San Juan nace en Bohemia (Checoslovaquia) , en un pueblo llamado Nopomuc, fue p\u00e1rroco de Praga y obtuvo el doctorado en la Universidad de Padua, ocup\u00f3 el alto puesto de Vicario General del Arzobispado. El rey de Praga, Wenceslao, ten\u00eda dos pecados la c\u00f3lera y los celos, Juan Nepomuceno confesor de la reina, fue obligado por el rey a contar los pecados que la reina le hab\u00eda dicho en confesi\u00f3n, y al no conseguirlo, se propuso matarlo. El Vicario Juan Nepomuceno tambi\u00e9n se opuso a que vendieran un convento, pues esos bienes pertenec\u00edan a la Santa Iglesia, entonces el rey se llen\u00f3 de c\u00f3lera, el Santo fue torturado y su cuerpo arrojado al r\u00edo Mondalva, cuando recogieron el cuerpo su lengua estaba incorrupta.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Juan 14, 1-6<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, dijo Jes\u00fas a sus disc\u00edpulos:<br>\u00abNo se turbe vuestro coraz\u00f3n, creed en Dios y creed tambi\u00e9n en m\u00ed. En la casa de mi Padre hay muchas moradas; si no, os lo habr\u00eda dicho, porque me voy a prepararos un lugar. Cuando vaya y os prepare un lugar, volver\u00e9 y os llevar\u00e9 conmigo, para que donde estoy yo est\u00e9is tambi\u00e9n vosotros. Y adonde yo voy, ya sab\u00e9is el camino\u00bb.<\/p>\n\n\n\n<p>Tom\u00e1s le dice:<br>\u00abSe\u00f1or, no sabemos ad\u00f3nde vas, \u00bfc\u00f3mo podemos saber el camino?\u00bb.<\/p>\n\n\n\n<p>Jes\u00fas le responde:<br>\u00abYo soy el camino y la verdad y la vida. Nadie va al Padre sino por m\u00ed\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-ast-global-color-4-color has-ast-global-color-0-background-color has-text-color has-background has-link-color wp-elements-7c483f14a3fda3793a543136fe826bc7\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-ast-global-color-2-color has-text-color has-link-color wp-elements-ad0f306573ebdbc054d218c9a269f4f7\"><strong>Un buen cristiano debe creer siempre<\/strong> que el cielo es su morada, por tanto nuestro coraz\u00f3n no debe estar turbado, hay una promesa dada por el resucitado: que hay muchas moradas preparadas y gozaremos eternamente con \u00e9l.<\/li>\n\n\n\n<li>La duda puede acechar nuestra humanidad como le sucedi\u00f3 a Tom\u00e1s, Jes\u00fas le recuerda con amor, que  \u00c9l es el camino, la verdad y la vida, es por eso que nuestra existencia siempre estar\u00e1 al seguro en el caminar del d\u00eda a d\u00eda por este mundo, porque tenemos la certeza, que la persona adorable de Jes\u00fas siempre estar\u00e1 a nuestro lado, motiv\u00e1ndonos, ense\u00f1\u00e1ndonos a perseverar para llegar un d\u00eda al premio celestial.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Hablarle a un amigo de la promesa del cielo.<\/li>\n\n\n\n<li>San Juan Nepomuceno nos ense\u00f1a que la confesi\u00f3n es un paso para arrepentirnos, convertirnos y llegar al cielo.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN JUAN NEPOMUCENO (1350-1393) San Juan nace en Bohemia (Checoslovaquia) , en un pueblo llamado Nopomuc, fue p\u00e1rroco de Praga y obtuvo el doctorado en la Universidad de Padua, ocup\u00f3 el alto puesto de Vicario General del Arzobispado. El rey de Praga, Wenceslao, ten\u00eda dos pecados la c\u00f3lera y los celos, Juan &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2025\/05\/15\/viernes-cuarta-semana-de-pascua16-de-mayo-ciclo-c\/\"> <span class=\"screen-reader-text\">VIERNES, Cuarta Semana De Pascua,16 de Mayo- (ciclo c)<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":6151,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[29],"tags":[],"class_list":["post-6148","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pascua"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/05\/16-de-mayo.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/05\/16-de-mayo.jpg",640,427,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/05\/16-de-mayo-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/05\/16-de-mayo-300x200.jpg",300,200,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/05\/16-de-mayo.jpg",640,427,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/05\/16-de-mayo.jpg",640,427,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/05\/16-de-mayo.jpg",640,427,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/05\/16-de-mayo.jpg",640,427,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SAN JUAN NEPOMUCENO (1350-1393) San Juan nace en Bohemia (Checoslovaquia) , en un pueblo llamado Nopomuc, fue p\u00e1rroco de Praga y obtuvo el doctorado en la Universidad de Padua, ocup\u00f3 el alto puesto de Vicario General del Arzobispado. El rey de Praga, Wenceslao, ten\u00eda dos pecados la c\u00f3lera y los celos, Juan&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/6148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=6148"}],"version-history":[{"count":3,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/6148\/revisions"}],"predecessor-version":[{"id":6152,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/6148\/revisions\/6152"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/6151"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=6148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=6148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=6148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}