{"id":5625,"date":"2025-02-12T19:27:05","date_gmt":"2025-02-13T00:27:05","guid":{"rendered":"https:\/\/devocionario.net\/?p=5625"},"modified":"2025-02-12T19:27:08","modified_gmt":"2025-02-13T00:27:08","slug":"jueves-13-de-febrero-quinta-semana-del-tiempo-ordinario-ciclo-c-2025","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2025\/02\/12\/jueves-13-de-febrero-quinta-semana-del-tiempo-ordinario-ciclo-c-2025\/","title":{"rendered":"JUEVES,-13 de Febrero-Quinta Semana del Tiempo Ordinario (ciclo C)-2025"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/02\/13-de-febrero.jpg\" alt=\"\" class=\"wp-image-5627\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/02\/13-de-febrero.jpg 640w, https:\/\/devocionario.net\/wp-content\/uploads\/2025\/02\/13-de-febrero-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color has-link-color wp-elements-4ad6af34cb69a1673530beb02b3a43d4\"><strong>SANTAS FUSCA Y MAURA (Siglo III )<\/strong><\/p>\n\n\n\n<p>Santa Fusca fue una joven nacida en Ravena (Italia), anhelaba convertirse al cristianismo, en la \u00e9poca de la persecuci\u00f3n a los cristianos a manos de Decio, esta mujer habl\u00f3 a su nodriza la animo a que se convirtiera como ella a la fe en Jes\u00fas, para bautizarse buscaron a un sacerdote llamado Hermoloro, de esto se enter\u00f3 el Padre de Fusca y se enojo tanto que busco la manera de devolver a su hija al paganismo, pero al no conseguirlo la denuncia ante el gobernador Quintiliano, este env\u00eda a tomar presas a las santas, pero aquellos hombres ven a un \u00e1ngel cerca de ellas y desisten de retenerlas, entonces estas mujeres voluntariamente fueron a presentarse y exponer su creencia en Jesucristo, fueron cruelmente flageladas y muertas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Marcos 7,24-30<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, Jes\u00fas fue a la regi\u00f3n de Tiro.<\/p>\n\n\n\n<p>Entr\u00f3 en una casa procurando pasar desapercibido, pero no logr\u00f3 ocultarse.<\/p>\n\n\n\n<p>Una mujer que ten\u00eda una hija pose\u00edda por un esp\u00edritu impuro se enter\u00f3 enseguida, fue a buscarlo y se le ech\u00f3 a los pies.<\/p>\n\n\n\n<p>La mujer era pagana, una fenicia de Siria, y le rogaba que echase el demonio de su hija.<\/p>\n\n\n\n<p>\u00c9l le dijo:<br>\u00abDeja que se sacien primero los hijos. No est\u00e1 bien tomar el pan de los hijos y ech\u00e1rselo a los perritos\u00bb.<\/p>\n\n\n\n<p>Pero ella replic\u00f3:<br>\u00abSe\u00f1or, pero tambi\u00e9n los perros, debajo de la mesa, comen las migajas que tiran los ni\u00f1os\u00bb.<\/p>\n\n\n\n<p>\u00c9l le contest\u00f3:<br>\u00abAnda, vete, que por eso que has dicho, el demonio ha salido de tu hija\u00bb.<\/p>\n\n\n\n<p>Al llegar a su casa, se encontr\u00f3 a la ni\u00f1a echada en la cama; el demonio se hab\u00eda marchado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-green-cyan-background-color has-background\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00bfHas sentido alguna vez que Jes\u00fas te pone a prueba para aumentar tu fe, para que conf\u00edes en \u00e9l?, \u00bfEstas en un momento de tu vida en el que quieres desfallecer como aquella mujer pagana, en la que el orgullo sobra, porque la necesidad es mayor?, ella no se sinti\u00f3 ofendida con la respuesta de Jesucristo, sino que insiste en aquello que anhela su coraz\u00f3n, que su hija sane, conf\u00eda en la misericordia de aquel de quien depende por completo.<\/li>\n\n\n\n<li>Que gran ejemplo nos ense\u00f1a aquella pagana, que gran acto de misericordia de parte de Dios, queridos hermanos a veces solo basta pararnos en nuestra propia verdad , tener humildad y dejar que la misericordia de Dios Padre inunde el escenario de nuestro coraz\u00f3n. A veces me asombra cuantas personas que no creen en Dios act\u00faan como si lo tuvieran dentro, insisten en hacer el bien, reconocen que la presencia de un ser supremo lo cambia todo, as\u00ed no haya pr\u00e1cticas religiosas de por medio, no dejemos que nuestro pecado nos averg\u00fcence hasta tal punto que nos aleje de Dios, de su presencia, ante \u00e9l somos fr\u00e1giles, d\u00e9biles, faltos de su amor, \u00e9l mira las miserias nuestras y nos levanta. \u00bf Has trabajado tu fe de manera que sea inquebrantable a base de tus desaf\u00edos de cada d\u00eda?\u00bfSon acaso los obst\u00e1culos de aceptar a Jes\u00fas en tu vida las barreras, que tu mismo creas? <em>\u201cLa fe se refiere a las cosas que no se ven, y la esperanza a las cosas que no est\u00e1n al alcance de la mano\u201d.<\/em> <strong>Santo Tom\u00e1s de Aquino.<\/strong><\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">&nbsp;&nbsp;<strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Hacer el rosario de la divina misericordia todos los d\u00edas., por nuestra conversi\u00f3n y la de los dem\u00e1s.<\/li>\n\n\n\n<li>San Fusca y Maura nos ense\u00f1an el valor de la fe para tener a Dios en el interior.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SANTAS FUSCA Y MAURA (Siglo III ) Santa Fusca fue una joven nacida en Ravena (Italia), anhelaba convertirse al cristianismo, en la \u00e9poca de la persecuci\u00f3n a los cristianos a manos de Decio, esta mujer habl\u00f3 a su nodriza la animo a que se convirtiera como ella a la fe en Jes\u00fas, &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2025\/02\/12\/jueves-13-de-febrero-quinta-semana-del-tiempo-ordinario-ciclo-c-2025\/\"> <span class=\"screen-reader-text\">JUEVES,-13 de Febrero-Quinta Semana del Tiempo Ordinario (ciclo C)-2025<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":5627,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5625","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/02\/13-de-febrero.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/02\/13-de-febrero.jpg",640,427,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/02\/13-de-febrero-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/02\/13-de-febrero-300x200.jpg",300,200,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/02\/13-de-febrero.jpg",640,427,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/02\/13-de-febrero.jpg",640,427,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/02\/13-de-febrero.jpg",640,427,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/02\/13-de-febrero.jpg",640,427,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SANTAS FUSCA Y MAURA (Siglo III ) Santa Fusca fue una joven nacida en Ravena (Italia), anhelaba convertirse al cristianismo, en la \u00e9poca de la persecuci\u00f3n a los cristianos a manos de Decio, esta mujer habl\u00f3 a su nodriza la animo a que se convirtiera como ella a la fe en Jes\u00fas,&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/5625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=5625"}],"version-history":[{"count":3,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/5625\/revisions"}],"predecessor-version":[{"id":5629,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/5625\/revisions\/5629"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/5627"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=5625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=5625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=5625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}