{"id":5510,"date":"2025-01-21T17:04:20","date_gmt":"2025-01-21T22:04:20","guid":{"rendered":"https:\/\/devocionario.net\/?p=5510"},"modified":"2025-01-21T17:04:22","modified_gmt":"2025-01-21T22:04:22","slug":"viernes-24-de-enero-segunda-semana-del-tiempo-ordinario-ciclo-c-2025","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2025\/01\/21\/viernes-24-de-enero-segunda-semana-del-tiempo-ordinario-ciclo-c-2025\/","title":{"rendered":"VIERNES,-24 de Enero-Segunda Semana del Tiempo Ordinario (ciclo C)-2025"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"612\" height=\"408\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/24-de-enero.jpg\" alt=\"\" class=\"wp-image-5511\" style=\"width:609px;height:auto\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/24-de-enero.jpg 612w, https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/24-de-enero-300x200.jpg 300w\" sizes=\"(max-width: 612px) 100vw, 612px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-black-color has-text-color\"><strong>SAN FRANCISCO DE SALES (1567-1622)<\/strong><\/p>\n\n\n\n<p>San Francisco nace en castillo de Sales en Saboya, bautizado al d\u00eda siguiente de nacido, desde ni\u00f1o sufr\u00eda quebrantos de salud pues naci\u00f3 prematuro, su Madre piadosa le ense\u00f1aba catequesis que \u00e9l repet\u00eda a quienes ve\u00eda, su Padre le consigue un profesor riguroso para que no se convirtiera en un ni\u00f1o mimado ya que su Madre lo cuidaba mucho y la pasaba con ella la mayor parte del tiempo, era ordenado debido a que se trazaba programas para el d\u00eda a d\u00eda, siempre destinando tiempo para orar ante el Sant\u00edsimo Sacramento, confesarse y asistir a misa, se distingui\u00f3 en ret\u00f3rica y en filosof\u00eda; despu\u00e9s se entreg\u00f3 apasionadamente al estudio de la teolog\u00eda, se ordena sacerdote fue obispo de Ginebra, fund\u00f3 junto con santa Juana de Chantal la Orden de la Visitaci\u00f3n, escribi\u00f3  tres libros famosos : &#8220;Las controversias&#8221;(contra los protestantes); La Introducci\u00f3n a la Vida Devota&#8221; (o Filotea) y El Tratado del Amor de Dios (o Te\u00f3timo), tanto como la colecci\u00f3n de sus sermones, San Francisco de Sales es Doctor de la Iglesia siendo llamado &#8220;El Doctor de la amabilidad&#8221;.<\/p>\n\n\n\n<p>&#8220;Puse toda mi esperanza en el Se\u00f1or, y me oy\u00f3 y escuch\u00f3 mis s\u00faplicas y me sac\u00f3 del foso de la miseria y del pantano de la iniquidad&#8221;.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>Marcos 3, 13-19<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, Jes\u00fas subi\u00f3 al monte, llam\u00f3 a los que \u00e9l quiso, y ellos lo siguieron. Constituy\u00f3 a doce para que se quedaran con \u00e9l, para mandarlos a predicar y para que tuvieran el poder de expulsar a los demonios.<\/p>\n\n\n\n<p>Constituy\u00f3 entonces a los Doce: a Sim\u00f3n, al cual le impuso el nombre de Pedro; despu\u00e9s, a Santiago y a Juan, hijos de Zebedeo, a quienes dio el nombre de Boanergues, es decir \u201chijos del trueno\u201d; a Andr\u00e9s, Felipe, Bartolom\u00e9, Mateo, Tom\u00e1s, Santiago el de Alfeo, Tadeo, Sim\u00f3n el Cananeo y a Judas Iscariote, que despu\u00e9s lo traicion\u00f3<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color has-link-color wp-elements-c3aceebcb6fa48cdd589f1f1fca27705\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00bfCu\u00e1l es tu vocaci\u00f3n en esta tierra?, \u00bfTe sientes inseguro con lo que eres y haces?, d\u00e9jame decirte que \u00e9l Se\u00f1or, elige a los torpes, a los humildes, a quienes tienen miedo, a quienes no conf\u00edan en sus potencialidades, Jesucristo no dud\u00f3 en escoger hombre comunes y corrientes para anunciar su mensaje, as\u00ed como en la historia de la salvaci\u00f3n y hasta el d\u00eda de hoy el Se\u00f1or escoge, sigue llamando a pesar de nuestras limitaciones.<\/li>\n\n\n\n<li>Jesucristo elige a quien quiere pues su gracia, su amor triunfa en la debilidad, la ideolog\u00eda de Jes\u00fas nos dice &#8220;cuando soy d\u00e9bil soy m\u00e1s fuerte&#8221;, Dios nos elige para s\u00ed y nos env\u00eda a otros, te has puesto a pensar \u00bfQu\u00e9 har\u00e9 con mi vida?, has estado en ese momento dif\u00edcil en el que no sabes que hacer, est\u00e1 respuesta s\u00f3lo las puede responder nuestro Dios que si conoce nuestro verdadero prop\u00f3sito en este mundo, as\u00ed que si te sientes as\u00ed s\u00f3lo ora y espera su voluntad, Dios quiere nuestra respuesta sin prisa pero sin pausa, bendiciones.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Buscar mi verdadera vocaci\u00f3n en esta tierra.<\/li>\n\n\n\n<li>San Francisco de Sales nos dice: <em>\u201cTened paciencia con todos, pero sobre todo con vosotros mismos; quiero decir que no os turb\u00e9is por vuestros defectos y que teng\u00e1is siempre el valor de liberaros de ellos. Me contento con que volv\u00e1is a comenzar cada d\u00eda; no hay mejor medio de perfecci\u00f3n que la propia vida espiritual que recomenc\u00e9is siempre sin pensar que ya hab\u00e9is hecho bastante\u201d.<\/em><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN FRANCISCO DE SALES (1567-1622) San Francisco nace en castillo de Sales en Saboya, bautizado al d\u00eda siguiente de nacido, desde ni\u00f1o sufr\u00eda quebrantos de salud pues naci\u00f3 prematuro, su Madre piadosa le ense\u00f1aba catequesis que \u00e9l repet\u00eda a quienes ve\u00eda, su Padre le consigue un profesor riguroso para que no se &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2025\/01\/21\/viernes-24-de-enero-segunda-semana-del-tiempo-ordinario-ciclo-c-2025\/\"> <span class=\"screen-reader-text\">VIERNES,-24 de Enero-Segunda Semana del Tiempo Ordinario (ciclo C)-2025<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":5511,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5510","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/24-de-enero.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/24-de-enero.jpg",612,408,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/24-de-enero-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/24-de-enero-300x200.jpg",300,200,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/24-de-enero.jpg",612,408,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/24-de-enero.jpg",612,408,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/24-de-enero.jpg",612,408,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/24-de-enero.jpg",612,408,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SAN FRANCISCO DE SALES (1567-1622) San Francisco nace en castillo de Sales en Saboya, bautizado al d\u00eda siguiente de nacido, desde ni\u00f1o sufr\u00eda quebrantos de salud pues naci\u00f3 prematuro, su Madre piadosa le ense\u00f1aba catequesis que \u00e9l repet\u00eda a quienes ve\u00eda, su Padre le consigue un profesor riguroso para que no se&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/5510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=5510"}],"version-history":[{"count":2,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/5510\/revisions"}],"predecessor-version":[{"id":5513,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/5510\/revisions\/5513"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/5511"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=5510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=5510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=5510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}