{"id":5485,"date":"2025-01-18T14:32:54","date_gmt":"2025-01-18T19:32:54","guid":{"rendered":"https:\/\/devocionario.net\/?p=5485"},"modified":"2025-01-18T14:32:56","modified_gmt":"2025-01-18T19:32:56","slug":"lunes-20-de-enero-segunda-semana-del-tiempo-ordinario-ciclo-c-2025","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2025\/01\/18\/lunes-20-de-enero-segunda-semana-del-tiempo-ordinario-ciclo-c-2025\/","title":{"rendered":"LUNES,-20 de Enero-Segunda Semana del Tiempo Ordinario (ciclo C)-2025"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/20-DE-ENERO-1024x682.jpg\" alt=\"\" class=\"wp-image-5486\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/20-DE-ENERO-1024x682.jpg 1024w, https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/20-DE-ENERO-300x200.jpg 300w, https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/20-DE-ENERO-768x512.jpg 768w, https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/20-DE-ENERO.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\"><strong>SAN SEBASTIAN (+288)<\/strong><\/p>\n\n\n\n<p>San Sebasti\u00e1n nace en Narbona (Francia), su educaci\u00f3n la obtuvo en Mil\u00e1n, su Padre era militar y noble, al criarse en este ambiente fue capit\u00e1n de la primera corte de la guardia pretoriana (era un cuerpo militar que serv\u00eda de escolta y protecci\u00f3n a los emperadores romanos), participaba de la disciplina militar pero no de sus actos paganos, pues era cristiano cualidad que desconoc\u00eda el emperador, animaba a los presos d\u00e1ndoles a conocer el amor de Cristo, tiempo despu\u00e9s al enterarse el emperador Maximino lo puso a elegir entre Jesucristo o ser soldado pagano, era claro que San Sebasti\u00e1n eligi\u00f3 la milicia de Cristo entonces el emperador se enojo tanto que mand\u00f3 a sus soldados que lo llevaran al estadio lo desnudaran y lo amarraran a un poste y ah\u00ed enviaron una lluvia de saetas, pensando los soldados que hab\u00eda muerto lo dejaron, inmediatamente sus amigos lo llevaron y lo escondieron donde una cristiana romana de nombre Irene, all\u00ed se recuper\u00f3. Luego sus compa\u00f1eros le dijeron que se ausentara de Roma pero \u00e9l se neg\u00f3 y presento ante el emperador para anunciar a Jesucristo este a su vez lo mand\u00f3 azotar hasta su muerte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Marcos 2,18-22<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, como los disc\u00edpulos de Juan y los fariseos estaban ayunando, vinieron unos y le preguntaron a Jes\u00fas:<br>\u00abLos disc\u00edpulos de Juan y los disc\u00edpulos de los fariseos ayunan. \u00bfPor qu\u00e9 los tuyos no?\u00bb.<\/p>\n\n\n\n<p>Jes\u00fas les contesta:<br>\u00ab\u00bfEs que pueden ayunar los amigos del esposo, mientras el esposo est\u00e1 con ellos? Mientras el esposo est\u00e1 con ellos, no pueden ayunar.<\/p>\n\n\n\n<p>Llegar\u00e1n d\u00edas en que les arrebatar\u00e1n al esposo, y entonces ayunar\u00e1n en aquel d\u00eda.<\/p>\n\n\n\n<p>Nadie echa un remiendo de pa\u00f1o sin remojar a un manto pasado; porque la pieza tira del manto \u2014lo nuevo de lo viejo\u2014 y deja un roto peor.<\/p>\n\n\n\n<p>Tampoco se echa vino nuevo en odres viejos; porque el vino revienta los odres, y se pierden el vino y los odres; a vino nuevo, odres nuevos\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color has-link-color wp-elements-c3aceebcb6fa48cdd589f1f1fca27705\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Jesucristo quiere dar a conocer la nueva creaci\u00f3n que se da mediante su presencia en la tierra, \u00e9l lo hace todo nuevo, pues ofrece una vida basada en la misericordia y el amor, pero los fariseos ve\u00edan s\u00f3lo lo externo, preocupados por una pr\u00e1ctica piadosa aun no reconocen a Jes\u00fas, es verdad que el ayuno es necesario para mantenerse firme en la meta que persiguen, pero el Maestro todav\u00eda estaba con ellos y su luz es m\u00e1s que suficiente para mantenerse en pie. Jesucristo no quiere abolir el ayuno sino quiere llevar a la integralidad al ser humano, estando con \u00e9l cada experiencia con Dios cobra valor.<\/li>\n\n\n\n<li>Jes\u00fas una vez m\u00e1s nos invita a estar alegres, esa es la verdadera caracter\u00edstica de un cristiano autentico, pues como vamos a estar tristes y preocupados si a\u00fan el novio est\u00e1 con nosotros, pero esto se logra mediante la esperanza que debemos conservar en cada uno de nuestros corazones, no debe haber ninguna clase de duelo mientras Jes\u00fas camina con nosotros.<\/li>\n\n\n\n<li>El ayuno es en cierta manera  una experiencia que nos motiva al autocontrol personal, y es sin duda alguna una herramienta eficaz para santificarnos, pero nuestra espiritualidad no debe fundamentarse en lo externo sino trabajar en nuestro interior, Jesucristo nos ense\u00f1a a ser libres, amas por que quieres, sigues a Jes\u00fas porque quieres agradar a Dios, vas a la Iglesia porque la Palabra de Dios y la Eucarist\u00eda de alimentan internamente al punto que te haces mejor persona, nuestra espiritualidad en estos tiempos o deben estar aferradas a pr\u00e1cticas piadosas solamente, sino ligada a la fuerza del Espiritu Santo.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ayunar en los tiempos que la Iglesia Cat\u00f3lica env\u00eda, pero hacerlo con el fin de obtener virtudes, como la paciencia, humildad, etc.<\/li>\n\n\n\n<li>San Sebasti\u00e1n nos ense\u00f1a que debemos abandonarnos en Dios, &#8220;Quien pierde su vida por mi la encontrar\u00e1&#8221;<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN SEBASTIAN (+288) San Sebasti\u00e1n nace en Narbona (Francia), su educaci\u00f3n la obtuvo en Mil\u00e1n, su Padre era militar y noble, al criarse en este ambiente fue capit\u00e1n de la primera corte de la guardia pretoriana (era un cuerpo militar que serv\u00eda de escolta y protecci\u00f3n a los emperadores romanos), participaba de &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2025\/01\/18\/lunes-20-de-enero-segunda-semana-del-tiempo-ordinario-ciclo-c-2025\/\"> <span class=\"screen-reader-text\">LUNES,-20 de Enero-Segunda Semana del Tiempo Ordinario (ciclo C)-2025<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":5486,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-5485","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tiempo-ordinario"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/20-DE-ENERO.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/20-DE-ENERO.jpg",1280,853,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/20-DE-ENERO-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/20-DE-ENERO-300x200.jpg",300,200,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/20-DE-ENERO-768x512.jpg",768,512,true],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/20-DE-ENERO-1024x682.jpg",1024,682,true],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/20-DE-ENERO.jpg",1280,853,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/20-DE-ENERO.jpg",1280,853,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SAN SEBASTIAN (+288) San Sebasti\u00e1n nace en Narbona (Francia), su educaci\u00f3n la obtuvo en Mil\u00e1n, su Padre era militar y noble, al criarse en este ambiente fue capit\u00e1n de la primera corte de la guardia pretoriana (era un cuerpo militar que serv\u00eda de escolta y protecci\u00f3n a los emperadores romanos), participaba de&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/5485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=5485"}],"version-history":[{"count":3,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/5485\/revisions"}],"predecessor-version":[{"id":5489,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/5485\/revisions\/5489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/5486"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=5485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=5485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=5485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}