{"id":5462,"date":"2025-01-09T17:55:17","date_gmt":"2025-01-09T22:55:17","guid":{"rendered":"https:\/\/devocionario.net\/?p=5462"},"modified":"2025-01-09T17:55:20","modified_gmt":"2025-01-09T22:55:20","slug":"jueves-16-de-enero-primera-semana-del-tiempo-ordinario-ciclo-c-2025","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2025\/01\/09\/jueves-16-de-enero-primera-semana-del-tiempo-ordinario-ciclo-c-2025\/","title":{"rendered":"JUEVES,-16 de Enero-Primera Semana del Tiempo Ordinario (ciclo C)-2025"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/16-DE-ENERO.jpg\" alt=\"\" class=\"wp-image-5463\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/16-DE-ENERO.jpg 640w, https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/16-DE-ENERO-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\"><strong>SAN MARCELO I (+309)<\/strong><\/p>\n\n\n\n<p>San Marcelo I fue el Papa n\u00famero 30 de la Iglesia Cat\u00f3lica, sucedi\u00f3 al Papa Marcelino despu\u00e9s de que este muriera , su pontificado dur\u00f3 tan solo un a\u00f1o, en \u00e9l se dedic\u00f3 a reorganizar las Iglesias pues estas hab\u00edan sido da\u00f1adas por causa de la persecuci\u00f3n de Diocleciano, comenz\u00f3 a restaurar templos, animar a los cristianos y a mantenerles su fe, dividi\u00f3 Roma en veinticinco (25) sectores y les asigno p\u00e1rrocos e hizo volver a muchos a la religi\u00f3n que hab\u00edan renegado de su fe, sin antes hacer acto de penitencia, m\u00e1s adelante muchos no estaban contentos con su labor apost\u00f3lica y deciden acusarlo ante el emperador Majencio, quien desterr\u00f3 al Santo expuls\u00e1ndolo de Roma, luego San Marcelo se hospeda en la casa de una laica y desde ah\u00ed animaba la fe de los laicos, luego el emperador al enterarse lo destierra y lo lleva a trabajar en zonas de caballer\u00eda y pesebreras de la zona, muere en el exilio<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong> San<\/strong> <strong>Marcos 1, 40-45<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, se le acerc\u00f3 a Jes\u00fas un leproso para suplicarle de rodillas: \u201cSi t\u00fa quieres, puedes curarme\u201d. Jes\u00fas se compadeci\u00f3 de \u00e9l, y extendiendo la mano, lo toc\u00f3 y le dijo: \u201c\u00a1S\u00ed quiero: sana!\u201d Inmediatamente se le quit\u00f3 la lepra y qued\u00f3 limpio.<\/p>\n\n\n\n<p>Al despedirlo, Jes\u00fas le mand\u00f3 con severidad: \u201cNo se lo cuentes a nadie; pero para que conste, ve a presentarte al sacerdote y ofrece por tu purificaci\u00f3n lo prescrito por Mois\u00e9s\u201d.<\/p>\n\n\n\n<p>Pero aquel hombre comenz\u00f3 a divulgar tanto el hecho, que Jes\u00fas no pod\u00eda ya entrar abiertamente en la ciudad, sino que se quedaba fuera, en lugares solitarios, a donde acud\u00edan a \u00e9l de todas partes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color has-link-color wp-elements-c3aceebcb6fa48cdd589f1f1fca27705\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En el Evangelio de este d\u00eda una vez m\u00e1s el Maestro sana, devuelve la dignidad a un hombre atado con la enfermedad de la lepra y discriminado por la comunidad, quien padec\u00eda de esta enfermedad estaba contaminado a causa del pecado seg\u00fan la ley.<\/li>\n\n\n\n<li>Jesucristo no tiene miedo de contaminarse, \u00e9l ve el coraz\u00f3n de los marginados, escucha su suplica y devuelve aquello que se ha perdido, la sanaci\u00f3n no solo del cuerpo se hab\u00eda dado en aquel hombre tambi\u00e9n la purificaci\u00f3n de su alma, a este leproso no le import\u00f3 m\u00e1s que reconocer en Jes\u00fas a su salvador, ya no val\u00eda ley, val\u00eda el amor de Dios para con \u00e9l. Jes\u00fas tambi\u00e9n advierte de presentarse ante los sacerdote pues como jud\u00edo comprend\u00eda las leyes judaicas y sabe que son necesarias.<\/li>\n\n\n\n<li>Las lepras de nuestra vida, el odio, el dolor, la enfermedad, la soledad, etc, nos aprisionan y debilitan nuestra voluntad, cuando vienen los momentos en que somos puestos aprueba nuestra confianza no est\u00e1 en Jes\u00fas, porque hemos moldeado nuestra persona fuera de la gracia que proviene de Dios, es Cristo mismo quien nos busca, que llama nuestra atenci\u00f3n, y no comprendemos que lo hace a trav\u00e9s de nuestras cruces de d\u00eda a d\u00eda que mal vistas por nosotros son oportunidades para acercarnos aquel que es todo amor, Jes\u00fas nos invita a mirar en el otro sus miserias y compadecernos como \u00e9l lo hizo, a amar y servir a quienes han perdido el horizonte es un acto de bondad y respuesta a su inconmensurable misericordia.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Visitar a una persona olvidada por la comunidad, llevarle toda mi compasi\u00f3n y ternura, hacerme cercano a \u00e9l.<\/li>\n\n\n\n<li>San Marcelo I nos ense\u00f1a a ser compasivos con los arrepentidos de coraz\u00f3n.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN MARCELO I (+309) San Marcelo I fue el Papa n\u00famero 30 de la Iglesia Cat\u00f3lica, sucedi\u00f3 al Papa Marcelino despu\u00e9s de que este muriera , su pontificado dur\u00f3 tan solo un a\u00f1o, en \u00e9l se dedic\u00f3 a reorganizar las Iglesias pues estas hab\u00edan sido da\u00f1adas por causa de la persecuci\u00f3n de &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2025\/01\/09\/jueves-16-de-enero-primera-semana-del-tiempo-ordinario-ciclo-c-2025\/\"> <span class=\"screen-reader-text\">JUEVES,-16 de Enero-Primera Semana del Tiempo Ordinario (ciclo C)-2025<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":5463,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5462","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/16-DE-ENERO.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/16-DE-ENERO.jpg",640,427,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/16-DE-ENERO-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/16-DE-ENERO-300x200.jpg",300,200,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/16-DE-ENERO.jpg",640,427,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/16-DE-ENERO.jpg",640,427,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/16-DE-ENERO.jpg",640,427,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/16-DE-ENERO.jpg",640,427,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SAN MARCELO I (+309) San Marcelo I fue el Papa n\u00famero 30 de la Iglesia Cat\u00f3lica, sucedi\u00f3 al Papa Marcelino despu\u00e9s de que este muriera , su pontificado dur\u00f3 tan solo un a\u00f1o, en \u00e9l se dedic\u00f3 a reorganizar las Iglesias pues estas hab\u00edan sido da\u00f1adas por causa de la persecuci\u00f3n de&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/5462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=5462"}],"version-history":[{"count":3,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/5462\/revisions"}],"predecessor-version":[{"id":5466,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/5462\/revisions\/5466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/5463"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=5462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=5462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=5462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}