{"id":5412,"date":"2025-01-06T20:08:34","date_gmt":"2025-01-07T01:08:34","guid":{"rendered":"https:\/\/devocionario.net\/?p=5412"},"modified":"2025-01-06T20:08:38","modified_gmt":"2025-01-07T01:08:38","slug":"martes-07-de-enero-segunda-semana-de-navidad-ciclo-c-2025","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2025\/01\/06\/martes-07-de-enero-segunda-semana-de-navidad-ciclo-c-2025\/","title":{"rendered":"MARTES,-07 de Enero-Segunda Semana de Navidad (ciclo C)-2025"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"612\" height=\"408\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/ENERO-07.jpg\" alt=\"\" class=\"wp-image-5415\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/ENERO-07.jpg 612w, https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/ENERO-07-300x200.jpg 300w\" sizes=\"(max-width: 612px) 100vw, 612px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-ast-global-color-2-color has-text-color\"><strong>SAN RAIMUNDO DE PE\u00d1AFORT (1180-1275)<\/strong><\/p>\n\n\n\n<p>San Raimundo fue hijo del noble castellano de Pe\u00f1afort, dedicado desde joven a los estudios filos\u00f3ficos y jur\u00eddicos, a sus veinte a\u00f1os dicta clases de filosof\u00eda en Barcelona y a los treinta a\u00f1os jurisprudencia en Bolonia, todo lo que ganaba lo invert\u00eda en los necesitados, ingres\u00f3 a la Orden de los dominicos, tiempo despu\u00e9s fue nombrado Superior General, despu\u00e9s renunci\u00f3 a este cargo y se dedic\u00f3 nuevamente a la ense\u00f1anza y a la pastoral, fue nombrado confesor del rey Santiago y continuamente le reprochaba sus conductas. Sus obras apost\u00f3licas se recuerdan por las misiones para la conversi\u00f3n de los hebreos y los mahometanos que viv\u00edan en Espa\u00f1a. redact\u00f3 obras de teolog\u00eda moral y de derecho, entre ellas la Summa casuum en la que se explica la administraci\u00f3n adecuada del sacramento de la penitencia. A\u00f1os despu\u00e9s El rey Jaime de Arag\u00f3n invit\u00f3 al santo a un viaje, pensando que el fraile le apoyar\u00eda en sus inmoralidades, entonces San Rainmundo pidi\u00f3 le dejar\u00e1n bajar de la embarcaci\u00f3n, pero el rey lo amenaz\u00f3 de muerte, luego pidiendo le dejar\u00e1n orar por las playas se fug\u00f3 haciendo el mismo un velero lleg\u00f3 a su convento en Barcelona todos se admiraron de su haza\u00f1a en la que Dios hab\u00eda puesto su mano, muere de casi cien a\u00f1os.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Marcos 6, 34-44<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, al desembarcar Jes\u00fas, vio una numerosa multitud que lo estaba esperando, y se compadeci\u00f3 de ellos, porque andaban como ovejas sin pastor, y se puso a ense\u00f1arles muchas cosas.<\/p>\n\n\n\n<p>Cuando ya atardec\u00eda, se acercaron sus disc\u00edpulos y le dijeron: &#8220;Estamos en despoblado y ya es muy tarde. Despide a la gente para que vayan por los caser\u00edos y poblados del contorno y compren algo de comer&#8221;. \u00c9l les replic\u00f3: &#8220;Denles ustedes de comer&#8221;. Ellos le dijeron: &#8220;\u00bfAcaso vamos a ir a comprar doscientos denarios de pan para darles de comer?&#8221; \u00c9l les pregunt\u00f3: &#8220;\u00bfCu\u00e1ntos panes tienen? Vayan a ver&#8221;. Cuando lo averiguaron, le dijeron: &#8220;Cinco panes y dos pescados&#8221;.<\/p>\n\n\n\n<p>Entonces orden\u00f3 Jes\u00fas que la gente se sentara en grupos sobre la hierba verde y se acomodaron en grupos de cien y de cincuenta. Tomando los cinco panes y los dos pescados, Jes\u00fas alz\u00f3 los ojos al cielo, bendijo a Dios, parti\u00f3 los panes y se los dio a los disc\u00edpulos para que los distribuyeran; lo mismo hizo con los dos pescados.<\/p>\n\n\n\n<p>Comieron todos hasta saciarse, y con las sobras de pan y de pescado que recogieron llenaron doce canastos. Los que comieron fueron cinco mil hombres.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color has-link-color wp-elements-eed1993375bedf114231f68e48e2d4e5\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Jes\u00fas sacia el hambre tanto corporal como espiritual de todos aquellos hombres, con tan poco hizo un milagro sorprendente, los disc\u00edpulos no comprendieron con quien estaban, pero es el Se\u00f1or mismo que les ense\u00f1a cuan importante es donarse con poco, sabiendo que Dios multiplica aquello que se cree es insignificante.<\/li>\n\n\n\n<li>Jes\u00fas agradece y luego da, este es un signo imposible para el hombre pero posible para Dios, el Maestro no necesito cantidades para ayudar a quienes necesitaban, s\u00f3lo confi\u00f3 en Dios e hizo su voluntad.<\/li>\n\n\n\n<li>En la actualidad no necesitamos de dinero para ayudar, s\u00f3lo se requiere una buena fe, firme, solo basta creer en quien es capaz de multiplicar aquello que poseemos, no solo materialmente sino espiritualmente en favor del bienestar de tantos necesitados.<\/li>\n\n\n\n<li>Cada vez que entendamos que para Dios no hay imposibles, que todo se puede en \u00e9l, nuestra vida comprender\u00e1 cada signo, hoy m\u00e1s que nunca cuando nuestra humanidad le falta m\u00e1s generosidad, no debemos pretender tener riquezas para ayudar, puedes hacerlo ahora, con lo que tienes, donarse para aquellos vulnerables, con palabras, con servicios, con ayudas, todo cuenta, no esperemos a tener, solo busquemos la manera de hacerlo posible. <strong>\u00abNo pierdas la oportunidad de hacer el bien, no la dejes pasar.\u00bb <em>San Felipe Neri<\/em><\/strong><\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">&nbsp;&nbsp;<strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Practicar la generosidad.<\/li>\n\n\n\n<li>San Raimundo de Pe\u00f1afort nos dice: &#8220;Los reyes de la tierra pueden impedirnos la huida, pero el Rey del cielo nos dar\u00e1 los medios para ello&#8221;.\u00a0<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN RAIMUNDO DE PE\u00d1AFORT (1180-1275) San Raimundo fue hijo del noble castellano de Pe\u00f1afort, dedicado desde joven a los estudios filos\u00f3ficos y jur\u00eddicos, a sus veinte a\u00f1os dicta clases de filosof\u00eda en Barcelona y a los treinta a\u00f1os jurisprudencia en Bolonia, todo lo que ganaba lo invert\u00eda en los necesitados, ingres\u00f3 a &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2025\/01\/06\/martes-07-de-enero-segunda-semana-de-navidad-ciclo-c-2025\/\"> <span class=\"screen-reader-text\">MARTES,-07 de Enero-Segunda Semana de Navidad (ciclo C)-2025<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":5415,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-5412","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-navidad"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/ENERO-07.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/ENERO-07.jpg",612,408,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/ENERO-07-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/ENERO-07-300x200.jpg",300,200,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/ENERO-07.jpg",612,408,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/ENERO-07.jpg",612,408,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/ENERO-07.jpg",612,408,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/ENERO-07.jpg",612,408,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SAN RAIMUNDO DE PE\u00d1AFORT (1180-1275) San Raimundo fue hijo del noble castellano de Pe\u00f1afort, dedicado desde joven a los estudios filos\u00f3ficos y jur\u00eddicos, a sus veinte a\u00f1os dicta clases de filosof\u00eda en Barcelona y a los treinta a\u00f1os jurisprudencia en Bolonia, todo lo que ganaba lo invert\u00eda en los necesitados, ingres\u00f3 a&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/5412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=5412"}],"version-history":[{"count":4,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/5412\/revisions"}],"predecessor-version":[{"id":5417,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/5412\/revisions\/5417"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/5415"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=5412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=5412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=5412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}