{"id":5381,"date":"2025-01-02T15:51:04","date_gmt":"2025-01-02T20:51:04","guid":{"rendered":"https:\/\/devocionario.net\/?p=5381"},"modified":"2025-01-02T15:51:07","modified_gmt":"2025-01-02T20:51:07","slug":"jueves-02-de-enero-octava-de-navidad-ciclo-c-2025","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2025\/01\/02\/jueves-02-de-enero-octava-de-navidad-ciclo-c-2025\/","title":{"rendered":"JUEVES, -02 de Enero-Octava de Navidad (ciclo C)-2025"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"425\" height=\"640\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/2-de-enero.jpg\" alt=\"\" class=\"wp-image-5384\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/2-de-enero.jpg 425w, https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/2-de-enero-199x300.jpg 199w\" sizes=\"(max-width: 425px) 100vw, 425px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-black-color has-text-color\"><strong>SAN BASILIO MAGNO  (329-379)<\/strong><\/p>\n\n\n\n<p>San Basilio nace en Ces\u00e1rea(Capadocia, Asia Menor), su familia cristiana sufri\u00f3 la persecuci\u00f3n, y San Basilio pas\u00f3 su infancia con su abuela Santa Macrina en el campo, sus estudios los termin\u00f3 en Atenas junto a San Gregorio Nacianceno quien era su amigo, tiempo despu\u00e9s regresa a Ces\u00e1rea a estudiar ret\u00f3rica, luego al bautizarse se ofreci\u00f3 al servicio de Dios, comenz\u00f3 a visitar monasterios para observar la vida religiosa, y despu\u00e9s al sum\u00e1rsele disc\u00edpulos fund\u00f3 un monasterio en Asia Menor. Luch\u00f3 contra los arrianos (doctrina que sostiene que Jes\u00fas no es Dios), ordenado di\u00e1cono, despu\u00e9s sacerdote comienza la defensa contra los herejes que persegu\u00edan a los cristianos, en esa \u00e9poca en Ces\u00e1rea atravesaban sequia y hambre, San Basilio vende sus bienes y los reparte a los m\u00e1s necesitados. A\u00f1os m\u00e1s tarde al morir Eusebio, San Basilio fue elegido Arzobispo en ese entonces el emperador Valente persegu\u00eda a los cristianos y enviando al Perfecto Modesto para convencer al santo de desistir, San Basilio le respondi\u00f3 que se mantendr\u00eda firme, que si lo desterraba Dios estar\u00eda con \u00e9l a donde fuera, entonces el emperador al firmar la carta de destierro la pluma fall\u00f3 tres veces, desde ese momento entendi\u00f3 y prometi\u00f3 no meterse con los asuntos de la Iglesia de Ces\u00e1rea, tiempo despu\u00e9s una nueva lucha por la divisi\u00f3n de su arquidi\u00f3cesis en la que le toc\u00f3 acceder, pero sin embargo su vida pastoral continu\u00f3 predicando en las ma\u00f1anas y por las tardes, y sus luchas por defender la fe cat\u00f3lica parec\u00eda no tener resultados, a\u00f1os m\u00e1s tarde estando en su lecho de muerte a los cuarenta y nueve a\u00f1os el emperador Valente fue herido y Graciano tom\u00f3 su lugar el arrianismo lleg\u00f3 a su fin.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Juan 1, 19-28<\/strong><\/p>\n\n\n\n<p>Este es el testimonio de Juan, cuando los jud\u00edos enviaron desde Jerusal\u00e9n sacerdotes y levitas a que le preguntaran:<br>\u00ab\u00bfT\u00fa qui\u00e9n eres?\u00bb<\/p>\n\n\n\n<p>\u00c9l confes\u00f3 y no neg\u00f3; confes\u00f3:<br>\u00abYo no soy el Mes\u00edas\u00bb.<\/p>\n\n\n\n<p>Le preguntaron:<br>\u00ab\u00bfEntonces, qu\u00e9? \u00bfEres t\u00fa El\u00edas?\u00bb.<\/p>\n\n\n\n<p>\u00c9l dijo:<br>\u00abNo lo soy\u00bb.<\/p>\n\n\n\n<p>\u00ab\u00bfEres t\u00fa el Profeta?\u00bb.<br>Respondi\u00f3: \u00abNo\u00bb.<\/p>\n\n\n\n<p>Y le dijeron:<br>\u00ab\u00bfQui\u00e9n eres, para que podamos dar una respuesta a los que nos han enviado? \u00bfQu\u00e9 dices de ti mismo?\u00bb.<\/p>\n\n\n\n<p>\u00c9l contest\u00f3:<br>\u00abYo soy la voz que grita en el desierto: \u201cAllanad el camino del Se\u00f1or\u201d, como dijo el profeta Isa\u00edas\u00bb.<\/p>\n\n\n\n<p>Entre los enviados hab\u00eda fariseos y le preguntaron:<br>\u00abEntonces, \u00bfpor qu\u00e9 bautizas si t\u00fa no eres el Mes\u00edas, ni El\u00edas, ni el Profeta?\u00bb.<\/p>\n\n\n\n<p>Juan les respondi\u00f3:<br>\u00abYo bautizo con agua; en medio de vosotros hay uno que no conoc\u00e9is, el que viene detr\u00e1s de m\u00ed, y al que no soy digno de desatar la correa de la sandalia\u00bb.<\/p>\n\n\n\n<p>Esto pasaba en Betania, en la otra orilla del Jord\u00e1n, donde Juan estaba bautizando.<\/p>\n\n\n\n<p><br>\u00abEn verdad, en verdad os digo: ver\u00e9is el cielo abierto y a los \u00e1ngeles de Dios subir y bajar sobre el Hijo del hombre\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color has-link-color wp-elements-eed1993375bedf114231f68e48e2d4e5\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En este pasaje b\u00edblico aparece Juan Bautista como protagonista o m\u00e1s bien como testigo de Jesucristo, la respuesta de Juan a quienes le preguntaban quien realmente era, no fue de orgullo precisamente sino de humildad mostrando el se\u00f1or\u00edo del Rey de reyes, porque su finalidad no era ser conocido \u00e9l sino dar a conocer a Jes\u00fas. Los Fariseos sent\u00edan inquietud de las acciones de Juan, y quer\u00edan cerciorarse de aquel de quien tanto hablan, ellos tem\u00edan de que su poder en la Iglesia fuera quitado m\u00e1s que reconocer al verdadero Mes\u00edas.<\/li>\n\n\n\n<li>Juan expone ante los incr\u00e9dulos la expresi\u00f3n &#8220;no soy yo&#8221; para que muchos entiendan que vendr\u00e1 Jes\u00fas, la ceguera de los fariseos no les permit\u00eda interpretar sus palabras, Juan insiste en dar a conocer a Jesucristo, manifest\u00e1ndose como testigo de la luz que es Cristo, sus obras no eran m\u00e1s que el testimonio de qui\u00e9n ser\u00eda el rey de Israel.<\/li>\n\n\n\n<li>Muchas veces en esta realidad, nuestra ceguera nos impide reconocer a Jes\u00fas en nuestro caminar diario, somos inquietos de experimentar el amor de Dios, pero ah\u00ed queda en la duda en la incertidumbre no trasciende hasta llegar a la acci\u00f3n, queremos pero nuestro inter\u00e9s por las cosas de este mundo es m\u00e1s fuerte. La humildad de Juan nos debe inquietar a imitar sus pasos, \u00bfEn estos momentos de nuestra vida somos testigos fieles de Jes\u00fas? \u00bf Somos sus servidores?, el orgullo nos impulsa a mostrar nuestros talentos, nuestras habilidades, a ser reconocidos y admirados por muchos, opacando la luz de Jes\u00fas, reconociendo mis propias fuerzas y no las de Dios que me sostienen en mi caminar diario.<\/li>\n\n\n\n<li>En el instante en que nos importe dar a conocer a Jes\u00fas mostr\u00e1ndolo como a la \u00fanica persona de la cu\u00e1l debemos depender, Queridos hermanos el Dios que tu y yo conocemos tiene poder es rey ahora y desde siempre, debemos tener la valent\u00eda y el coraje de anunciarlo con nuestro vivir diario en el amor.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">&nbsp;&nbsp;<strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Aprender a que los dem\u00e1s sobresalgan antes que nosotros.<\/li>\n\n\n\n<li>San Basilio nos dice:Caes con\u00a0cada altaner\u00eda, enojo y cada soberbia. Nada te es dado para gloriarte, porque tu gloria y tu esperanza deben estar puestas en\u00a0El, para que tu puedas vivir la vida que vendr\u00e1 en Cristo.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN BASILIO MAGNO (329-379) San Basilio nace en Ces\u00e1rea(Capadocia, Asia Menor), su familia cristiana sufri\u00f3 la persecuci\u00f3n, y San Basilio pas\u00f3 su infancia con su abuela Santa Macrina en el campo, sus estudios los termin\u00f3 en Atenas junto a San Gregorio Nacianceno quien era su amigo, tiempo despu\u00e9s regresa a Ces\u00e1rea a &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2025\/01\/02\/jueves-02-de-enero-octava-de-navidad-ciclo-c-2025\/\"> <span class=\"screen-reader-text\">JUEVES, -02 de Enero-Octava de Navidad (ciclo C)-2025<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":5384,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-5381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-octava-de-navidad"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/2-de-enero.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/2-de-enero.jpg",425,640,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/2-de-enero-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/2-de-enero-199x300.jpg",199,300,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/2-de-enero.jpg",425,640,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/2-de-enero.jpg",425,640,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/2-de-enero.jpg",425,640,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2025\/01\/2-de-enero.jpg",425,640,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SAN BASILIO MAGNO (329-379) San Basilio nace en Ces\u00e1rea(Capadocia, Asia Menor), su familia cristiana sufri\u00f3 la persecuci\u00f3n, y San Basilio pas\u00f3 su infancia con su abuela Santa Macrina en el campo, sus estudios los termin\u00f3 en Atenas junto a San Gregorio Nacianceno quien era su amigo, tiempo despu\u00e9s regresa a Ces\u00e1rea a&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/5381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=5381"}],"version-history":[{"count":4,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/5381\/revisions"}],"predecessor-version":[{"id":5387,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/5381\/revisions\/5387"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/5384"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=5381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=5381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=5381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}