{"id":5125,"date":"2024-11-18T15:53:46","date_gmt":"2024-11-18T20:53:46","guid":{"rendered":"https:\/\/devocionario.net\/?p=5125"},"modified":"2024-11-19T15:43:36","modified_gmt":"2024-11-19T20:43:36","slug":"jueves-trigesimo-tercera-semana-del-tiempo-ordinario-ciclo-b-21-de-noviembre-2024","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2024\/11\/18\/jueves-trigesimo-tercera-semana-del-tiempo-ordinario-ciclo-b-21-de-noviembre-2024\/","title":{"rendered":"JUEVES, Trig\u00e9simo Tercera Semana del Tiempo Ordinario (ciclo b) -21 de Noviembre, 2024"},"content":{"rendered":"\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/11\/WhatsApp-Audio-2024-11-19-at-3.42.29-PM-online-audio-converter.com_.mp3\"><\/audio><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"612\" height=\"408\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/11\/NOVIEMBRE-21.jpg\" alt=\"\" class=\"wp-image-5127\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/11\/NOVIEMBRE-21.jpg 612w, https:\/\/devocionario.net\/wp-content\/uploads\/2024\/11\/NOVIEMBRE-21-300x200.jpg 300w\" sizes=\"(max-width: 612px) 100vw, 612px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\"><strong>PRESENTACI\u00d3N DE LA BIENAVENTURADA VIRGEN MAR\u00cdA (543)<\/strong><\/p>\n\n\n\n<p>Hoy la Iglesia celebra la Presentaci\u00f3n de la sant\u00edsima Virgen Mar\u00eda, seg\u00fan cuenta la tradici\u00f3n, Mar\u00eda fue llevada al templo de Jerusal\u00e9n por sus padres, San Joaqu\u00edn y Santa Ana, para ser educada en la religi\u00f3n del pueblo de Israel cuando ten\u00eda tres a\u00f1os de edad, desde este momento Mar\u00eda tendr\u00eda conocimiento de la llegada del Mes\u00edas, Mar\u00eda va creciendo seg\u00fan los designios del Espiritu Santo, &#8220;La llena de gracia&#8221;, esta fiesta se recuerda por la dedicaci\u00f3n de la Iglesia de Santa Mar\u00eda la Nueva, situada cerca al templo de Jerusal\u00e9n. El Papa Gregorio XI comenz\u00f3 a celebrar esta festividad en Avignon (Francia), y el Papa Sixto V la incluyo en la liturgia de la Iglesia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Lucas 19,41-44<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, al acercarse Jes\u00fas a Jerusal\u00e9n y ver la ciudad, llor\u00f3 sobre ella, mientras dec\u00eda:<br>\u00ab\u00a1Si reconocieras t\u00fa tambi\u00e9n en este d\u00eda lo que conduce a la paz! Pero ahora est\u00e1 escondido a tus ojos.<br>Pues vendr\u00e1n d\u00edas sobre ti en que tus enemigos te rodear\u00e1n de trincheras, te sitiar\u00e1n, apretar\u00e1n el cerco de todos lados, te arrasar\u00e1n con tus hijos dentro, y no dejar\u00e1n piedra sobre piedra. Porque no reconociste el tiempo de tu visita\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color has-link-color wp-elements-c3aceebcb6fa48cdd589f1f1fca27705\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00bfQu\u00e9 sucesos de la vida te hacen llorar?, \u00bfHas experimentado la tristeza? Creer\u00eda que si!!, todos hemos pasado por situaciones de dolor, tristeza, que nos hacen llorar, en esta pasaje b\u00edblico encontramos aun Jes\u00fas triste, por la incredulidad del pueblo de Jerusal\u00e9n que hab\u00eda presenciado sus prodigios pero no cre\u00edan en sus palabras.<\/li>\n\n\n\n<li>Jesucristo llora ante tantas injusticias, y se lamenta por todos los adversarios que impiden anunciar su mensaje salvador, su coraz\u00f3n siente dolor desde que comienza su vida p\u00fablica al ver tantos que conoc\u00edan a Dios a trav\u00e9s de su ley pero eran incoherentes ante la pr\u00e1ctica real del amor hacia los hermanos, muchos pensaron que El Se\u00f1or era un profeta, les pareci\u00f3 muy normal quien les predicaba la verdad, no reconocieron los signos de los tiempos no vieron al salvador.<\/li>\n\n\n\n<li>Jesucristo en la actualidad continua derramando l\u00e1grimas por la humanidad, por su falta de fe, y por su falta de amor , nunca se ha cansado de esperar, anhela que la raza humana vuelva su mirada a \u00e9l, que entienda  las se\u00f1ales que anuncian su venida, vivimos en este mundo crucificando a Jes\u00fas una y otra vez, pero \u00e9l en su infinita misericordia nos muestra compasi\u00f3n, y lamenta d\u00eda y noche por nuestra desobediencia. Aprovechemos su presencia en la Sagrada eucarist\u00eda, en \u00e9l que sufre, en \u00e9l necesitado, aprendamos a conmovernos por el sufrimiento de los dem\u00e1s, a orar siempre por quienes rechazan el mensaje de Jes\u00fas y no lo ponen en pr\u00e1ctica.<\/li>\n\n\n\n<li>Debemos hacer un alto en el camino y reflexionar de los actos que cometemos y que hacen llorar y entristecer el coraz\u00f3n de Jes\u00fas, ya no podemos estar en el mundo y en las cosas de Dios, nuestra vida debe agradarle s\u00f3lo a \u00e9l ,\u00bf te conduces a caminos de paz?<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">&nbsp;&nbsp;<strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Orar por quienes rechazan el mensaje de Jesucristo.<\/li>\n\n\n\n<li>La Presentaci\u00f3n de la Virgen Mar\u00eda evoca la consagraci\u00f3n que la Virgen hizo de s\u00ed misma a Dios, entrega prefigurada en su concepci\u00f3n inmaculada y que se va realizando a lo largo de su vida, en sinton\u00eda con los designios del Esp\u00edritu Santo.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA PRESENTACI\u00d3N DE LA BIENAVENTURADA VIRGEN MAR\u00cdA (543) Hoy la Iglesia celebra la Presentaci\u00f3n de la sant\u00edsima Virgen Mar\u00eda, seg\u00fan cuenta la tradici\u00f3n, Mar\u00eda fue llevada al templo de Jerusal\u00e9n por sus padres, San Joaqu\u00edn y Santa Ana, para ser educada en la religi\u00f3n del pueblo de Israel cuando ten\u00eda tres a\u00f1os de &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2024\/11\/18\/jueves-trigesimo-tercera-semana-del-tiempo-ordinario-ciclo-b-21-de-noviembre-2024\/\"> <span class=\"screen-reader-text\">JUEVES, Trig\u00e9simo Tercera Semana del Tiempo Ordinario (ciclo b) -21 de Noviembre, 2024<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":5127,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/11\/NOVIEMBRE-21.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/11\/NOVIEMBRE-21.jpg",612,408,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/11\/NOVIEMBRE-21-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/11\/NOVIEMBRE-21-300x200.jpg",300,200,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/11\/NOVIEMBRE-21.jpg",612,408,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/11\/NOVIEMBRE-21.jpg",612,408,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/11\/NOVIEMBRE-21.jpg",612,408,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/11\/NOVIEMBRE-21.jpg",612,408,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA PRESENTACI\u00d3N DE LA BIENAVENTURADA VIRGEN MAR\u00cdA (543) Hoy la Iglesia celebra la Presentaci\u00f3n de la sant\u00edsima Virgen Mar\u00eda, seg\u00fan cuenta la tradici\u00f3n, Mar\u00eda fue llevada al templo de Jerusal\u00e9n por sus padres, San Joaqu\u00edn y Santa Ana, para ser educada en la religi\u00f3n del pueblo de Israel cuando ten\u00eda tres a\u00f1os de&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/5125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=5125"}],"version-history":[{"count":5,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/5125\/revisions"}],"predecessor-version":[{"id":5159,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/5125\/revisions\/5159"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/5127"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=5125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=5125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=5125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}