{"id":4966,"date":"2024-10-28T20:43:40","date_gmt":"2024-10-29T01:43:40","guid":{"rendered":"https:\/\/devocionario.net\/?p=4966"},"modified":"2024-10-28T20:43:42","modified_gmt":"2024-10-29T01:43:42","slug":"martes-trigesima-semana-del-tiempo-ordinario-ciclo-b-29-de-octubre-2024","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2024\/10\/28\/martes-trigesima-semana-del-tiempo-ordinario-ciclo-b-29-de-octubre-2024\/","title":{"rendered":"MARTES, Trig\u00e9sima Semana del Tiempo Ordinario (ciclo b) -29 de Octubre, 2024"},"content":{"rendered":"\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/10\/WhatsApp-Audio-2024-10-28-at-8.41.56-PM-online-audio-converter.com_.mp3\"><\/audio><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"408\" height=\"612\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/10\/OCTUBRE-29-1.jpg\" alt=\"\" class=\"wp-image-4968\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/10\/OCTUBRE-29-1.jpg 408w, https:\/\/devocionario.net\/wp-content\/uploads\/2024\/10\/OCTUBRE-29-1-200x300.jpg 200w\" sizes=\"(max-width: 408px) 100vw, 408px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-ast-global-color-2-color has-text-color\"><strong>SAN NARCISO (95-211)<\/strong><\/p>\n\n\n\n<p>San Narciso naci\u00f3 en Jerusal\u00e9n y educado en el cristianismo, se ordeno presb\u00edtero y luego fue elegido obispo de Jerusal\u00e9n cuando tenia una edad avanzada, asiste y preside el concilio de Cesarea para que junto con Roma se unificara la celebraci\u00f3n de la Pascua. Tiempo despu\u00e9s sus cl\u00e9rigos se confabularon para calumniarlo con un crimen atroz pues le ten\u00edan envidia al Santo por sus gran \u00e9xito como Obispo, luego de que sucediera esta triste situaci\u00f3n, perdona a sus difamadores y se retira a un lugar por casi ocho a\u00f1os, un d\u00eda uno de los que calumniaron a San Narciso anuncia ante el p\u00fablico inocencia del santo, entonces decide regresar con los fieles y colaborar a Alejandro, obispo de Flaviada en la Capadocia y le suceder\u00e1 a\u00f1os m\u00e1s tarde, muere de m\u00e1s de cien a\u00f1os de edad.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Lucas 13,18-21<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, , dec\u00eda Jes\u00fas:<br>\u00ab\u00bfA qu\u00e9 es semejante el reino de Dios o a qu\u00e9 lo comparar\u00e9?<br>Es semejante a un grano de mostaza que un hombre toma y siembra en su huerto; creci\u00f3, se hizo un \u00e1rbol y los p\u00e1jaros del cielo anidaron en sus ramas\u00bb.<br>Y dijo de nuevo:<br>\u00ab\u00bfA qu\u00e9 comparar\u00e9 el reino de Dios?<br>Es semejante a la levadura que una mujer tom\u00f3 y meti\u00f3 en tres medidas de harina, hasta que todo ferment\u00f3\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color has-link-color wp-elements-c3aceebcb6fa48cdd589f1f1fca27705\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ninguno de nosotros puede ver minuto a minuto el crecimiento de un \u00e1rbol, o como la levadura en que momento hizo fermentar la masa, son detalles que pasan desapercibidos, pero que son importantes para que tanto el \u00e1rbol como la masa crezcan, igualmente es el Reino de Dios, todos los d\u00edas pedimos en el Padre Nuestro que venga el Reino de Dios a nosotros pero no estamos atentos a las peque\u00f1as o simples cosas que nos pasan a diario y que hacen que ese reino crezca y se fortalezca en nuestro interior, como orar, regalar un consejo, ser amable, hacer un favor, ense\u00f1ar a los ni\u00f1os etc.<\/li>\n\n\n\n<li>Dios act\u00faa de manera misteriosa en nuestra vida y en la de los dem\u00e1s, \u00b4\u00bfcuantas veces te sientes deprimido, angustiado, con temores? pensando que Dios no har\u00e1 grandes cosas por ti, y que incluso ni te escucha, recuerda Dios trabaja en el silencio, pero es que lo que sucede es que aun no conoces su acci\u00f3n, no eres paciente y quieres ver resultados de manera inmediata, pero \u00e9l se vale de nuestras peque\u00f1eces para sacar lo mejor de nosotros, nos convierte en lo inimaginable solo debemos permitir se haga su voluntad en nuestro obrar y esperar el momento oportuno para crecer como \u00e9l desea.<\/li>\n\n\n\n<li>Jesucristo nos ense\u00f1a a confiar en la acci\u00f3n salvadora de Nuestro Padre Y a trabajar por el reino de Dios, sin desanimarnos pues Dios obra en el momento que menos lo imaginemos, ve y lleva la semilla de la Palabra de Dios que lo dem\u00e1s lo har\u00e1 \u00e9l.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">&nbsp;&nbsp;<strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Que har\u00e9 para expandir el reino de los cielos, \u00bfCu\u00e1l es mi aporte? <\/li>\n\n\n\n<li>San Narciso nos ense\u00f1a que la paciencia ante la cruz es fundamental para alcanzar el cielo.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN NARCISO (95-211) San Narciso naci\u00f3 en Jerusal\u00e9n y educado en el cristianismo, se ordeno presb\u00edtero y luego fue elegido obispo de Jerusal\u00e9n cuando tenia una edad avanzada, asiste y preside el concilio de Cesarea para que junto con Roma se unificara la celebraci\u00f3n de la Pascua. Tiempo despu\u00e9s sus cl\u00e9rigos se &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2024\/10\/28\/martes-trigesima-semana-del-tiempo-ordinario-ciclo-b-29-de-octubre-2024\/\"> <span class=\"screen-reader-text\">MARTES, Trig\u00e9sima Semana del Tiempo Ordinario (ciclo b) -29 de Octubre, 2024<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":4967,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/10\/OCTUBRE-29.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/10\/OCTUBRE-29.jpg",408,612,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/10\/OCTUBRE-29-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/10\/OCTUBRE-29-200x300.jpg",200,300,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/10\/OCTUBRE-29.jpg",408,612,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/10\/OCTUBRE-29.jpg",408,612,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/10\/OCTUBRE-29.jpg",408,612,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/10\/OCTUBRE-29.jpg",408,612,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SAN NARCISO (95-211) San Narciso naci\u00f3 en Jerusal\u00e9n y educado en el cristianismo, se ordeno presb\u00edtero y luego fue elegido obispo de Jerusal\u00e9n cuando tenia una edad avanzada, asiste y preside el concilio de Cesarea para que junto con Roma se unificara la celebraci\u00f3n de la Pascua. Tiempo despu\u00e9s sus cl\u00e9rigos se&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/4966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=4966"}],"version-history":[{"count":2,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/4966\/revisions"}],"predecessor-version":[{"id":4971,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/4966\/revisions\/4971"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/4967"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=4966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=4966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=4966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}