{"id":4810,"date":"2024-10-07T20:20:41","date_gmt":"2024-10-08T01:20:41","guid":{"rendered":"https:\/\/devocionario.net\/?p=4810"},"modified":"2024-10-08T06:32:01","modified_gmt":"2024-10-08T11:32:01","slug":"martes-vigesimo-septima-semana-del-tiempo-ordinario-ciclo-b-08-de-octubre-2024","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2024\/10\/07\/martes-vigesimo-septima-semana-del-tiempo-ordinario-ciclo-b-08-de-octubre-2024\/","title":{"rendered":"MARTES, Vig\u00e9simo S\u00e9ptima Semana del Tiempo Ordinario (ciclo b) -08 de Octubre, 2024"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"612\" height=\"344\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/10\/octubre-8.jpg\" alt=\"\" class=\"wp-image-4818\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/10\/octubre-8.jpg 612w, https:\/\/devocionario.net\/wp-content\/uploads\/2024\/10\/octubre-8-300x169.jpg 300w\" sizes=\"(max-width: 612px) 100vw, 612px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/10\/WhatsApp-Audio-2024-10-07-at-8.14.33-PM-online-audio-converter.com_.mp3\"><\/audio><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-ast-global-color-6-color has-text-color\"><strong>SANTA PELAGIA DE ANTIOQUIA (+468)<\/strong><\/p>\n\n\n\n<p>San Pelagia era una comediante en Antioqu\u00eda, desde muy joven hab\u00eda compartido con los catec\u00famenos, pero fue creciendo en el mundo y se dedico a las danzas sensuales la llamaban &#8220;Margarita&#8221;, un d\u00eda por curiosidad Pelagia entr\u00f3 al templo y al o\u00edr al obispo de la misericordia infinita de Dios para con los hombres, ella intent\u00f3 rezar pero no se acord\u00f3 de como hacerlo, as\u00ed que se dispone a escribir una carta al obispo que dec\u00eda estas palabras: &#8220;Al santo disc\u00edpulo de Jes\u00fas: He o\u00eddo decir que tu Dios baj\u00f3 del cielo a la tierra para salvaci\u00f3n de los hombres. \u00c9l no desde\u00f1\u00f3 hablar con la mujer pecadora. Si eres su disc\u00edpulo, esc\u00fachame. No me niegues el bien y el consuelo de o\u00edr tu palabra para poder hallar gracia, por tu medio, con Jesucristo, nuestro Salvador.&#8221; Sent\u00eda en su coraz\u00f3n la necesidad de dejar su desordenada vida para hallar la gracia de Dios, el obispo crey\u00f3 en su conversi\u00f3n, la bautiz\u00f3 confirmo y pudo al fin recibir la Santa Eucarist\u00eda, luego vendi\u00f3 lo que ten\u00eda y lo di\u00f3 a los pobres y dej\u00f3 Antioquia. Cerca de Jerusal\u00e9n hab\u00eda una gruta all\u00ed se qued\u00f3 para vivir en oraci\u00f3n y penitencia, Santa Pelagia a todos lo que se pasaban por ah\u00ed dec\u00eda que era Pelagio un hombre ermita\u00f1o, tiempo despu\u00e9s un di\u00e1cono decidi\u00f3 ir a visitar a Pelagio, luego nuevamente al regresar lo encontr\u00f3 muerto y en el momento de ungirlo con mirra se di\u00f3 cuenta que era una mujer, entonces mujeres del Jord\u00e1n y Jeric\u00f3 marcharon con luces y cantando himnos dieron cristiana sepultura a Pelagia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Lucas 10,38-42<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, entr\u00f3 Jes\u00fas en una aldea, y una mujer llamada Marta lo recibi\u00f3 en su casa.<br>Esta ten\u00eda una hermana llamada Mar\u00eda, que, sentada junto a los pies del Se\u00f1or, escuchaba su palabra.<br>Marta, en cambio, andaba muy afanada con los muchos servicios; hasta que, acerc\u00e1ndose, dijo:<br>\u00abSe\u00f1or, \u00bfno te importa que mi hermana me haya dejado sola para servir? Dile que me eche una mano\u00bb.<br>Respondiendo, le dijo el Se\u00f1or:<br>\u00abMarta, Marta, andas inquieta y preocupada con muchas cosas; solo una es necesaria. Mar\u00eda, pues, ha escogido la parte mejor, y no le ser\u00e1 quitada\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color has-link-color wp-elements-c3aceebcb6fa48cdd589f1f1fca27705\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Hoy en d\u00eda se ha invertido el orden de prioridades en nuestras vidas,  al levantarnos damos  importancia a nuestras responsabilidades cotidianas, y escuchar y meditar en la Palabra de Dios, o contemplar la presencia de Jesucristo en nuestras vidas esta en \u00faltimo lugar,  est\u00e1 ultima se da si no  terminas agotado(a), iniciamos el d\u00eda preocupados, atareados, acelerados y hasta ansiosos de querer hacer todo al tiempo, pero estas cosas nos est\u00e1n robando la oportunidad de tener una relaci\u00f3n estrecha con el Se\u00f1or.<\/li>\n\n\n\n<li>Marta y Mar\u00eda son un vivo reflejo de la sociedad de estos tiempos, pero debemos ver que la actitud de Marta es de servicio, pero un servicio no cimentado en el Maestro, mientras que la actitud de Mar\u00eda   es contemplativa al estar en la presencia de Jes\u00fas, ambas actitudes son buenas pero se deben complementar, es decir, orar y trabajar, ser activos y contemplativos, es una realidad que debemos tener una vida activa para sustentarnos, en el caso de Marta serv\u00eda para brindar a Jesucristo algo de comer, pero termino por perderse la mejor parte, que har\u00eda que sus tareas fueran m\u00e1s productivas al darle a Jes\u00fas el primer lugar,<\/li>\n\n\n\n<li>\u00bfC\u00f3mo es tu d\u00eda a d\u00eda? , \u00bfJesucristo se convierte en el centro de tu vida o est\u00e1 como una opci\u00f3n para ti?, acoger la Palabra de Dios me permite que mi servicio vaya dirigido por el Se\u00f1or, debemos mantener un equilibrio entre la oraci\u00f3n y el trabajo, no busquemos esto como pretexto para dejar de ser diligentes, sino que teniendo como fundamento la contemplaci\u00f3n en lo divino podremos avanzar en el servicio seg\u00fan la voluntad de Dios en los espacios, ambientes ,lugares donde me desarrollo personalmente.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">&nbsp;&nbsp;<strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Al levantarme buscar un lugar en el que pueda orar en silencio y encomendar mi d\u00eda al Se\u00f1or.<\/li>\n\n\n\n<li>Santa Pelagia se entreg\u00f3 a la vida contemplativa como ella que hermoso ser\u00eda que nuestra vida estuviera en torno a la oraci\u00f3n y la meditaci\u00f3n en Jesucristo, abandonando los placeres del mundo.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SANTA PELAGIA DE ANTIOQUIA (+468) San Pelagia era una comediante en Antioqu\u00eda, desde muy joven hab\u00eda compartido con los catec\u00famenos, pero fue creciendo en el mundo y se dedico a las danzas sensuales la llamaban &#8220;Margarita&#8221;, un d\u00eda por curiosidad Pelagia entr\u00f3 al templo y al o\u00edr al obispo de la misericordia &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2024\/10\/07\/martes-vigesimo-septima-semana-del-tiempo-ordinario-ciclo-b-08-de-octubre-2024\/\"> <span class=\"screen-reader-text\">MARTES, Vig\u00e9simo S\u00e9ptima Semana del Tiempo Ordinario (ciclo b) -08 de Octubre, 2024<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":4818,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/10\/octubre-8.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/10\/octubre-8.jpg",612,344,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/10\/octubre-8-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/10\/octubre-8-300x169.jpg",300,169,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/10\/octubre-8.jpg",612,344,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/10\/octubre-8.jpg",612,344,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/10\/octubre-8.jpg",612,344,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/10\/octubre-8.jpg",612,344,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":3,"uagb_excerpt":"SANTO DEL D\u00cdA SANTA PELAGIA DE ANTIOQUIA (+468) San Pelagia era una comediante en Antioqu\u00eda, desde muy joven hab\u00eda compartido con los catec\u00famenos, pero fue creciendo en el mundo y se dedico a las danzas sensuales la llamaban &#8220;Margarita&#8221;, un d\u00eda por curiosidad Pelagia entr\u00f3 al templo y al o\u00edr al obispo de la misericordia&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/4810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=4810"}],"version-history":[{"count":4,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/4810\/revisions"}],"predecessor-version":[{"id":4843,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/4810\/revisions\/4843"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/4818"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=4810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=4810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=4810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}