{"id":4788,"date":"2024-10-02T17:32:16","date_gmt":"2024-10-02T22:32:16","guid":{"rendered":"https:\/\/devocionario.net\/?p=4788"},"modified":"2024-10-02T17:32:18","modified_gmt":"2024-10-02T22:32:18","slug":"sabado-vigesimo-sexta-semana-del-tiempo-ordinario-ciclo-b-05-de-octubre-2024","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2024\/10\/02\/sabado-vigesimo-sexta-semana-del-tiempo-ordinario-ciclo-b-05-de-octubre-2024\/","title":{"rendered":"SABADO, Vig\u00e9simo Sexta Semana del Tiempo Ordinario (ciclo b) -05 de Octubre, 2024"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"428\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/09\/OCTUBRE-5.jpg\" alt=\"\" class=\"wp-image-4789\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/09\/OCTUBRE-5.jpg 640w, https:\/\/devocionario.net\/wp-content\/uploads\/2024\/09\/OCTUBRE-5-300x201.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/09\/WhatsApp-Audio-2024-09-30-at-8.33.52-PM-online-audio-converter.com_.mp3\"><\/audio><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-ast-global-color-6-color has-text-color\"><strong>SANTA FAUSTINA KOWALSKA (1905-1938)<\/strong><\/p>\n\n\n\n<p>San Faustina naci\u00f3 en la aldea de Glogowiec, cerca de Lodz, cuando estaba peque\u00f1a le gustaba estar en oraci\u00f3n, en penitencia, practicaba el amor con los pobres, no termin\u00f3 sus estudios sino que se dedic\u00f3 a trabajar en casas de familia acomodadas. A\u00f1os m\u00e1s tarde ingres\u00f3 a la Congregaci\u00f3n de las Hermanas de la Madre de Dios de la Misericordia, donde se dedico durante trece a\u00f1os como cocinera, jardinera y portera en su comunidad\u00ad, su relaci\u00f3n con Dios fue muy intima, su anhelo de ser santa le permiti\u00f3 entregarse por completo a Jes\u00fas, por sus estigmas de sufrimiento y extraordinarias gracias m\u00edsticas, el Se\u00f1or se le revel\u00f3 y le pidi\u00f3 escribiera un diario acerca &nbsp;de su misericordia para el provecho de aquellos que leyendo estos escritos, encontrar\u00e1n en sus almas consuelo y adquirir\u00e1n valor para acercarse a \u00e9l, fue una obra que revel\u00f3 la misericordia divina del Se\u00f1or Jesucristo y la que el mismo Se\u00f1or le pidi\u00f3 se celebrar\u00e1 una fiesta especial a la Divina Misericordia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Mateo 7,7-11<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, dijo Jes\u00fas a sus disc\u00edpulos:<br>\u00abPedid y se os dar\u00e1, buscad y encontrar\u00e9is, llamad y se os abrir\u00e1; porque todo el que pide recibe, quien busca encuentra y al que llama se le abre.<br>Si a alguno de vosotros le pide su hijo pan, \u00bfle dar\u00e1 una piedra?; y si le pide pescado, \u00bfle dar\u00e1 una serpiente? Pues si vosotros, aun siendo malos, sab\u00e9is dar cosas buenas a vuestros hijos, \u00a1cu\u00e1nto m\u00e1s vuestro Padre que est\u00e1 en los cielos dar\u00e1 cosas buenas a los que le piden!\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color has-link-color wp-elements-c3aceebcb6fa48cdd589f1f1fca27705\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En estos tiempos parece que meditar esta de moda, meditar es algo as\u00ed como rumiar, si rumiar lo que hacen los animales, masticando su alimento por segunda vez, bueno ahora enfoquemos este termino a Dios, la meditaci\u00f3n que el mundo nos ofrece es tan diferente, pues se fundamenta en c\u00e1lculos humanos, pero la meditaci\u00f3n en Dios nos permite ver esperanza, misericordia a mis inseguridades, temores, pecados. \u00bfSabes orar?, \u00bfC\u00f3mo te diriges a Dios?, la mayor\u00eda de las personas no sabemos como se debe orar, pensamos que orar es expresarnos de una manera misteriosa, sobrenatural, es tan sencillo como cuando te sientas con alguien de confianza y le cuentas toda tu vida sabiendo que te conoce pero aun as\u00ed te escucha, as\u00ed sucede con la oraci\u00f3n dirigida a Dios.<\/li>\n\n\n\n<li> Jesucristo nos hace una invitaci\u00f3n, el de pedir por nuestras necesidades no a un Dios ajeno a nosotros sino a nuestro Padre, quien conociendo todo absolutamente todo de nosotros nos escucha y responde en el momento adecuado, pero para que esta oraci\u00f3n sea eficaz se debe aceptar su voluntad y esperar con paciencia, adem\u00e1s se debe volver una necesidad diaria de comunicaci\u00f3n con un Padre que ama y espera.<\/li>\n\n\n\n<li>La oraci\u00f3n no esta condicionada al tiempo, al lugar, sino que fluye de manera natural en donde quiera nos encontremos, no necesitamos tener doctorados para dirigirnos a nuestro Padre, si decir nuestro Pap\u00e1 como no lo ense\u00f1o Jesucristo no te emociona es una frialdad incre\u00edble de tu parte.<\/li>\n\n\n\n<li>Debemos tener cuidado cuando nuestras oraciones despliegan una lista de peticiones ego\u00edstas y particulares, m\u00e1s bien debe basarse en la gratitud, Jes\u00fas nos ense\u00f1a que la oraci\u00f3n debe ser permanente, a DIOS PADRE le gusta que le repitas, lo que necesitas aun sabi\u00e9ndolo, \u00e9l poder de la oraci\u00f3n estan maravillosa que sucede lo impensable, no dejes de orar en todo momento.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">&nbsp;&nbsp;<strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Orar siempre, y motivar a otros a hacerlo.<\/li>\n\n\n\n<li>Santa Faustina nos ense\u00f1a: \u201cNi gracias, ni revelaciones, ni \u00e9xtasis, ni ning\u00fan otro don concedido al alma la hace perfecta, sino la comuni\u00f3n interior de mi alma con Dios. Estos dones son solamente un adorno del alma, pero no constituyen ni la sustancia ni la perfecci\u00f3n\u201d&nbsp;<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SANTA FAUSTINA KOWALSKA (1905-1938) San Faustina naci\u00f3 en la aldea de Glogowiec, cerca de Lodz, cuando estaba peque\u00f1a le gustaba estar en oraci\u00f3n, en penitencia, practicaba el amor con los pobres, no termin\u00f3 sus estudios sino que se dedic\u00f3 a trabajar en casas de familia acomodadas. A\u00f1os m\u00e1s tarde ingres\u00f3 a la &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2024\/10\/02\/sabado-vigesimo-sexta-semana-del-tiempo-ordinario-ciclo-b-05-de-octubre-2024\/\"> <span class=\"screen-reader-text\">SABADO, Vig\u00e9simo Sexta Semana del Tiempo Ordinario (ciclo b) -05 de Octubre, 2024<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":4789,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-4788","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tiempo-ordinario"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/09\/OCTUBRE-5.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/09\/OCTUBRE-5.jpg",640,428,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/09\/OCTUBRE-5-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/09\/OCTUBRE-5-300x201.jpg",300,201,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/09\/OCTUBRE-5.jpg",640,428,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/09\/OCTUBRE-5.jpg",640,428,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/09\/OCTUBRE-5.jpg",640,428,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/09\/OCTUBRE-5.jpg",640,428,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":1,"uagb_excerpt":"SANTO DEL D\u00cdA SANTA FAUSTINA KOWALSKA (1905-1938) San Faustina naci\u00f3 en la aldea de Glogowiec, cerca de Lodz, cuando estaba peque\u00f1a le gustaba estar en oraci\u00f3n, en penitencia, practicaba el amor con los pobres, no termin\u00f3 sus estudios sino que se dedic\u00f3 a trabajar en casas de familia acomodadas. A\u00f1os m\u00e1s tarde ingres\u00f3 a la&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/4788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=4788"}],"version-history":[{"count":3,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/4788\/revisions"}],"predecessor-version":[{"id":4800,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/4788\/revisions\/4800"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/4789"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=4788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=4788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=4788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}