{"id":4634,"date":"2024-09-16T06:11:34","date_gmt":"2024-09-16T11:11:34","guid":{"rendered":"https:\/\/devocionario.net\/?p=4634"},"modified":"2024-09-16T06:11:36","modified_gmt":"2024-09-16T11:11:36","slug":"lunes-vigesimo-cuarta-semana-del-tiempo-ordinario-ciclo-b-16-de-septiembre-2024","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2024\/09\/16\/lunes-vigesimo-cuarta-semana-del-tiempo-ordinario-ciclo-b-16-de-septiembre-2024\/","title":{"rendered":"LUNES, Vig\u00e9simo Cuarta Semana del Tiempo Ordinario (ciclo b) -16 de Septiembre, 2024"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"612\" height=\"408\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/09\/septiembre-16.jpg\" alt=\"\" class=\"wp-image-4644\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/09\/septiembre-16.jpg 612w, https:\/\/devocionario.net\/wp-content\/uploads\/2024\/09\/septiembre-16-300x200.jpg 300w\" sizes=\"(max-width: 612px) 100vw, 612px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/09\/WhatsApp-Audio-2024-09-16-at-6.10.14-AM-online-audio-converter.com_.mp3\"><\/audio><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\"><strong>SANTOS CORNELIO Y CIPRIANO (+252,258)<\/strong><\/p>\n\n\n\n<p>San Cornelio y Cipriano fueron dos victimas de la persecuci\u00f3n de Valeriano, San Cipriano fue un obispo nacido en el a\u00f1o 200 en \u00c1frica, convertido al cristianismo a la edad de cuarenta a\u00f1os, fue un buen Maestro y Predicador, ayudo a muchos, vendi\u00f3 sus bienes los dio a los pobres, continuo en su ministerio aun siendo perseguidos, en el mandato de Valeriano hizo caso omiso de no celebrar misa y fue condenado a muerte, decapitado por no adorar a otros dioses. San Cornelio fue elegido Papa en el a\u00f1o 251, Cipriano y algunos obispos africanos estaban a favor del Papa, seg\u00fan los emperadores San Cornelio era libel\u00e1tico \u00f3sea que ten\u00eda un certificado que le permit\u00eda no le molestar\u00e1n en cuestiones de religi\u00f3n que hab\u00eda obtenido de los altos mandos, entonces el emperador Galo lo confin\u00f3 en Civitavecchia hasta que all\u00ed falleci\u00f3.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Lucas 7,1-10<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, cuando Jes\u00fas termin\u00f3 de exponer todas sus ense\u00f1anzas al pueblo, entr\u00f3 en Cafarna\u00fan.<\/p>\n\n\n\n<p>Un centuri\u00f3n ten\u00eda enfermo, a punto de morir, a un criado a quien estimaba mucho. Al o\u00edr hablar de Jes\u00fas, el centuri\u00f3n le envi\u00f3 unos ancianos de los jud\u00edos, rog\u00e1ndole que viniese a curar a su criado. Ellos, present\u00e1ndose a Jes\u00fas, le rogaban encarecidamente:<br>\u00abMerece que se lo concedas, porque tiene afecto a nuestra gente y nos ha construido la sinagoga\u00bb.<\/p>\n\n\n\n<p>Jes\u00fas se puso en camino con ellos. No estaba lejos de la casa, cuando el centuri\u00f3n le envi\u00f3 unos amigos a decirle:<\/p>\n\n\n\n<p>\u00abSe\u00f1or, no te molestes; porque no soy digno de que entres bajo mi techo; por eso tampoco me cre\u00ed digno de venir a ti personalmente. Dilo de palabra, y mi criado quedar\u00e1 sano. Porque tambi\u00e9n yo soy un hombre sometido a una autoridad y con soldados a mis \u00f3rdenes; y le digo a uno: &#8220;Ve&#8221;, y va; al otro: &#8220;Ven&#8221;, y viene; y a mi criado: &#8220;Haz esto&#8221;, y lo hace\u00bb.<\/p>\n\n\n\n<p>Al o\u00edr esto, Jes\u00fas se admir\u00f3 de \u00e9l y, volvi\u00e9ndose a la gente que lo segu\u00eda, dijo:<br>\u00abOs digo que ni en Israel he encontrado tanta fe\u00bb.<\/p>\n\n\n\n<p>Y al volver a casa, los enviados encontraron al siervo sano.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color has-link-color wp-elements-c3aceebcb6fa48cdd589f1f1fca27705\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En el evangelio de hoy nuevamente una expresi\u00f3n de fe sale a relucir, y en esta ocasi\u00f3n en un centuri\u00f3n Romano, que reconoce la autoridad y el poder de Jes\u00fas para sanar. La fama de Jesucristo por\u00a0 sus milagros llego a o\u00eddos de este hombre que al compadecerse de su siervo, emprende camino en busca del Maestro, en el centuri\u00f3n solo se halla humildad, porque se cree indigno, pues su casa quiz\u00e1s no era la m\u00e1s adecuada para que el Mes\u00edas entrara en ella, \u00bfo ser\u00eda quiz\u00e1s su vida?, pero solo bastaba en saber que con una palabra del Maestro todo cambiar\u00eda y esto solo lo podr\u00eda hacer la fe. Con cuanto amor y bondad\u00a0 Jes\u00fas miraba a quien estaba enfermo, en su vida p\u00fablica lo que m\u00e1s hizo fue brindar compasi\u00f3n, misericordia y ternura a quienes sufr\u00edan dolencias corporales y espirituales, y a nadie neg\u00f3 la oportunidad de ser sanado pues su bondad es infinita, y sabe que quien tiene sed de Dios y se abandona en sus manos solo obtendr\u00e1 lo que anhela su coraz\u00f3n.<\/li>\n\n\n\n<li><strong>\u00a0<\/strong>En este pasaje b\u00edblico Jesucristo exalta la fe del Centuri\u00f3n, porque no siendo jud\u00edo cree en sus palabras, solo con haber escuchado de \u00e9l, pero Jes\u00fas lo hac\u00eda con una \u00fanica intenci\u00f3n, mostrar al pueblo cuan incr\u00e9dulos eran, que nacidos en las pr\u00e1cticas piadosas jud\u00edas no reconoc\u00edan quien estaba frente a ellos. La fe no es m\u00e1s que esperar en quien se ha puesto toda confianza, es por eso que Jesucristo se vale de las enfermedades para que le hallen, busca a cada momento la atenci\u00f3n del hombre para que lo haga parte de su vida y como el centuri\u00f3n quiere una fe firme que sea capaz de saber que lo que pide ya se ha cumplido. <\/li>\n\n\n\n<li>Cuantas veces en nuestra vida nos hemos sentido indignos de presentarnos ante Jes\u00fas, de contarle nuestros problemas, abandon\u00e1ndonos en sus manos, pero nuestra falta de fe y confianza en \u00e9l, ha hecho de nosotros hombres y mujeres incapaces de reconocer a quien puede sanarnos realmente, nos falta humildad para darnos cuenta que estamos tan enfermos que necesitamos de su compasi\u00f3n para caminar por este valle de l\u00e1grimas, nuestra mente impone a Dios para que nuestra voluntad sea escuchada, sin antes dejar que sea \u00e9l quien tome las riendas de nuestra vida, pues \u00e9l nos ha creado y conoce que necesitamos para ser felices, como nuestro alfarero nos moldea en el dolor, y por m\u00e1s que queramos huir de nuestras realidades \u00e9l nos dice que busquemos en el sufrimiento una oportunidad para ser mejores, para pulirnos en la fe. Estando en la Iglesia, en misa, en la oraci\u00f3n, en cualesquier pr\u00e1ctica piadosa dudamos de las grandes obras que Jes\u00fas puede hacer en nosotros, pero cuantos ateos, o personas que tiene otras ideolog\u00edas nos ense\u00f1an acciones heroicas que manifiestan la fe. Recordemos que quienes asisten a la iglesia no son m\u00e1s que enfermos necesitados de la gracia de Dios.<\/li>\n\n\n\n<li>\u00bfVemos la bondad en el otro como lo hace Jes\u00fas con nosotros?, como nos cuesta ver m\u00e1s all\u00e1 de las apariencias, Jes\u00fas nos ense\u00f1a una forma de vivir y es dar todo de nosotros a quien necesita. La fe queridos miembros de la iglesia no es m\u00e1s que la convicci\u00f3n de la esperanza, si creemos sabremos que quien nos sostiene es nuestro salvador Jesucristo, que regalo tan grande de Dios para con nosotros, nos considera tanto en nuestras debilidades que solo nos exige la fe como el tama\u00f1o de un grano de mostaza, y aun as\u00ed le fallamos. Si nuestra fe est\u00e1 siempre firme s\u00f3lo bastara una palabra para que seamos sanados, esta frase repetida una y otra vez en la santa misa no debe ser desapercibida, debemos hacer que se cumpla, en el momento de nuestra enfermedad y debilidad tengamos presente que Jes\u00fas es quien tiene el poder sobre nuestra existencia reconocerlo en su autoridad es entender que su acci\u00f3n salvadora nos alcanzar\u00e1 sin reservas y veremos en nosotros un milagro que solo la fe en \u00e9l explica.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">&nbsp;&nbsp;<strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Acrecentar nuestra fe con la oraci\u00f3n.<\/li>\n\n\n\n<li>San  Cipriano nos ense\u00f1a:&#8221; Yo soy cristiano y soy obispo. No reconozco a ning\u00fan otro Dios, sino al \u00fanico y verdadero Dios que hizo el cielo y la tierra&#8221;.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SANTOS CORNELIO Y CIPRIANO (+252,258) San Cornelio y Cipriano fueron dos victimas de la persecuci\u00f3n de Valeriano, San Cipriano fue un obispo nacido en el a\u00f1o 200 en \u00c1frica, convertido al cristianismo a la edad de cuarenta a\u00f1os, fue un buen Maestro y Predicador, ayudo a muchos, vendi\u00f3 sus bienes los dio &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2024\/09\/16\/lunes-vigesimo-cuarta-semana-del-tiempo-ordinario-ciclo-b-16-de-septiembre-2024\/\"> <span class=\"screen-reader-text\">LUNES, Vig\u00e9simo Cuarta Semana del Tiempo Ordinario (ciclo b) -16 de Septiembre, 2024<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":4644,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4634","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/09\/septiembre-16.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/09\/septiembre-16.jpg",612,408,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/09\/septiembre-16-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/09\/septiembre-16-300x200.jpg",300,200,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/09\/septiembre-16.jpg",612,408,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/09\/septiembre-16.jpg",612,408,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/09\/septiembre-16.jpg",612,408,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/09\/septiembre-16.jpg",612,408,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":1,"uagb_excerpt":"SANTO DEL D\u00cdA SANTOS CORNELIO Y CIPRIANO (+252,258) San Cornelio y Cipriano fueron dos victimas de la persecuci\u00f3n de Valeriano, San Cipriano fue un obispo nacido en el a\u00f1o 200 en \u00c1frica, convertido al cristianismo a la edad de cuarenta a\u00f1os, fue un buen Maestro y Predicador, ayudo a muchos, vendi\u00f3 sus bienes los dio&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/4634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=4634"}],"version-history":[{"count":6,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/4634\/revisions"}],"predecessor-version":[{"id":6957,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/4634\/revisions\/6957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/4644"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=4634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=4634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=4634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}