{"id":4420,"date":"2024-08-15T16:45:29","date_gmt":"2024-08-15T21:45:29","guid":{"rendered":"https:\/\/devocionario.net\/?p=4420"},"modified":"2024-08-15T16:45:31","modified_gmt":"2024-08-15T21:45:31","slug":"domingo-vigesima-semana-del-tiempo-ordinario-ciclo-b-18-de-agosto-2024","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2024\/08\/15\/domingo-vigesima-semana-del-tiempo-ordinario-ciclo-b-18-de-agosto-2024\/","title":{"rendered":"DOMINGO, Vig\u00e9sima Semana del Tiempo Ordinario (ciclo b) -18 de agosto, 2024"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"427\" height=\"640\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/08\/AGOSTO-18.jpg\" alt=\"\" class=\"wp-image-4421\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/08\/AGOSTO-18.jpg 427w, https:\/\/devocionario.net\/wp-content\/uploads\/2024\/08\/AGOSTO-18-200x300.jpg 200w\" sizes=\"(max-width: 427px) 100vw, 427px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-black-color has-text-color\"><strong>SANTA ELENA  (+329)<\/strong><\/p>\n\n\n\n<p>Santa Elena naci\u00f3 en una familia pagana y pobre, desde su juventud presenci\u00f3 la muerte de muchos cristianos, y no entend\u00eda porque eran torturados y asesinados, era mujer noble de coraz\u00f3n, contrajo matrimonio con Constancio y de ese matrimonio tuvieron un hijo quien tuvo como nombre Cesar de Maximiano, su esposo la repudi\u00f3 para casarse con la hijastra de Maximiano, y su hijo que tomo el nombre de Constantino se fue con su pap\u00e1 a educarse en el palacio, luego a\u00f1os m\u00e1s tarde muriendo su Padre se lleva a su Madre, le da poder para levantar iglesias, y tambi\u00e9n se dejo influenciar por ella en ciertos asuntos que se refer\u00edan a los cristianos. A\u00f1os m\u00e1s tarde Santa Elena viaja a los santos lugares en busca del madero donde fue crucificado el Redentor, su af\u00e1n por encontrar esta important\u00edsima cruz la llev\u00f3 hasta los jud\u00edos que por fin dieron respuesta a su b\u00fasqueda, luego decide enviar una parte de la cruz a Jerusal\u00e9n, otra a Constantinopla y otra a Roma para que fuese venerada, tiempo despu\u00e9s muere cumpliendo con su misi\u00f3n de llevar la cruz de Cristo y darla a conocer para que creyeran en Jesucristo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Juan 6,51-58<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, dijo Jes\u00fas a la gente:<br>\u00abYo soy el pan vivo que ha bajado del cielo; el que coma de este pan vivir\u00e1 para siempre. Y el pan que yo dar\u00e9 es mi carne para la vida del mundo\u00bb.<\/p>\n\n\n\n<p>Disputaban los jud\u00edos entre s\u00ed:<br>\u00ab\u00bfC\u00f3mo puede este darnos a comer su carne?\u00bb.<\/p>\n\n\n\n<p>Entonces Jes\u00fas les dijo:<br>\u00abEn verdad, en verdad os digo: si no com\u00e9is la carne del Hijo del hombre y no beb\u00e9is su sangre, no ten\u00e9is vida en vosotros. El que come mi carne y bebe mi sangre tiene vida eterna, y yo lo resucitar\u00e9 en el \u00faltimo d\u00eda.<\/p>\n\n\n\n<p>Mi carne es verdadera comida, y mi sangre es verdadera bebida.<\/p>\n\n\n\n<p>El que come mi carne y bebe mi sangre habita en m\u00ed y yo en \u00e9l.<\/p>\n\n\n\n<p>Como el Padre que vive me ha enviado, y yo vivo por el Padre, as\u00ed, del mismo modo, el que me come vivir\u00e1 por m\u00ed.<\/p>\n\n\n\n<p>Este es el pan que ha bajado del cielo: no como el de vuestros padres, que lo comieron y murieron; el que come este pan vivir\u00e1 para siempre\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color has-link-color wp-elements-c3aceebcb6fa48cdd589f1f1fca27705\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>.<\/li>\n\n\n\n<li>En este Domingo d\u00eda del Se\u00f1or, Jes\u00fas quiere darles a conocer a los jud\u00edos un misterio extraordinario de su misma persona dada como alimento verdadero para la humanidad, pero la incredulidad les impide comprender lo que \u00e9l realmente quiere revelarles.<\/li>\n\n\n\n<li>Para los hebreos sangre y carne es la totalidad del ser, de ah\u00ed que Jes\u00fas se vale de esta expresi\u00f3n para dar a entender la intimidad que quiere tener con nosotros; escuchar a Jesucristo decir que deben comer su carne y su sangre es un esc\u00e1ndalo, no es que Cristo quisiera incitarlos a una pr\u00e1ctica fuera de la religi\u00f3n sino que era una manera eficaz de explicar que \u00e9l era el alimento necesario para su crecimiento espiritual, es \u00e9l quien sacia cualquier hambre de Dios, es \u00e9l quien nos nutre.<\/li>\n\n\n\n<li>Sabemos que en todo hogar el pan es importante, es un &nbsp;t\u00e9rmino que abarca un significado amplio del alimento en general, sin \u00e9l nuestro cuerpo no podr\u00e1 subsistir es por eso que Jes\u00fas toma este ejemplo para referirse que quien come de \u00e9l que es el pan vivo no tendr\u00e1 nunca hambre, \u00e9l se hace ese pan vivo y definitivo que alimenta no por un tiempo sino que nos saciar\u00e1 por toda la eternidad.<\/li>\n\n\n\n<li>Jesucristo nos invita a ser uno con \u00e9l por medio de la sagrada Eucarist\u00eda.<\/li>\n\n\n\n<li>\u00abLa Eucarist\u00eda es el amor que se convierte en alimento.\u00bb \u2013<em><strong> San Agust\u00edn<\/strong><\/em><\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">&nbsp;&nbsp;<strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Realizar las 100 visitas al Sant\u00edsimo Sacramento del Altar.<\/li>\n\n\n\n<li>Santa Elena nos ense\u00f1a a difundir la piedad e la Pasi\u00f3n de Nuestro Se\u00f1or Jesucristo.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SANTA ELENA (+329) Santa Elena naci\u00f3 en una familia pagana y pobre, desde su juventud presenci\u00f3 la muerte de muchos cristianos, y no entend\u00eda porque eran torturados y asesinados, era mujer noble de coraz\u00f3n, contrajo matrimonio con Constancio y de ese matrimonio tuvieron un hijo quien tuvo como nombre Cesar de Maximiano, &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2024\/08\/15\/domingo-vigesima-semana-del-tiempo-ordinario-ciclo-b-18-de-agosto-2024\/\"> <span class=\"screen-reader-text\">DOMINGO, Vig\u00e9sima Semana del Tiempo Ordinario (ciclo b) -18 de agosto, 2024<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":4421,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4420","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/08\/AGOSTO-18.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/08\/AGOSTO-18.jpg",427,640,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/08\/AGOSTO-18-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/08\/AGOSTO-18-200x300.jpg",200,300,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/08\/AGOSTO-18.jpg",427,640,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/08\/AGOSTO-18.jpg",427,640,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/08\/AGOSTO-18.jpg",427,640,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/08\/AGOSTO-18.jpg",427,640,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SANTA ELENA (+329) Santa Elena naci\u00f3 en una familia pagana y pobre, desde su juventud presenci\u00f3 la muerte de muchos cristianos, y no entend\u00eda porque eran torturados y asesinados, era mujer noble de coraz\u00f3n, contrajo matrimonio con Constancio y de ese matrimonio tuvieron un hijo quien tuvo como nombre Cesar de Maximiano,&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/4420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=4420"}],"version-history":[{"count":5,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/4420\/revisions"}],"predecessor-version":[{"id":6776,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/4420\/revisions\/6776"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/4421"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=4420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=4420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=4420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}