{"id":4377,"date":"2024-08-09T18:40:00","date_gmt":"2024-08-09T23:40:00","guid":{"rendered":"https:\/\/devocionario.net\/?p=4377"},"modified":"2024-08-09T18:40:02","modified_gmt":"2024-08-09T23:40:02","slug":"domingo-decimonovena-semana-del-tiempo-ordinario-ciclo-b-11-de-agosto-2024","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2024\/08\/09\/domingo-decimonovena-semana-del-tiempo-ordinario-ciclo-b-11-de-agosto-2024\/","title":{"rendered":"DOMINGO, Decimonovena Semana del Tiempo Ordinario (ciclo b) -11 de agosto, 2024"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/08\/AGOSTO-11.jpg\" alt=\"\" class=\"wp-image-4378\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/08\/AGOSTO-11.jpg 640w, https:\/\/devocionario.net\/wp-content\/uploads\/2024\/08\/AGOSTO-11-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-ast-global-color-6-color has-text-color\"><strong>SANTA CLARA (1193-1253)<\/strong><\/p>\n\n\n\n<p>Santa Clara fue una disc\u00edpula fiel de San Francisco de As\u00eds, naci\u00f3 en As\u00eds, hija del conde Sasso Rosso, un domingo de ramos huyo a la iglesia de Santa Mar\u00eda de los \u00c1ngeles sin que lo supieran sus padres, donde la esperaba San Francisco de as\u00eds con un h\u00e1bito de su misma orden, le cort\u00f3 sus trenzas y coloco un trapo negro para ocultar su cabellera, desde muy peque\u00f1a Santa Clara quer\u00eda imitar los pasos de San Francisco, por eso decide renunciar a sus riquezas y vivir en servicio para los dem\u00e1s junto al santo, as\u00ed que a\u00f1os m\u00e1s tarde junto con su hermana In\u00e9s y otras j\u00f3venes funda una comunidad dedic\u00e1ndose a los m\u00e1s pobres, y ped\u00eda limosna, pues el lema de la comunidad era vivir de la providencia de Dios, tiempo despu\u00e9s muere en el convento glorificando Dios.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Juan 6,41-51<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, los jud\u00edos murmuraban de Jes\u00fas porque hab\u00eda dicho: \u00abYo soy el pan bajado del cielo\u00bb, y dec\u00edan:<br>\u00ab\u00bfNo es este Jes\u00fas, el hijo de Jos\u00e9? \u00bfNo conocemos a su padre y a su madre? \u00bfC\u00f3mo dice ahora que ha bajado del cielo?\u00bb<\/p>\n\n\n\n<p>Jes\u00fas tom\u00f3 la palabra y les dijo:<br>\u00abNo critiqu\u00e9is. Nadie puede venir a m\u00ed si no lo atrae el Padre que me ha enviado.<\/p>\n\n\n\n<p>Y yo lo resucitar\u00e9 en el \u00faltimo d\u00eda.<\/p>\n\n\n\n<p>Est\u00e1 escrito en los profetas: \u201cSer\u00e1n todos disc\u00edpulos de Dios\u201d.<\/p>\n\n\n\n<p>Todo el que escucha al Padre y aprende, viene a m\u00ed.<\/p>\n\n\n\n<p>No es que alguien haya visto al Padre, a no ser el que est\u00e1 junto a Dios: ese ha visto al Padre. En verdad, en verdad os digo: el que cree tiene vida eterna.<\/p>\n\n\n\n<p>Yo soy el pan de la vida. Vuestros padres comieron en el desierto el man\u00e1 y murieron: este es el pan que baja del cielo, para que el hombre coma de \u00e9l y no muera.<\/p>\n\n\n\n<p>Yo soy el pan vivo que ha bajado del cielo; el que coma de este pan vivir\u00e1 para siempre.<\/p>\n\n\n\n<p>Y el pan que yo dar\u00e9 es mi carne para la vida del mundo\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color has-link-color wp-elements-c3aceebcb6fa48cdd589f1f1fca27705\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En este Domingo d\u00eda del Se\u00f1or, el Evangelio quiere dar a conocer a los jud\u00edos un misterio extraordinario  el alimento verdadero para la humanidad, pero la incredulidad les impide comprender lo que \u00e9l realmente quiere revelarles, es \u00e9l mismo d\u00e1ndose como nutrimento que da vida.<\/li>\n\n\n\n<li>Para los hebreos sangre y carne es la totalidad del ser, de ah\u00ed que Jes\u00fas se vale de esta expresi\u00f3n para dar a entender la intimidad que quiere tener con nosotros; escuchar a Jesucristo decir que deben comer su carne y su sangre es un esc\u00e1ndalo, no es que Cristo quisiera incitarlos a una pr\u00e1ctica can\u00edbal,sino que era una manera eficaz de explicar que \u00e9l era el alimento necesario para su crecimiento espiritual, es \u00e9l quien sacia cualquier hambre de Dios, es \u00e9l quien nos nutre.<\/li>\n\n\n\n<li>Sabemos que en todo hogar el pan es importante, es un &nbsp;t\u00e9rmino que abarca un significado amplio del alimento en general, sin \u00e9l nuestro cuerpo no podr\u00e1 subsistir es por eso que Jes\u00fas toma este ejemplo para referirse que quien come de \u00e9l que es el pan vivo no tendr\u00e1 nunca hambre, \u00e9l se hace ese pan vivo y definitivo que alimenta no por un tiempo sino que nos saciar\u00e1 por toda la eternidad.<\/li>\n\n\n\n<li>Jesucristo nos invita a ser uno con \u00e9l por medio de la sagrada Eucarist\u00eda, nos hace participes de un banquete que se da a todo aquel que quiera aceptarlo en su interior que quiera que \u00e9l haga morada en su ser.<\/li>\n\n\n\n<li>Es el cuerpo y la sangre del mismo Jes\u00fas contemplado en las esencias del pan y del vino consagrado, un milagro de amor infinito.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">&nbsp;&nbsp;<strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Hoy comulgar\u00e9, pero si no lo puedo hacer buscar la gracia a trav\u00e9s del sacramento de la confesi\u00f3n. <\/li>\n\n\n\n<li>San Clara de As\u00eds: &#8220;Solo hay un error en la vida, no gastarla en Dios&#8221;.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SANTA CLARA (1193-1253) Santa Clara fue una disc\u00edpula fiel de San Francisco de As\u00eds, naci\u00f3 en As\u00eds, hija del conde Sasso Rosso, un domingo de ramos huyo a la iglesia de Santa Mar\u00eda de los \u00c1ngeles sin que lo supieran sus padres, donde la esperaba San Francisco de as\u00eds con un h\u00e1bito &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2024\/08\/09\/domingo-decimonovena-semana-del-tiempo-ordinario-ciclo-b-11-de-agosto-2024\/\"> <span class=\"screen-reader-text\">DOMINGO, Decimonovena Semana del Tiempo Ordinario (ciclo b) -11 de agosto, 2024<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":4378,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/08\/AGOSTO-11.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/08\/AGOSTO-11.jpg",640,427,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/08\/AGOSTO-11-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/08\/AGOSTO-11-300x200.jpg",300,200,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/08\/AGOSTO-11.jpg",640,427,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/08\/AGOSTO-11.jpg",640,427,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/08\/AGOSTO-11.jpg",640,427,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/08\/AGOSTO-11.jpg",640,427,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SANTA CLARA (1193-1253) Santa Clara fue una disc\u00edpula fiel de San Francisco de As\u00eds, naci\u00f3 en As\u00eds, hija del conde Sasso Rosso, un domingo de ramos huyo a la iglesia de Santa Mar\u00eda de los \u00c1ngeles sin que lo supieran sus padres, donde la esperaba San Francisco de as\u00eds con un h\u00e1bito&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/4377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=4377"}],"version-history":[{"count":4,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/4377\/revisions"}],"predecessor-version":[{"id":6723,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/4377\/revisions\/6723"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/4378"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=4377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=4377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=4377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}