{"id":4217,"date":"2024-07-12T11:11:16","date_gmt":"2024-07-12T16:11:16","guid":{"rendered":"https:\/\/devocionario.net\/?p=4217"},"modified":"2024-07-12T11:11:18","modified_gmt":"2024-07-12T16:11:18","slug":"domingo-decimoquinta-semana-del-tiempo-ordinario-ciclo-b-14-de-julio-2024","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2024\/07\/12\/domingo-decimoquinta-semana-del-tiempo-ordinario-ciclo-b-14-de-julio-2024\/","title":{"rendered":"DOMINGO, D\u00e9cimoquinta Semana del Tiempo Ordinario (ciclo b) -14 de julio, 2024"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"612\" height=\"408\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/07\/julio-14.jpg\" alt=\"\" class=\"wp-image-4218\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/07\/julio-14.jpg 612w, https:\/\/devocionario.net\/wp-content\/uploads\/2024\/07\/julio-14-300x200.jpg 300w\" sizes=\"(max-width: 612px) 100vw, 612px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\"><strong>SAN CAMILO DE LELIS (1550-1614)<\/strong><\/p>\n\n\n\n<p>San Camilo nacido en Abruzos(Italia), encamin\u00f3 su vida a la carrera militar como su padre, durante las guerra obtuvo una llaga en uno de sus pies, lo cu\u00e1l le hizo dejar las armas y dirigirse al hospital, all\u00ed se dedic\u00f3 al cuidado de los enfermos porque le gustaba servir, y tambi\u00e9n al juego de azar que lo llev\u00f3 a la ruina, pues su obsesi\u00f3n por esta pr\u00e1ctica era tan grande que perdi\u00f3 su estabilidad econ\u00f3mica. A\u00f1os m\u00e1s tarde a la edad de 25 a\u00f1os, en total pobreza, y ocupando el cargo de mensajero en un convento de los Capuchinos, se convirti\u00f3 por una predica escuchada de un padre superior , pidi\u00f3 perd\u00f3n por sus pecados y quiso pertenecer a la comunidad de los franciscanos pero su llaga en el pie volvi\u00f3 aparecer, luego pidi\u00f3 ser admitido en los Capuchinos pero su problema de salud siempre lo enviaba al hospital as\u00ed que se dedico a curar enfermos, y estando en este servicio lo nombraron asistente general del hospital. Despu\u00e9s teniendo la direcci\u00f3n espiritual de San Felipe Neri y estudiando teolog\u00eda, se ordenada sacerdote, fund\u00f3 una comunidad llamada siervos de los enfermos encargada al servicio de los hospitales, pues la demanda de peregrinos que llegaban a Roma era tan grande que decidi\u00f3 dedicarse por completo a este hermoso servicio con los enfermos, trataba a cada uno de ellos como si fuera el mismo Jes\u00fas, su paciencia le permiti\u00f3 sobrellevar su enfermedad durante muchos a\u00f1os y nunca se quejo, al contrario serv\u00eda con amor a quienes padec\u00edan dolores del cuerpo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Marcos 6,7-13<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, llam\u00f3 Jes\u00fas a los Doce y los fue enviando de dos en dos, d\u00e1ndoles autoridad sobre los esp\u00edritus inmundos. Les encarg\u00f3 que llevaran para el camino un bast\u00f3n y nada m\u00e1s, pero ni pan, ni alforja, ni dinero suelto en la faja; que llevasen sandalias, pero no una t\u00fanica de repuesto.<br>Y a\u00f1adi\u00f3:<br>\u00abQuedaos en la casa donde entr\u00e9is, hasta que os vay\u00e1is de aquel sitio. Y si un lugar no os recibe ni os escucha, al marcharos sacud\u00edos el polvo de los pies, en testimonio contra ellos\u00bb.<br>Ellos salieron a predicar la conversi\u00f3n, echaban muchos demonios, ung\u00edan con aceite a muchos enfermos y los curaban.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color has-link-color wp-elements-c3aceebcb6fa48cdd589f1f1fca27705\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En el Evangelio este Domingo Jes\u00fas env\u00eda de dos en dos a sus seguidores, \u00bfporqu\u00e9? para que se acompa\u00f1en mutuamente, en esta \u00e9poca la palabra de dos testigos era cre\u00edble as\u00ed que Jes\u00fas no duda en enviarlos, les encarga una misi\u00f3n a sus disc\u00edpulos, el anuncio del Reino de Dios, los escoge para si y los env\u00eda a los dem\u00e1s, les dio su autoridad y poder para realizar milagros, no solo los motiva a Evangelizar sino que les da las armas necesarias para dar cumplimiento a su misi\u00f3n, Jes\u00fas les recuerda que las posesiones no es lo principal de ahora en adelante en sus vidas, lo primordial es llevar la Buena Nueva de Salvaci\u00f3n a todos los pueblos, les ense\u00f1a que se deben despojar y vivir cada d\u00eda intensamente en el camino de la evangelizaci\u00f3n.<\/li>\n\n\n\n<li>Les advierte que  muchos no escuchar\u00e1n sus palabras, pero que deben continuar, el sacudir el polvo de los pies para los jud\u00edos tenia un significado importante, y era dar por terminada toda responsabilidad con aquello que pudiese pasar con quienes no acogieran el Evangelio, el haberlo llevado ya era un hecho cumplido dentro de la misi\u00f3n, los ap\u00f3stoles no dudaron en ir a poner en pr\u00e1ctica lo que hab\u00edan escuchado y aprendido del Maestro.<\/li>\n\n\n\n<li>\u00bfJes\u00fas te ha llamado? \u00bfC\u00f3mo has respondido ha ese llamado?, \u00bfconf\u00edas en las palabras de Jesucristo cuando lees la Sagrada Escritura?, en el mundo de hoy Jes\u00fas nos ha hecho muchos llamamientos dulces y tiernos a lo largo de nuestra vida, nos dota de talentos, carismas y dones para ponerlos al servicio de la Evangelizaci\u00f3n, y son muchos los momentos que ignoramos su voz, nos da miedo abandonarnos y unirnos  a la voluntad de Cristo, y confiar en sus palabras, la iglesia de Jes\u00fas esta basada en el servicio y la misi\u00f3n, que nos permite dar a Conocer a Dios y hacer que lo amen como \u00e9l desea, despojarnos de lo material se hace dif\u00edcil, pero no imposible cuando lo \u00fanico que debemos buscar es a Jesucristo.<\/li>\n\n\n\n<li>Existen aun personas que reh\u00fasan de o\u00edr la palabra de Dios, se hacen los sordos y ciegos, e ignoran que Jes\u00fas les salvar\u00e1, no tienen el amor de Dios en sus corazones,  \u00bfQu\u00e9 deber\u00edamos hacer?, nuestro testimonio de vida juega un papel muy crucial a la hora de misionar porque los hechos hablan m\u00e1s que las palabras, pero si a quienes he transmitido el mensaje de Jes\u00fas no aceptan seguirlo, lo que debo hace es orar por ellos, no vayamos por donde todos van en el camino de la perdici\u00f3n seamos aquellos que sacudamos el polvo de nuestros pies y no seamos polvo que enferma y opaca la mirada de otros que quieran conocer a Dios.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">&nbsp;&nbsp;<strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Visitar un hogar este d\u00eda e invitar a un acompa\u00f1ante.<\/li>\n\n\n\n<li>San Camilo de Lelis nos ense\u00f1a: &#8220;Hermanos,\u00a0vamos\u00a0al\u00a0hospital\u00a0a\u00a0servir\u00a0a\u00a0Cristo,\u00a0remunerador\u00a0de\u00a0toda\u00a0buena\u00a0obra&#8221;.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN CAMILO DE LELIS (1550-1614) San Camilo nacido en Abruzos(Italia), encamin\u00f3 su vida a la carrera militar como su padre, durante las guerra obtuvo una llaga en uno de sus pies, lo cu\u00e1l le hizo dejar las armas y dirigirse al hospital, all\u00ed se dedic\u00f3 al cuidado de los enfermos porque le &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2024\/07\/12\/domingo-decimoquinta-semana-del-tiempo-ordinario-ciclo-b-14-de-julio-2024\/\"> <span class=\"screen-reader-text\">DOMINGO, D\u00e9cimoquinta Semana del Tiempo Ordinario (ciclo b) -14 de julio, 2024<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":4218,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4217","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/07\/julio-14.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/07\/julio-14.jpg",612,408,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/07\/julio-14-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/07\/julio-14-300x200.jpg",300,200,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/07\/julio-14.jpg",612,408,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/07\/julio-14.jpg",612,408,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/07\/julio-14.jpg",612,408,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/07\/julio-14.jpg",612,408,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SAN CAMILO DE LELIS (1550-1614) San Camilo nacido en Abruzos(Italia), encamin\u00f3 su vida a la carrera militar como su padre, durante las guerra obtuvo una llaga en uno de sus pies, lo cu\u00e1l le hizo dejar las armas y dirigirse al hospital, all\u00ed se dedic\u00f3 al cuidado de los enfermos porque le&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/4217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=4217"}],"version-history":[{"count":4,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/4217\/revisions"}],"predecessor-version":[{"id":4222,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/4217\/revisions\/4222"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/4218"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=4217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=4217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=4217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}