{"id":4001,"date":"2024-06-06T13:13:35","date_gmt":"2024-06-06T18:13:35","guid":{"rendered":"https:\/\/devocionario.net\/?p=4001"},"modified":"2024-06-06T13:13:37","modified_gmt":"2024-06-06T18:13:37","slug":"lunes-decima-semana-del-tiempo-ordinario-ciclo-b-10-de-junio-2024","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2024\/06\/06\/lunes-decima-semana-del-tiempo-ordinario-ciclo-b-10-de-junio-2024\/","title":{"rendered":"LUNES, Decima Semana del Tiempo Ordinario (ciclo b) -10 de junio, 2024"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"612\" height=\"408\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/06\/JUNIO-10.jpg\" alt=\"\" class=\"wp-image-4002\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/06\/JUNIO-10.jpg 612w, https:\/\/devocionario.net\/wp-content\/uploads\/2024\/06\/JUNIO-10-300x200.jpg 300w\" sizes=\"(max-width: 612px) 100vw, 612px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\"><strong>SAN JUAN DOMINICI (1355-1419)<\/strong><\/p>\n\n\n\n<p>San Juan Dominici se orden\u00f3 como predicador de los Dominicos a los 17 a\u00f1os, fund\u00f3 dos conventos uno en Venecia que nombr\u00f3 como Corpus Christi junto con algunos disc\u00edpulos de Catalina de Siena y en Fi\u00e9sole el convento de Santo Domingo, este \u00faltimo fue bast\u00f3n para la reforma. Cuando lo enviaron a Roma se convirti\u00f3 en el consejero de Gregorio XII que m\u00e1s adelante lo nombr\u00f3 obispo de la di\u00f3cesis de Ragusa, su fidelidad en los tiempos del cisma le permiti\u00f3 ganarse la confianza del papa Mart\u00edn V que\u00a0 envi\u00e1ndolo a Hungr\u00eda a disputar la herej\u00eda de Juan Huss, cuando trataba estos asuntos muri\u00f3 en Buda.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Mateo 5,1-12<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, al ver Jes\u00fas el gent\u00edo, subi\u00f3 al monte, se sent\u00f3 y se acercaron sus disc\u00edpulos; y, abriendo su boca, les ense\u00f1aba diciendo:<\/p>\n\n\n\n<p>\u00abBienaventurados los pobres en el esp\u00edritu,<br>porque de ellos es el reino de los cielos.<\/p>\n\n\n\n<p>Bienaventurados los mansos,<br>porque ellos heredar\u00e1n la tierra.<\/p>\n\n\n\n<p>Bienaventurados los que lloran,<br>porque ellos ser\u00e1n consolados.<\/p>\n\n\n\n<p>Bienaventurados los que tienen hambre y sed de la justicia,<br>porque ellos quedar\u00e1n saciados.<\/p>\n\n\n\n<p>Bienaventurados los misericordiosos,<br>porque ellos alcanzar\u00e1n misericordia.<\/p>\n\n\n\n<p>Bienaventurados los limpios de coraz\u00f3n,<br>porque ellos ver\u00e1n a Dios.<\/p>\n\n\n\n<p>Bienaventurados los que trabajan por la paz,<br>porque ellos ser\u00e1n llamados hijos de Dios.<\/p>\n\n\n\n<p>Bienaventurados los perseguidos por causa de la justicia,<br>porque de ellos es el reino de los cielos.<\/p>\n\n\n\n<p>Bienaventurados vosotros cuando os insulten y os persigan y os calumnien de cualquier modo por mi causa. Alegraos y regocijaos, porque vuestra recompensa ser\u00e1 grande en el cielo, que de la misma manera persiguieron a los profetas anteriores a vosotros\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color has-link-color wp-elements-c3aceebcb6fa48cdd589f1f1fca27705\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En este Evangelio Jes\u00fas invita a quienes le escuchan a ser hombres y mujeres dichosos con el servicio a los hermanos, despojarse del mundo materialista para vivir la verdadera felicidad que se basa en negarse as\u00ed mismo para donarse por completo a Jes\u00fas. Las bienaventuranzas son formas de vivir al ejemplo de Jesucristo que permite poner los ojos al cielo y vivir en este mundo haciendo la voluntad de Dios conscientes que la recompensa ser\u00e1 grande en su reino de amor. Jes\u00fas se presenta como un nuevo Mois\u00e9s que revela al pueblo unas reglas de oro.<\/li>\n\n\n\n<li>Al ser testigos de la luz y la verdad que es Jesucristo el hombre estar\u00e1 expuesto a insultos, a sentirse raro y excluido de la sociedad, y al  ir en contra de las ideolog\u00edas ser\u00e1 tomado como incomprensible, pero es que quien va a favor de la justicia no tendr\u00e1 cabida en este mundo pero todo pasar\u00e1 si se mantiene la fe en Jes\u00fas.<\/li>\n\n\n\n<li>En esta vida lo que debemos procurar es buscar los bienes de arriba, esmerarnos por alcanzar el cielo y por ser salvos, sufriendo con los dem\u00e1s y ayud\u00e1ndonos mutuamente en la construcci\u00f3n del reino, las bienaventuranzas deben ser para nosotros reglas de oro que nos mantengan firmes sin desviarnos del camino que nos conduce a Jesucristo.<\/li>\n\n\n\n<li>Cumplir  las bienaventuranzas nos har\u00e1 seres dichosos y cada sufrimiento ac\u00e1 en la tierra ser\u00e1 un premio en el cielo, debemos llevar nuestra cruz de cada d\u00eda con dignidad y amor pues seremos recompensados, no seamos parte de este mundo sino que viviendo en \u00e9l la luz de Cristo ilumine mi camino y el de otros. No busquemos el aplauso de este mundo sino el rechazo que ser\u00e1 signo de que estamos con Jes\u00fas, pues sepamos que primero lo odiaron a \u00e9l , pero nos ense\u00f1a que seremos vencedores por medio de su nombre y participes de la patria celestial, pero no pensemos que seguir a Jesucristo solo aplica en predicar, tambi\u00e9n en nuestra forma de vivir, hacer visible la verdad a trav\u00e9s de nuestros actos implica ser perseguidos, pues iremos en contra del mundo .<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">&nbsp;&nbsp;<strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cumplir con las bienaventuranzas.<\/li>\n\n\n\n<li>San Dominici se mantuvo firme a pesar de la tribulaci\u00f3n que sufr\u00eda la Iglesia, como \u00e9l sepamos mantenernos firmes hasta el fin defendiendo la verdad y siendo testigos de la luz.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN JUAN DOMINICI (1355-1419) San Juan Dominici se orden\u00f3 como predicador de los Dominicos a los 17 a\u00f1os, fund\u00f3 dos conventos uno en Venecia que nombr\u00f3 como Corpus Christi junto con algunos disc\u00edpulos de Catalina de Siena y en Fi\u00e9sole el convento de Santo Domingo, este \u00faltimo fue bast\u00f3n para la reforma. &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2024\/06\/06\/lunes-decima-semana-del-tiempo-ordinario-ciclo-b-10-de-junio-2024\/\"> <span class=\"screen-reader-text\">LUNES, Decima Semana del Tiempo Ordinario (ciclo b) -10 de junio, 2024<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":4002,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/06\/JUNIO-10.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/06\/JUNIO-10.jpg",612,408,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/06\/JUNIO-10-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/06\/JUNIO-10-300x200.jpg",300,200,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/06\/JUNIO-10.jpg",612,408,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/06\/JUNIO-10.jpg",612,408,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/06\/JUNIO-10.jpg",612,408,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/06\/JUNIO-10.jpg",612,408,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SAN JUAN DOMINICI (1355-1419) San Juan Dominici se orden\u00f3 como predicador de los Dominicos a los 17 a\u00f1os, fund\u00f3 dos conventos uno en Venecia que nombr\u00f3 como Corpus Christi junto con algunos disc\u00edpulos de Catalina de Siena y en Fi\u00e9sole el convento de Santo Domingo, este \u00faltimo fue bast\u00f3n para la reforma.&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/4001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=4001"}],"version-history":[{"count":6,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/4001\/revisions"}],"predecessor-version":[{"id":4008,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/4001\/revisions\/4008"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/4002"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=4001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=4001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=4001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}