{"id":3972,"date":"2024-06-03T16:32:39","date_gmt":"2024-06-03T21:32:39","guid":{"rendered":"https:\/\/devocionario.net\/?p=3972"},"modified":"2024-06-03T16:32:41","modified_gmt":"2024-06-03T21:32:41","slug":"miercoles-novena-semana-del-tiempo-ordinario-ciclo-b-05-de-junio-2024","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2024\/06\/03\/miercoles-novena-semana-del-tiempo-ordinario-ciclo-b-05-de-junio-2024\/","title":{"rendered":"MIERCOLES, Novena Semana del Tiempo Ordinario (ciclo b) -05 de junio, 2024"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"480\" height=\"640\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/06\/junio-5.jpg\" alt=\"\" class=\"wp-image-3974\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/06\/junio-5.jpg 480w, https:\/\/devocionario.net\/wp-content\/uploads\/2024\/06\/junio-5-225x300.jpg 225w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color has-link-color wp-elements-29ed430cf169455f63993e410b80d045\"><strong>SAN BONIFACIO (673-754)<\/strong><\/p>\n\n\n\n<p>San Bonifacio nace en Devon, Inglaterra, fue Obispo y m\u00e1rtir, monje de Alemania que una vez ordenado obispo fue enviado a Germania para evangelizar a los pueblos; en su regreso a Alemania\u00a0 decidi\u00f3 cortar un roble que era de gran valor para los paganos pues lo consideraban un dios, all\u00ed construy\u00f3 una iglesia, al cometer tal haza\u00f1a logr\u00f3 que muchos se reunieran en aquel lugar aprovechando la oportunidad anunci\u00f3 la fe de Cristo. Ya anciano cuando celebraba la Misa un grupo de infieles armados con espadas intimidaron a los misioneros, Bonifacio exclam\u00f3 \u201cNo teman. Todas las armas de este mundo no pueden matar nuestra alma\u201d, la espada de uno de ellos se dirigi\u00f3 a la cabeza del m\u00e1rtir, Bonifacio se cubri\u00f3 con el misal pero no resisti\u00f3 al impacto muriendo instant\u00e1neamente.\u00a0 <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Marcos 12,18-27<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, se acercan a Jes\u00fas unos saduceos, los cuales dicen que no hay resurrecci\u00f3n, y le preguntan:<br>\u00abMaestro, Mois\u00e9s nos dej\u00f3 escrito: \u201cSi a uno se le muere su hermano, dejando mujer pero no hijos, que se case con la viuda y de descendencia a su hermano\u201d.<br>Pues bien, hab\u00eda siete hermanos: el primero se cas\u00f3 y muri\u00f3 sin hijos; el segundo se cas\u00f3 con la viuda y muri\u00f3 tambi\u00e9n sin hijos; lo mismo el tercero; y ninguno de los siete dej\u00f3 hijos. Por \u00faltimo muri\u00f3 la mujer.<br>Cuando llegue la resurrecci\u00f3n y resuciten, \u00bfde cu\u00e1l de ellos ser\u00e1 mujer? Porque los siete han estado casados con ella\u00bb.<br>Jes\u00fas les respondi\u00f3:<br>\u00ab\u00bfNo est\u00e1is equivocados, por no entender la Escritura ni el poder de Dios? Pues cuando resuciten, ni los hombres se casar\u00e1n ni las mujeres ser\u00e1n dadas en matrimonio, ser\u00e1n como \u00e1ngeles del cielo.<br>Y a prop\u00f3sito de que los muertos resucitan, \u00bfno hab\u00e9is le\u00eddo en el libro de Mois\u00e9s, en el episodio de la zarza, lo que le dijo Dios: \u201cYo soy el Dios de Abrah\u00e1n, el Dios de Isaac, el Dios de Jacob\u201d? No es Dios de muertos, sino de vivos. Est\u00e1is muy equivocados\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color has-link-color wp-elements-c3aceebcb6fa48cdd589f1f1fca27705\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En el Evangelio de hoy, los Saduceos estaban encerrados en sus propias creencias bloqueados en su forma de pensar cerrando sus corazones a cosas nuevas y a otras posibilidades que pudiesen escuchar, limitados a escuchar el mensaje de Jes\u00fas, es que en el cielo solo Dios ser\u00e1 el centro, ya nada m\u00e1s importa porque \u00e9l lo llenara todo, es por eso que enamorarse de \u00e9l, depender solo de \u00e9l es la tarea de cada cristiano.<\/li>\n\n\n\n<li>Jes\u00fas quiere mostrar el misterio de la muerte y la resurrecci\u00f3n que est\u00e1 m\u00e1s all\u00e1 de la capacidad de entendimiento, y se entiende a la luz de la fe,  revela una promesa que no acaba con la muerte pues si se permanece en su presencia en esta tierra en la eternidad tambi\u00e9n lo ser\u00e1, esta vida es una preparaci\u00f3n a la otra vida a la eterna, Dios vive y vivir\u00e1 siempre, es lo que cada hombre debe tener presente, esta vida es un paso.<\/li>\n\n\n\n<li>Jesucristo nos invita a tener fe, teniendo la certeza que el Dios a quien seguimos es un Dios vivo, que molde\u00e1ndonos con su amor nos promete continuidad en la otra vida despu\u00e9s de la muerte.<\/li>\n\n\n\n<li>En la actualidad muchos religiosos preocupados por ciertos detalles olvidan lo que supremamente importa y es el mensaje de Dios que da vida.<\/li>\n\n\n\n<li>Creer en la resurrecci\u00f3n me hace part\u00edcipe de la vida eterna, pues tenemos la confianza que todo nuestro esfuerzo tendr\u00e1 su recompensa, que tendremos una vida junto al Padre, que la promesa hecha por Cristo que estar\u00eda por siempre con nosotros se cumplir\u00e1, no cerremos nuestro coraz\u00f3n a creer que si morimos con Jesucristo, tambi\u00e9n viviremos con \u00e9l.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">&nbsp;&nbsp;<strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Orar por los difuntos para que Dios les conceda vivir en su mansi\u00f3n celestial, su gran misericordia de Padre los arrope y los haga participes de su resurrecci\u00f3n.<\/li>\n\n\n\n<li>San Bonifacio nos dice: &#8220;Vencerse as\u00ed mismo es la mayor de las victorias&#8221;.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN BONIFACIO (673-754) San Bonifacio nace en Devon, Inglaterra, fue Obispo y m\u00e1rtir, monje de Alemania que una vez ordenado obispo fue enviado a Germania para evangelizar a los pueblos; en su regreso a Alemania\u00a0 decidi\u00f3 cortar un roble que era de gran valor para los paganos pues lo consideraban un dios, &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2024\/06\/03\/miercoles-novena-semana-del-tiempo-ordinario-ciclo-b-05-de-junio-2024\/\"> <span class=\"screen-reader-text\">MIERCOLES, Novena Semana del Tiempo Ordinario (ciclo b) -05 de junio, 2024<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":3974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3972","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/06\/junio-5.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/06\/junio-5.jpg",480,640,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/06\/junio-5-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/06\/junio-5-225x300.jpg",225,300,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/06\/junio-5.jpg",480,640,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/06\/junio-5.jpg",480,640,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/06\/junio-5.jpg",480,640,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/06\/junio-5.jpg",480,640,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SAN BONIFACIO (673-754) San Bonifacio nace en Devon, Inglaterra, fue Obispo y m\u00e1rtir, monje de Alemania que una vez ordenado obispo fue enviado a Germania para evangelizar a los pueblos; en su regreso a Alemania\u00a0 decidi\u00f3 cortar un roble que era de gran valor para los paganos pues lo consideraban un dios,&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/3972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=3972"}],"version-history":[{"count":4,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/3972\/revisions"}],"predecessor-version":[{"id":6278,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/3972\/revisions\/6278"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/3974"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=3972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=3972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=3972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}