{"id":3440,"date":"2024-02-08T13:32:13","date_gmt":"2024-02-08T18:32:13","guid":{"rendered":"https:\/\/devocionario.net\/?p=3440"},"modified":"2024-02-08T13:32:16","modified_gmt":"2024-02-08T18:32:16","slug":"lunes-sexta-semana-del-tiempo-ordinario-ciclo-b-12-febrero-2024","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2024\/02\/08\/lunes-sexta-semana-del-tiempo-ordinario-ciclo-b-12-febrero-2024\/","title":{"rendered":"LUNES, Sexta semana del tiempo Ordinario (ciclo b) -12 febrero, 2024"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/02\/Febrero-11.jpg\" alt=\"\" class=\"wp-image-3441\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/02\/Febrero-11.jpg 640w, https:\/\/devocionario.net\/wp-content\/uploads\/2024\/02\/Febrero-11-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color has-link-color wp-elements-f75eacb4c46db4cb4b7d55d7ef455096\"><strong>SANTA EULALIA DE BARCELONA (SIGLO IV)<\/strong><\/p>\n\n\n\n<p>Santa Eulalia vivi\u00f3 en la actual Barcelona, siendo Papa San Marcelino, cuando el emperador Diocleciano comenz\u00f3 la persecuci\u00f3n de los cristianos, Santa Eulalia con tan solo trece a\u00f1os de edad estaba enfadada y tenia iniciativas de presentarse ante el gobierno y defender su fe en Jesucristo, pero sus Padres la llevaron a un campo, d\u00edas despu\u00e9s ella se escap\u00f3 y se dirigi\u00f3 inmediatamente ante el gobernador Daciano para protestar de los cultos a los \u00eddolos, el gobernador le ofreci\u00f3 regalos y le mostr\u00f3 los tipos de tortura para que ella desistiera de su fe , pero ella insist\u00eda en defender su adoraci\u00f3n a Dios, as\u00ed que la torturaron d\u00e1ndole golpes con varillas de hierro y luego su cabellera se enciende y muere ahogada con el humo, quienes la torturaron vieron salir como una paloma y sintieron remordimiento de esta inocente ni\u00f1a.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Marcos  8,11-13<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, se presentaron los fariseos y se pusieron a discutir con Jes\u00fas; para ponerlo a prueba, le pidieron un signo del cielo.<\/p>\n\n\n\n<p>Jes\u00fas dio un profundo suspiro y dijo:<br>\u00ab\u00bfPor qu\u00e9 esta generaci\u00f3n reclama un signo? En verdad os digo que no se le dar\u00e1 un signo a esta generaci\u00f3n\u00bb.<\/p>\n\n\n\n<p>Los dej\u00f3, se embarc\u00f3 de nuevo y se fue a la otra orilla.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color has-link-color wp-elements-c3aceebcb6fa48cdd589f1f1fca27705\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>San Marcos hoy presenta a un Jes\u00fas indiferente a la pregunta sin fe de los fariseos, estos hombres no esperaban a un Mes\u00edas con las caracter\u00edsticas de Jes\u00fas, esperaban a un Mes\u00edas que vendr\u00eda a sacar a los invasores, a los pecadores del Pueblo de Israel, es por eso que enceguecidos criticaban las actuaciones de Jesucristo, rechazaban su mensaje dirigido directamente a los pecadores, a los pobres, y a los marginados.<\/li>\n\n\n\n<li>Jesucristo sabe que quien cree en \u00e9l s\u00f3lo implora misericordia, un signo no es m\u00e1s que  la falta de fe, quien no cree quiere ver para creer, quiere aprobar las palabras con hechos, pero Jes\u00fas les deja,  la ignorancia de los fariseos es constante su ceguera es irreversible. Jes\u00fas es su vida p\u00fablica insisti\u00f3 en encarnar el rostro misericordioso y humano de Dios Padre, no ven\u00eda como un Dios fant\u00e1stico y majestuoso, sino lo contrario, humilde y compasivo con la raza humana.<\/li>\n\n\n\n<li>No estamos muy lejos del cumplimiento de este pasaje b\u00edblico en nuestro tiempo, buscamos milagros para creerle a Jesucristo, si sanamos, si obtenemos el trabajo anhelado, si en casa todo anda bien, si somos exitosos y pr\u00f3speros son los signos que nos permiten tener la confianza en el Se\u00f1or, es lastimoso pensar de esta manera, no es lo que debemos conocer de Jes\u00fas entre m\u00e1s nos sumergimos en su persona encontraremos  pruebas a nuestro paso, entre m\u00e1s conocemos de \u00e9l no podemos buscar signos, nosotros mismos nos hacemos signos de conversi\u00f3n para quienes quieran saber de ese Dios amor.<\/li>\n\n\n\n<li>El ser humano siempre va buscando signos para comprender los designios de Dios, no busquemos esto hermanos, vivamos la fe en Dios desde otra perspectiva, amando, sirviendo, all\u00ed en esas acciones encontraremos el verdadero significado de nuestras vidas, la respuesta a la Palabra de Dios, y comprobaremos que imitar a Jes\u00fas es lo que realmente importa, que amarlo es lo que nos salvara y nos llevar\u00e1 a su reino celestial.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">&nbsp;&nbsp;<strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cuando salga a la calle buscar\u00e9 a Jes\u00fas en el rostro del necesitado, del enfermo y comprender\u00e9 su amor hacia mi.<\/li>\n\n\n\n<li>San Eulalia nos invita a tener valent\u00eda y a preguntarnos no como hacemos el bien , sino por quien hacemos el bien, solo por Jesucristo.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SANTA EULALIA DE BARCELONA (SIGLO IV) Santa Eulalia vivi\u00f3 en la actual Barcelona, siendo Papa San Marcelino, cuando el emperador Diocleciano comenz\u00f3 la persecuci\u00f3n de los cristianos, Santa Eulalia con tan solo trece a\u00f1os de edad estaba enfadada y tenia iniciativas de presentarse ante el gobierno y defender su fe en Jesucristo, &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2024\/02\/08\/lunes-sexta-semana-del-tiempo-ordinario-ciclo-b-12-febrero-2024\/\"> <span class=\"screen-reader-text\">LUNES, Sexta semana del tiempo Ordinario (ciclo b) -12 febrero, 2024<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":3441,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-3440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tiempo-ordinario"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2024\/02\/Febrero-11.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/02\/Febrero-11.jpg",640,427,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/02\/Febrero-11-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/02\/Febrero-11-300x200.jpg",300,200,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/02\/Febrero-11.jpg",640,427,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/02\/Febrero-11.jpg",640,427,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/02\/Febrero-11.jpg",640,427,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2024\/02\/Febrero-11.jpg",640,427,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SANTA EULALIA DE BARCELONA (SIGLO IV) Santa Eulalia vivi\u00f3 en la actual Barcelona, siendo Papa San Marcelino, cuando el emperador Diocleciano comenz\u00f3 la persecuci\u00f3n de los cristianos, Santa Eulalia con tan solo trece a\u00f1os de edad estaba enfadada y tenia iniciativas de presentarse ante el gobierno y defender su fe en Jesucristo,&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/3440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=3440"}],"version-history":[{"count":2,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/3440\/revisions"}],"predecessor-version":[{"id":3443,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/3440\/revisions\/3443"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/3441"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=3440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=3440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=3440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}