{"id":3181,"date":"2023-12-15T10:01:37","date_gmt":"2023-12-15T15:01:37","guid":{"rendered":"https:\/\/devocionario.net\/?p=3181"},"modified":"2023-12-15T10:01:39","modified_gmt":"2023-12-15T15:01:39","slug":"viernes-segunda-semana-de-adviento-ciclo-b-15-diciembre-2023","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2023\/12\/15\/viernes-segunda-semana-de-adviento-ciclo-b-15-diciembre-2023\/","title":{"rendered":"VIERNES, segunda semana de adviento (ciclo b) -15 diciembre, 2023"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/12\/diciembre-15-682x1024.jpg\" alt=\"\" class=\"wp-image-3184\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/12\/diciembre-15-682x1024.jpg 682w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/12\/diciembre-15-200x300.jpg 200w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/12\/diciembre-15-768x1152.jpg 768w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/12\/diciembre-15.jpg 853w\" sizes=\"(max-width: 682px) 100vw, 682px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\"><strong>SANTA MAR\u00cdA DE LA ROSA (1813-1855)<\/strong><\/p>\n\n\n\n<p>Santa Mar\u00eda nace en Brescia (Italia), su Madre muri\u00f3 cuando ella era muy peque\u00f1a, su Padre ya le hab\u00eda conseguido un esposo en su adolescencia pero Mar\u00eda pidi\u00f3 la intercesi\u00f3n de su p\u00e1rroco para que convenciera a su Padre de la vida que quer\u00eda llevar sirviendo a los m\u00e1s pobres y guardando castidad, su Padre acept\u00f3 y la apoyo. Santa Mar\u00eda fund\u00f3 unas asociaciones religiosas con mujeres que hac\u00edan parte del negocio de tejidos de su Padre as\u00ed como la finca familiar, a ellas les infundi\u00f3 un fervor y piedad enormes, y un esp\u00edritu de caridad admirable, en su Parroquia tambi\u00e9n organiz\u00f3 retiros y misiones para acrecentar la espiritualidad de muchos, estudiaba libros religiosos y de teolog\u00eda y tenia mucha sabidur\u00eda . A\u00f1os m\u00e1s tarde la peste del c\u00f3lera llego a Brescia y Mar\u00eda se ofreci\u00f3 en compa\u00f1\u00eda de una viuda para prestar el servicio de enfermer\u00eda, a muchos ayudaron y su Padre con temor le autoriz\u00f3 estar en los hospitales. Fueron muchas ni\u00f1as que quedaron hu\u00e9rfanas, as\u00ed que Mar\u00eda se encarga de la administraci\u00f3n de los talleres que los gobernantes dejaron en sus manos, pero luego ella decide fundar sus propios orfanatos, tiempo despu\u00e9s Monse\u00f1or Pinzoni fund\u00f3 una asociaci\u00f3n piadosa de mujeres para atender a los enfermos de los hospitales y nombraron a Mar\u00eda como Superiora aquella asociaci\u00f3n se llam\u00f3  Esclavas de la Caridad, fueron llamadas por los militares, su obra con los enfermos fue impresionantemente hermosa, un d\u00eda los soldados entraron donde ellas estaban y quisieron irrespetarlas y Santa Mar\u00eda tomo un crucifijo junto con sus compa\u00f1eras que llevaban cirios encendidos y evitaron que los soldados entraran, este crucifijo se convirti\u00f3 en un signo de devoci\u00f3n. Santa Mar\u00eda se dirige un d\u00eda al Sumo Pont\u00edfice P\u00edo Nono para que fuera aprobada su consagraci\u00f3n, luego por su delicada salud muere de un ataque.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Mateo 11,16-19<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, dijo Jes\u00fas al gent\u00edo:<br>\u00ab\u00bfA qui\u00e9n comparar\u00e9 esta generaci\u00f3n?<br>Se asemeja a unos ni\u00f1os sentados en la plaza, que gritan diciendo: \u201cHemos tocado la flauta, y no hab\u00e9is bailado; hemos entonado lamentaciones, y no hab\u00e9is llorado\u201d.<br>Porque vino Juan, que ni com\u00eda ni beb\u00eda, y dicen: \u201cTiene un demonio\u201d. Vino el Hijo del hombre, que come y bebe, y dicen: \u201cAh\u00ed ten\u00e9is a un comil\u00f3n y borracho, amigo de publicanos y pecadores\u201d.<br>Pero la sabidur\u00eda se ha acreditado por sus obras\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-purple-color has-text-color\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Jes\u00fas en este pasaje b\u00edblico, se queda admirado de la inconformidad de quienes escuchan el mensaje de Dios, est\u00e1n cerrados excus\u00e1ndose de su mal proceder, una generaci\u00f3n cerrada al anuncio del Evangelio. <\/li>\n\n\n\n<li>Jesucristo denuncia a quienes muestran una total indiferencia a su presencia, les anuncia la Buena Nueva respaldada por las obras, los profetas vinieron a proclamar la palabra de Dios, pero sus obras hablaron de ese Dios del que predicaban, y as\u00ed tambi\u00e9n Jes\u00fas lo hizo en su vida p\u00fablica, su coherencia de vida fue el testimonio exacto para anunciar a los pueblos el plan de salvaci\u00f3n trazado por Dios para toda la humanidad.<\/li>\n\n\n\n<li>Hoy en d\u00eda somos esa generaci\u00f3n de la que Jes\u00fas hace una denuncia, estamos en todo momento excus\u00e1ndonos y criticando el porque no asistimos a la Iglesia, el porque andamos sin piedad, \u00bf No ser\u00e1 m\u00e1s bien que nos hacemos los sordos y los ciegos para no dejar nuestro pecado e ignorar nuestra constante conversi\u00f3n?, El Se\u00f1or nos interpela, nos habla, nos invita a dejar toda nuestra vida pasada por \u00e9l.<\/li>\n\n\n\n<li>El ser humano esta dado a criticar  siempre a destruir las obras buenas, muchas veces vemos el lado negativo de las cosas, sin antes reflexionar y \u00bfYo que estoy haciendo por construir el reino de Dios? , nuestra incoherencia nos hace tambalear en la fe y alejarnos de la verdadera riqueza de nuestra vida y es tener a Jesucristo en nuestros corazones,\u00bf Cu\u00e1l es nuestra actitud frente a las cosas de Dios? \u00bf Que hago para llevar a otros a este camino de fe?.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">&nbsp;&nbsp;<strong>PR\u00c1CTICA DIARIA<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Hoy dejar\u00e9 la critica destructiva y aportare ideas sabias para la construcci\u00f3n de templos espirituales en mi parroquia.<\/li>\n\n\n\n<li>Santa Mar\u00eda no le import\u00f3 la critica sino que empleo la sabidur\u00eda para ayudar a los m\u00e1s necesitados sin da\u00f1ar a otros.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SANTA MAR\u00cdA DE LA ROSA (1813-1855) Santa Mar\u00eda nace en Brescia (Italia), su Madre muri\u00f3 cuando ella era muy peque\u00f1a, su Padre ya le hab\u00eda conseguido un esposo en su adolescencia pero Mar\u00eda pidi\u00f3 la intercesi\u00f3n de su p\u00e1rroco para que convenciera a su Padre de la vida que quer\u00eda llevar sirviendo &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2023\/12\/15\/viernes-segunda-semana-de-adviento-ciclo-b-15-diciembre-2023\/\"> <span class=\"screen-reader-text\">VIERNES, segunda semana de adviento (ciclo b) -15 diciembre, 2023<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":3184,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-3181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tiempo-adviento"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/12\/diciembre-15.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/12\/diciembre-15.jpg",853,1280,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/12\/diciembre-15-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/12\/diciembre-15-200x300.jpg",200,300,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/12\/diciembre-15-768x1152.jpg",768,1152,true],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/12\/diciembre-15-682x1024.jpg",682,1024,true],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/12\/diciembre-15.jpg",853,1280,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/12\/diciembre-15.jpg",853,1280,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SANTA MAR\u00cdA DE LA ROSA (1813-1855) Santa Mar\u00eda nace en Brescia (Italia), su Madre muri\u00f3 cuando ella era muy peque\u00f1a, su Padre ya le hab\u00eda conseguido un esposo en su adolescencia pero Mar\u00eda pidi\u00f3 la intercesi\u00f3n de su p\u00e1rroco para que convenciera a su Padre de la vida que quer\u00eda llevar sirviendo&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/3181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=3181"}],"version-history":[{"count":2,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/3181\/revisions"}],"predecessor-version":[{"id":3185,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/3181\/revisions\/3185"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/3184"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=3181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=3181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=3181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}