{"id":3142,"date":"2023-12-05T17:14:07","date_gmt":"2023-12-05T22:14:07","guid":{"rendered":"https:\/\/devocionario.net\/?p=3142"},"modified":"2023-12-05T17:14:09","modified_gmt":"2023-12-05T22:14:09","slug":"miercoles-primera-semana-de-adviento-ciclo-b-06-diciembre-2023","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2023\/12\/05\/miercoles-primera-semana-de-adviento-ciclo-b-06-diciembre-2023\/","title":{"rendered":"MIERCOLES, primera semana de adviento (ciclo b) -06 diciembre, 2023"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"612\" height=\"382\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/12\/DICIEMBRE-6.jpg\" alt=\"\" class=\"wp-image-3143\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/12\/DICIEMBRE-6.jpg 612w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/12\/DICIEMBRE-6-300x187.jpg 300w\" sizes=\"(max-width: 612px) 100vw, 612px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\"><strong>SAN NICOLAS DE MIRA (270-352)<\/strong><\/p>\n\n\n\n<p>San Nicol\u00e1s nace en la ciudad de Licia (Territorio de Turqu\u00eda), en una familia cristiana y acomodada, eran generosos sus Padres con la gente del pueblo, un d\u00eda cayeron enfermos por una epidemia y murieron dejando a San Nicol\u00e1s hu\u00e9rfano pero con riquezas, tiempo despu\u00e9s ingres\u00f3 al monasterio y se hizo sacerdote, luego, de su llegada de Tierra Santa fue nombrado  Obispo de Mira aproximadamente en el siglo IV, este Santo vivi\u00f3 una vida de generosidad con sus semejantes, defendi\u00f3 la fe en aquellos tiempos donde el arrianismo (niegan la divinidad de Jesucristo) era popular, adem\u00e1s se cuenta que ayud\u00f3 a muchos pobres, en especial a tres v\u00edrgenes que ser\u00edan prostituidas por su Padre por vivir en extrema pobreza, San Nicol\u00e1s subi\u00f3 a la chimenea y regalo monedas de oro, y as\u00ed pudo salvarlas de su destino de pecado, tambi\u00e9n se dice que por su intercesi\u00f3n en la oraci\u00f3n logro resucitar a tres ni\u00f1os que hab\u00edan sido asesinados, en la actualidad a este Santo se le conoce como Santa Claus, o Papa Noel.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Mateo 15,29-37<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, Jes\u00fas, se dirigi\u00f3 al mar de Galilea, subi\u00f3 al monte y se sent\u00f3 en \u00e9l.<br>Acudi\u00f3 a \u00e9l mucha gente llevando tullidos, ciegos, lisiados, sordomudos y muchos otros; los pon\u00edan a sus pies, y \u00e9l los curaba.<\/p>\n\n\n\n<p>La gente se admiraba al ver hablar a los mudos, sanos a los lisiados, andar a los tullidos y con vista a los ciegos, y daban gloria al Dios de Israel.<\/p>\n\n\n\n<p>Jes\u00fas llam\u00f3 a sus disc\u00edpulos y les dijo:<br>\u00abSiento compasi\u00f3n de la gente, porque llevan ya tres d\u00edas conmigo y no tienen qu\u00e9 comer. Y no quiero despedirlos en ayunas, no sea que desfallezcan en el camino\u00bb.<\/p>\n\n\n\n<p>Los disc\u00edpulos le dijeron:<br>\u00ab\u00bfDe d\u00f3nde vamos a sacar en un despoblado panes suficientes para saciar a tanta gente?\u00bb.<\/p>\n\n\n\n<p>Jes\u00fas les dijo:<br>\u00ab\u00bfCu\u00e1ntos panes ten\u00e9is?\u00bb.<\/p>\n\n\n\n<p>Ellos contestaron:<br>\u00abSiete y algunos peces\u00bb.<\/p>\n\n\n\n<p>\u00c9l mand\u00f3 a la gente que se sentara en el suelo. Tom\u00f3 los siete panes y los peces, pronunci\u00f3 la acci\u00f3n de gracias, los parti\u00f3 y los fue dando a los disc\u00edpulos, y los disc\u00edpulos a la gente.<br>Comieron todos hasta saciarse y recogieron las sobras: siete canastos llenos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En el Evangelio de este d\u00eda Jes\u00fas siente compasi\u00f3n por quienes le escuchan, oye y atiende a las necesidades de las gentes, su mirada siempre estaba enfocada en los pobres, enfermos y necesitados de su misericordia y gracia. Jes\u00fas observa lo que el hombre pasa desapercibido, \u00e9l ve m\u00e1s all\u00e1 de las apariencias y no s\u00f3lo atiende sino que actua.<\/li>\n\n\n\n<li>Jesucristo hace ante sus disc\u00edpulos la multiplicaci\u00f3n de los panes para ense\u00f1arles el verdadero sentido de la generosidad, cuando hay compasi\u00f3n la solidaridad, hospitalidad y todo lo que se entiende por ayuda al hermano son valores que se deben aplicar para socorrer a quienes necesitan de una mano amiga, los ap\u00f3stoles pasaron por desapercibido aquel momento, pero quien realmente ama siente compasi\u00f3n por quienes le rodean es Jesucristo que proporciona alimento, y se hace alimento, Jes\u00fas utiliza aquella poca comida y la convierte en abundancia, porque para \u00e9l no existen los limites. Antes de repartir los panes y peces da gracias, cuando se aplica la gratuidad siempre el hombre ser\u00e1 bendecido.<\/li>\n\n\n\n<li>Hoy Jes\u00fas nos recuerda cuan importante somos para \u00e9l, siente compasi\u00f3n de nosotros, atiende a nuestras suplicas y necesidades, no le importa como le hallamos ofendido, sino que siempre esta dispuesto a recibirnos y a saciarnos de \u00e9l, este Evangelio de hoy nos recuerda que no andamos solos en el camino Jes\u00fas se hace alimento no perecedero que nos mantiene firmes y no nos permite desfallecer en el sendero de nuestra vida, La Eucarist\u00eda nos da las fuerzas necesarias para continuar escuchando a Jes\u00fas y seguirlo siempre.&#8221;La Eucarist\u00eda es el Sacramento de Amor: significa Amor, produce Amor&#8221;. <em>Santo Tom\u00e1s de Aquino. <\/em>\u201cCristo te muestra su mesa, es decir, a s\u00ed mismo. Ac\u00e9rcate a esa mesa y s\u00e1ciate. S\u00e9 pobre, y quedar\u00e1s saciado\u201d <em>San Agust\u00edn.<\/em><\/li>\n\n\n\n<li>Ser generosos nos permite utilizar nuestros pocos recursos en favor de quienes necesitan, cuando somos agradecidos ante Dios, podemos dar todo de nosotros porque Dios nos proporciona todo lo que poseemos, sentir con el otro nos motiva e impulsa a no ser indiferentes ante el dolor humano, nos llena de generosidad y nos revela el verdadero prop\u00f3sito de nuestra existencia aqu\u00ed en esta tierra. \u201cSi se enfr\u00eda nuestro amor, se entumece nuestra acci\u00f3n\u201d\u00a0<em>San Agust\u00edn<\/em>.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">&nbsp;&nbsp;<strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Invitar con alegr\u00eda a un amigo (a) que no haya tenido la experiencia de ir a misa, motivarlo para que busque a Dios a trav\u00e9s de la Eucarist\u00eda.<\/li>\n\n\n\n<li>Visitar una familia que necesita de mi ayuda, y llevarle un mercado.<\/li>\n\n\n\n<li>San Nicol\u00e1s me ense\u00f1a el valor de la generosidad en este tiempo de adviento donde se me invita a compartir con mis hermanos necesitados.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN NICOLAS DE MIRA (270-352) San Nicol\u00e1s nace en la ciudad de Licia (Territorio de Turqu\u00eda), en una familia cristiana y acomodada, eran generosos sus Padres con la gente del pueblo, un d\u00eda cayeron enfermos por una epidemia y murieron dejando a San Nicol\u00e1s hu\u00e9rfano pero con riquezas, tiempo despu\u00e9s ingres\u00f3 al &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2023\/12\/05\/miercoles-primera-semana-de-adviento-ciclo-b-06-diciembre-2023\/\"> <span class=\"screen-reader-text\">MIERCOLES, primera semana de adviento (ciclo b) -06 diciembre, 2023<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":3143,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-3142","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tiempo-adviento"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/12\/DICIEMBRE-6.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/12\/DICIEMBRE-6.jpg",612,382,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/12\/DICIEMBRE-6-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/12\/DICIEMBRE-6-300x187.jpg",300,187,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/12\/DICIEMBRE-6.jpg",612,382,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/12\/DICIEMBRE-6.jpg",612,382,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/12\/DICIEMBRE-6.jpg",612,382,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/12\/DICIEMBRE-6.jpg",612,382,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SAN NICOLAS DE MIRA (270-352) San Nicol\u00e1s nace en la ciudad de Licia (Territorio de Turqu\u00eda), en una familia cristiana y acomodada, eran generosos sus Padres con la gente del pueblo, un d\u00eda cayeron enfermos por una epidemia y murieron dejando a San Nicol\u00e1s hu\u00e9rfano pero con riquezas, tiempo despu\u00e9s ingres\u00f3 al&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/3142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=3142"}],"version-history":[{"count":2,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/3142\/revisions"}],"predecessor-version":[{"id":3145,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/3142\/revisions\/3145"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/3143"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=3142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=3142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=3142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}