{"id":3115,"date":"2023-11-29T17:16:40","date_gmt":"2023-11-29T22:16:40","guid":{"rendered":"https:\/\/devocionario.net\/?p=3115"},"modified":"2023-11-29T17:16:42","modified_gmt":"2023-11-29T22:16:42","slug":"jueves-trigesimo-cuarta-semana-del-tiempo-ordinario-ciclo-a-30-noviembre-2023","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2023\/11\/29\/jueves-trigesimo-cuarta-semana-del-tiempo-ordinario-ciclo-a-30-noviembre-2023\/","title":{"rendered":"JUEVES, trig\u00e9simo cuarta semana del tiempo ordinario (ciclo a) -30 noviembre, 2023"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"380\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/11\/NOVIEMBRE-30.jpg\" alt=\"\" class=\"wp-image-3116\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/11\/NOVIEMBRE-30.jpg 640w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/11\/NOVIEMBRE-30-300x178.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\"><strong>SAN ANDR\u00c9S APOSTOL (+60 d.c)<\/strong><\/p>\n\n\n\n<p>San Andr\u00e9s nacido en Betsaida (Galilea) fue un humilde pescador igual que su hermano Sim\u00f3n Pedro, ambos desempe\u00f1aban este oficio en Cafarna\u00fam, San Andr\u00e9s fue llamado por Jes\u00fas en el lago de Tiber\u00edades junto con Juan. Desde antes el ap\u00f3stol ya ten\u00eda la iniciativa de seguir al Mes\u00edas, gracias a la predicaci\u00f3n de San Juan Bautista, fue \u00e9l quien motivo a su hermano Pedro para que siguiera a Jes\u00fas llev\u00e1ndolo hasta el Maestro, en los evangelios se habla unas tres veces de Andr\u00e9s, en la multiplicaci\u00f3n de los panes, como intermediario de los forasteros, y la pregunta que le hace a Jes\u00fas para que profetice sobre la destrucci\u00f3n de Jerusal\u00e9n, despu\u00e9s de la Ascenci\u00f3n de Jesucristo anuncia la buena noticia en regiones b\u00e1rbaras como la Scitia, en la Rusia meridional, como refiere el historiador Eusebio, no se tiene certeza como muri\u00f3. El primero en recordar su memoria fue San Gregorio Nacianceno.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Mateo 4,18-22<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, paseando Jes\u00fas junto al mar de Galilea vio a dos hermanos, a Sim\u00f3n, llamado Pedro, y a Andr\u00e9s, que estaban echando la red en el mar, pues eran pescadores.<br>Les dijo:<br>\u00abVenid en pos de m\u00ed y os har\u00e9 pescadores de hombres\u00bb.<br>Inmediatamente dejaron las redes y lo siguieron.<br>Y pasando adelante vio a otros dos hermanos, a Santiago, hijo de Zebedeo, y a Juan, su hermano, que estaban en la barca repasando las redes con Zebedeo, su padre, y los llam\u00f3. Inmediatamente dejaron la barca y a su padre y lo siguieron.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Hoy se recuerda la memoria del Ap\u00f3stol Andr\u00e9s uno de los doce que acompa\u00f1\u00f3 a Jes\u00fas en su vida p\u00fablica, el Evangelio narra el llamamiento de Andr\u00e9s en su oficio como pescador, a este hombre no le import\u00f3 dejar todo por seguir al Maestro, y a Jes\u00fas no le interes\u00f3 que era lo que hac\u00edan sino se intereso en la persona, en lo que hab\u00eda en sus interiores, ve fraternidad, y este es el inicio de una buena evangelizaci\u00f3n, estar unidos en las buenas y en las malas.<\/li>\n\n\n\n<li>Andr\u00e9s ya hab\u00eda escuchado todo acerca del Mes\u00edas as\u00ed que dejando a su Padre y el sustento econ\u00f3mico, se lanza a la aventura de conocer aquel hombre que ofrece salvaci\u00f3n, y que le da el titulo de pescador de hombres, Jes\u00fas no busco personas con altos conocimientos, sino seres humanos que dieran un si sin ninguna clase de apegos, los quer\u00eda libres para anunciar su reino de amor.<\/li>\n\n\n\n<li>Hoy nuevamente Jesucristo nos hace llamamientos dulces y tiernos para que dejemos todo por seguirle, las redes que nos atan no nos permiten escuchar la voz de Dios, estamos tan apegados a las personas y a los bienes materiales, que cada llamamiento se convierte en fallido, \u00bfQu\u00e9 estoy dispuesto hacer por anunciar a Jesucristo y su mensaje salv\u00edfico?.<\/li>\n\n\n\n<li>Los ap\u00f3stoles no tuvieron ni el m\u00e1s m\u00ednimo reparo por entrar en aquella fraternidad dispuesta a llevar a todos los rincones de la tierra el mensaje del Se\u00f1or, hasta la muerte lucharon, unidos perseveraron hasta el fin, la invitaci\u00f3n de Jes\u00fas a los disc\u00edpulos de esta generaci\u00f3n es muy clara, dejar aquello que me esclaviza y no me deja avanzar en el plan de salvaci\u00f3n dise\u00f1ado por Dios para la humanidad, que estamos esperando para iniciar hoy el camino de la evangelizaci\u00f3n, desde el bautismo somos llamados a una vida en Jesucristo, nunca es tarde para comenzar, solo debemos dejarnos cautivar por el Se\u00f1or y dejar que me utilice como instrumento clave para la misi\u00f3n que ayuda a que todos lleguen al conocimiento perfecto de la verdad.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">&nbsp;&nbsp;<strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Invitar con alegr\u00eda a un amigo (a) que no haya tenido la experiencia de ir a misa, motivarlo para que busque a Dios a trav\u00e9s de la Eucarist\u00eda.<\/li>\n\n\n\n<li>San Andr\u00e9s desde  su llamamiento nos motiva a atender a la voz de Dios que resuena en nuestros corazones para que le sirvamos en la expansi\u00f3n de su mensaje de salvaci\u00f3n.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN ANDR\u00c9S APOSTOL (+60 d.c) San Andr\u00e9s nacido en Betsaida (Galilea) fue un humilde pescador igual que su hermano Sim\u00f3n Pedro, ambos desempe\u00f1aban este oficio en Cafarna\u00fam, San Andr\u00e9s fue llamado por Jes\u00fas en el lago de Tiber\u00edades junto con Juan. Desde antes el ap\u00f3stol ya ten\u00eda la iniciativa de seguir al &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2023\/11\/29\/jueves-trigesimo-cuarta-semana-del-tiempo-ordinario-ciclo-a-30-noviembre-2023\/\"> <span class=\"screen-reader-text\">JUEVES, trig\u00e9simo cuarta semana del tiempo ordinario (ciclo a) -30 noviembre, 2023<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":3116,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/11\/NOVIEMBRE-30.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/11\/NOVIEMBRE-30.jpg",640,380,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/11\/NOVIEMBRE-30-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/11\/NOVIEMBRE-30-300x178.jpg",300,178,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/11\/NOVIEMBRE-30.jpg",640,380,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/11\/NOVIEMBRE-30.jpg",640,380,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/11\/NOVIEMBRE-30.jpg",640,380,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/11\/NOVIEMBRE-30.jpg",640,380,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":1,"uagb_excerpt":"SANTO DEL D\u00cdA SAN ANDR\u00c9S APOSTOL (+60 d.c) San Andr\u00e9s nacido en Betsaida (Galilea) fue un humilde pescador igual que su hermano Sim\u00f3n Pedro, ambos desempe\u00f1aban este oficio en Cafarna\u00fam, San Andr\u00e9s fue llamado por Jes\u00fas en el lago de Tiber\u00edades junto con Juan. Desde antes el ap\u00f3stol ya ten\u00eda la iniciativa de seguir al&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/3115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=3115"}],"version-history":[{"count":2,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/3115\/revisions"}],"predecessor-version":[{"id":3119,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/3115\/revisions\/3119"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/3116"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=3115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=3115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=3115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}