{"id":2862,"date":"2023-10-02T20:46:12","date_gmt":"2023-10-03T01:46:12","guid":{"rendered":"https:\/\/devocionario.net\/?p=2862"},"modified":"2023-10-02T20:46:14","modified_gmt":"2023-10-03T01:46:14","slug":"martes-vigesimo-sexta-semana-del-tiempo-ordinario-ciclo-a-03-octubre-2023","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2023\/10\/02\/martes-vigesimo-sexta-semana-del-tiempo-ordinario-ciclo-a-03-octubre-2023\/","title":{"rendered":"MARTES, vig\u00e9simo sexta semana del tiempo ordinario (ciclo a) -03 octubre, 2023"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"425\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/10\/octubre-3.jpg\" alt=\"\" class=\"wp-image-2865\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/10\/octubre-3.jpg 640w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/10\/octubre-3-300x199.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\"><strong>SAN FRANCISCO BORJA(1510-1572)<\/strong><\/p>\n\n\n\n<p>San Francisco nace en Gand\u00eda (Valencia), desde joven tuvo como encargo ponerse al servicio como paje de la hermana de Carlos V, m\u00e1s adelante le dieron el titulo de marqu\u00e9s a sus veinte a\u00f1os, se cas\u00f3 y tuvo ocho hijos, pero una vez muerta su esposa se dedic\u00f3 a la vida espiritual de forma secreta, cuando fue nombrado virrey en Catalu\u00f1a, a\u00f1os m\u00e1s tarde ingresa como miembro de la Compa\u00f1\u00eda de Jes\u00fas , hace sus votos de castidad y de obediencia, celebra su primera Misa, llev\u00f3 una vida de humildad y renunci\u00f3 a todos los t\u00edtulos, el mismo Carlos V lo nombr\u00f3 Cardenal pero renunci\u00f3 pues la Compa\u00f1\u00eda de Jes\u00fas le prohib\u00eda aceptar cualquier dignidad eclesi\u00e1stica, fund\u00f3 el primer colegio Jesuita en Europa, escribi\u00f3 tratados sobre la vida espiritual, luego fue elegido prep\u00f3sito general cargo que desempe\u00f1o hasta su muerte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Lucas 9,51-56<\/strong><\/p>\n\n\n\n<p>Cuando se completaron los d\u00edas en que iba a ser llevado al cielo, Jes\u00fas torn\u00f3 la decisi\u00f3n de ir a Jerusal\u00e9n. Y envi\u00f3 mensajeros delante de \u00e9l.<\/p>\n\n\n\n<p>De camino, entraron en una aldea de samaritanos para hacer los preparativos. Pero no lo recibieron, porque su aspecto era el de uno que caminaba hacia Jerusal\u00e9n.<\/p>\n\n\n\n<p>Al ver esto, Santiago y Juan, disc\u00edpulos suyos, le dijeron:<br>\u00abSe\u00f1or, \u00bfquieres que digamos que baje fuego del cielo que acabe con ellos?\u00bb.<\/p>\n\n\n\n<p>\u00c9l se volvi\u00f3 y los rega\u00f1\u00f3. Y se encaminaron hacia otra aldea.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En el Evangelio de hoy Jesucristo no quiere perder tiempo en ir aquellos Samaritanos para anunciarles la Buena Nueva de Salvaci\u00f3n, pues quiere que todos se salven, toma la decisi\u00f3n de ir antes de su pasi\u00f3n, quiere cumplir la voluntad del Padre Celestial, y quiere llevar el reino de Dios a todos sin distinci\u00f3n.<\/li>\n\n\n\n<li>Aun los disc\u00edpulos no entienden el prop\u00f3sito de la Evangelizaci\u00f3n, no comprenden que sin cruz no hay redenci\u00f3n, que si su Maestro no se entrega para padecer no salvar\u00e1 a la humanidad, ellos piensan que estar con Jes\u00fas ser\u00eda todo bueno, milagros, sanaciones, liberaciones, pero no hay aprendido que tambi\u00e9n habr\u00e1n dificultades que tienen que sobrellevar para cumplir la misi\u00f3n, Jes\u00fas los reprende por su forma de hablar, pues est\u00e1n abusando de la compa\u00f1\u00eda de Jes\u00fas, y la autoridad que Jes\u00fas les dar\u00e1 m\u00e1s tarde no es para condenar sino para salvar.<\/li>\n\n\n\n<li>Dios nos ha encargado una misi\u00f3n desde nuestro bautismo y es expandir su reino y dar testimonio de su amor, debemos cumplir la voluntad de Dios como lo hizo su hijo Jesucristo, nos ha dejado una gran ense\u00f1anza en sus evangelios, que primeramente debemos procurar obedecer a Dios, no podemos perder tiempo, es hoy el momento de lanzarnos a la aventura de anunciar las Buenas Nuevas a todos sin ser selectivos, nunca es tarde para ense\u00f1ar a otros el camino que conduce a la vida eterna.<\/li>\n\n\n\n<li>Cuando estamos dispuestos a seguir a Jes\u00fas debemos prepararnos y saber que vendr\u00e1 la prueba, no es f\u00e1cil ser fieles a Dios pero tampoco es imposible si estamos tomados de la mano de Jesucristo, debemos mantenernos firmes y llenarnos de fortaleza y paciencia para aceptar el rechazo de la Palabra de Dios por aquellos que no quieren conocer a Jes\u00fas, debemos insistir a tiempo y a destiempo, porque esa es nuestra misi\u00f3n aqu\u00ed en la tierra, no podemos abusar de aquellos dones que Dios nos concede para pisotear a los dem\u00e1s m\u00e1s bien debemos ponerlos al servicio de muchos que son o no creyentes, a ejemplo de Jes\u00fas atraigamos a todos a la verdad y manifestemos siempre un coraz\u00f3n amante con aquellos de conciencia d\u00e9bil.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">&nbsp;&nbsp;<strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Invitar con alegr\u00eda a un amigo (a) que no haya tenido la experiencia de ir a misa, motivarlo para que busque a Dios a trav\u00e9s de la Eucarist\u00eda, sino acepta seguir insistiendo hasta lograrlo.<\/li>\n\n\n\n<li>San Francisco Borja nos ense\u00f1a que la humildad nos permite ser compasivos y nos hace comprender que sin Dios no somos nada.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN FRANCISCO BORJA(1510-1572) San Francisco nace en Gand\u00eda (Valencia), desde joven tuvo como encargo ponerse al servicio como paje de la hermana de Carlos V, m\u00e1s adelante le dieron el titulo de marqu\u00e9s a sus veinte a\u00f1os, se cas\u00f3 y tuvo ocho hijos, pero una vez muerta su esposa se dedic\u00f3 a &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2023\/10\/02\/martes-vigesimo-sexta-semana-del-tiempo-ordinario-ciclo-a-03-octubre-2023\/\"> <span class=\"screen-reader-text\">MARTES, vig\u00e9simo sexta semana del tiempo ordinario (ciclo a) -03 octubre, 2023<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":2865,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2862","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/10\/octubre-3.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/10\/octubre-3.jpg",640,425,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/10\/octubre-3-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/10\/octubre-3-300x199.jpg",300,199,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/10\/octubre-3.jpg",640,425,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/10\/octubre-3.jpg",640,425,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/10\/octubre-3.jpg",640,425,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/10\/octubre-3.jpg",640,425,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SAN FRANCISCO BORJA(1510-1572) San Francisco nace en Gand\u00eda (Valencia), desde joven tuvo como encargo ponerse al servicio como paje de la hermana de Carlos V, m\u00e1s adelante le dieron el titulo de marqu\u00e9s a sus veinte a\u00f1os, se cas\u00f3 y tuvo ocho hijos, pero una vez muerta su esposa se dedic\u00f3 a&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=2862"}],"version-history":[{"count":2,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2862\/revisions"}],"predecessor-version":[{"id":2866,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2862\/revisions\/2866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/2865"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=2862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=2862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=2862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}