{"id":2834,"date":"2023-09-25T16:52:40","date_gmt":"2023-09-25T21:52:40","guid":{"rendered":"https:\/\/devocionario.net\/?p=2834"},"modified":"2023-09-25T18:23:22","modified_gmt":"2023-09-25T23:23:22","slug":"miercoles-vigesimo-quinta-semana-del-tiempo-ordinario-ciclo-a-27-septiembre-2023","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2023\/09\/25\/miercoles-vigesimo-quinta-semana-del-tiempo-ordinario-ciclo-a-27-septiembre-2023\/","title":{"rendered":"MIERCOLES, vig\u00e9simo quinta semana del tiempo ordinario (ciclo a) -27 septiembre, 2023"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"852\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/septiembre-27-1024x852.jpg\" alt=\"\" class=\"wp-image-2845\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/septiembre-27-1024x852.jpg 1024w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/septiembre-27-300x250.jpg 300w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/septiembre-27-768x639.jpg 768w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/septiembre-27.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"612\" height=\"408\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/septiembre-27.webp\" alt=\"\" class=\"wp-image-2835\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/septiembre-27.webp 612w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/septiembre-27-300x200.webp 300w\" sizes=\"(max-width: 612px) 100vw, 612px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\"><strong>SAN VICENTE DE PAUL (1581-1660)<\/strong><\/p>\n\n\n\n<p>San Vicente naci\u00f3 en Dax (Francia) en la regi\u00f3n de las Landas muy cerca  a la frontera Espa\u00f1ola, creci\u00f3 en una familia pobre, se dedic\u00f3 desde muy peque\u00f1o al campo como pastor, cuando fue joven una persona admiraba sus grandes cualidades y le di\u00f3 la oportunidad de estudiar en Zaragoza y a Toulouse, una vez ordenado sacerdote a temprana edad s\u00f3lo cuando tenia diecinueve a\u00f1os, se dedic\u00f3 a los m\u00e1s pobres en compa\u00f1\u00eda con otra santa, durante su ministerio fund\u00f3 dos Sociedades a quien llam\u00f3 Hijas de la Caridad que se dedicaba a los pobres y los Sacerdotes de la Misi\u00f3n que misionaban a las gentes de los campos, tambi\u00e9n fund\u00f3 seminarios para aquellos que quer\u00edan entregar la vida a Dios, fue gran amigo y confidente de San Francisco de Sales, muri\u00f3 diciendo Confianza, Jes\u00fas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Lucas 9,1-6<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, habiendo convocado Jes\u00fas a los Doce, les dio poder y autoridad sobre toda clase de demonios y para curar enfermedades.<\/p>\n\n\n\n<p>Luego los envi\u00f3 a proclamar el reino de Dios y a curar a los enfermos, dici\u00e9ndoles:<br>\u00abNo llev\u00e9is nada para el camino: ni bast\u00f3n ni alforja, ni pan ni dinero; tampoco teng\u00e1is dos t\u00fanicas cada uno.<\/p>\n\n\n\n<p>Quedaos en la casa donde entr\u00e9is, hasta que os vay\u00e1is de aquel sitio.<\/p>\n\n\n\n<p>Y si algunos no os reciben, al salir de aquel pueblo sacud\u00edos el polvo de vuestros pies, como testimonio contra ellos\u00bb.<\/p>\n\n\n\n<p>Se pusieron en camino y fueron de aldea en aldea, anunciando la Buena Noticia y curando en todas partes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En el Evangelio de hoy Jes\u00fas habla de una manera clara a sus disc\u00edpulos encarg\u00e1ndoles una misi\u00f3n, el anuncio del Reino de Dios, los escoge para si y los env\u00eda a los dem\u00e1s, les di\u00f3 su autoridad y poder para realizar milagros, no solo los motiva a Evangelizar sino que les da las armas necesarias para dar cumplimiento a su misi\u00f3n, Jes\u00fas les recuerda que las posesiones no es lo principal de ahora en adelante en sus vidas, lo primordial es llevar la Buena Nueva de Salvaci\u00f3n a todos los pueblos, les ense\u00f1a que preocuparse por lo material no es lo que interesa que lo fundamental es dar a conocer su reino de amor. <\/li>\n\n\n\n<li>Les advierte que habr\u00e1n muchos que no escuchar\u00e1n y no prestar\u00e1n atenci\u00f3n a sus palabras, pero que deben continuar, el sacudir el polvo de los pies para los jud\u00edos tenia un significado importante, y era dar por terminada toda responsabilidad con aquello que pudiese pasar con quienes no acogieran el Evangelio, el haberlo  llevado ya era un hecho cumplido dentro de la misi\u00f3n, los ap\u00f3stoles no dudaron en ir a poner en pr\u00e1ctica lo que hab\u00edan escuchado y aprendido del Maestro.<\/li>\n\n\n\n<li>\u00bfJes\u00fas te ha llamado? \u00bfC\u00f3mo has respondido ha ese llamado?, \u00bfconf\u00edas en las palabras de Jesucristo cuando lees la Sagrada Escritura?, en el mundo de hoy Jes\u00fas nos ha hecho muchos llamamientos dulces y tiernos a lo largo de nuestra vida, nos dota de talentos, carismas y dones para ponerlos al servicio de la Evangelizaci\u00f3n, y son muchos los momentos que ignoramos su voz, nos da miedo abandonarnos y unirnos  a la voluntad de Cristo, y confiar en sus palabras, la iglesia de Jes\u00fas esta basada en el servicio y la misi\u00f3n, que nos permite dar a Conocer a Dios y hacer que lo amen como \u00e9l desea, despojarnos de lo material se hace dif\u00edcil, pero no imposible cuando lo \u00fanico que debemos buscar es a Jesucristo.<\/li>\n\n\n\n<li>Existen aun personas que reh\u00fasan de o\u00edr la palabra de Dios, se hacen los sordos y ciegos, e ignoran que Jes\u00fas les salvar\u00e1, no tienen el amor de Dios en sus corazones, pero muchos son los que caminan en las tinieblas, y quienes creemos en Jes\u00fas y tratamos de ser mejores personas, y queremos atraer a otros al camino del bien \u00bfQu\u00e9 deber\u00edamos hacer?, nuestro testimonio de vida juega un papel muy crucial a la hora de misionar porque los hechos hablan m\u00e1s que las palabras, pero si a quienes he transmitido el mensaje de Jes\u00fas no aceptan seguirlo, lo que debo hace es orar por ellos, no vayamos por donde todos van en el camino de la perdici\u00f3n seamos aquellos que sacudamos el polvo de nuestros pies y no seamos polvo que enferma y opaca la mirada de otros que quieran conocer a Dios.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">&nbsp;&nbsp;<strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>De hoy en adelante me ofrecer\u00e9 en mi parroquia m\u00e1s cercana como misionero activo que lleve la Palabra de Dios a todos los hogares.<\/li>\n\n\n\n<li>San Vicente de Paul desde muy temprana edad cumpli\u00f3 y sigui\u00f3 el camino que Dios le tenia trazado, se don\u00f3 a los pobres, como \u00e9l sepamos hinchar nuestro coraz\u00f3n del amor de Dios para servir a los dem\u00e1s.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN VICENTE DE PAUL (1581-1660) San Vicente naci\u00f3 en Dax (Francia) en la regi\u00f3n de las Landas muy cerca a la frontera Espa\u00f1ola, creci\u00f3 en una familia pobre, se dedic\u00f3 desde muy peque\u00f1o al campo como pastor, cuando fue joven una persona admiraba sus grandes cualidades y le di\u00f3 la oportunidad de &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2023\/09\/25\/miercoles-vigesimo-quinta-semana-del-tiempo-ordinario-ciclo-a-27-septiembre-2023\/\"> <span class=\"screen-reader-text\">MIERCOLES, vig\u00e9simo quinta semana del tiempo ordinario (ciclo a) -27 septiembre, 2023<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":2835,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2834","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/septiembre-27.webp","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/septiembre-27.webp",612,408,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/septiembre-27-150x150.webp",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/septiembre-27-300x200.webp",300,200,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/septiembre-27.webp",612,408,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/septiembre-27.webp",612,408,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/septiembre-27.webp",612,408,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/septiembre-27.webp",612,408,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SAN VICENTE DE PAUL (1581-1660) San Vicente naci\u00f3 en Dax (Francia) en la regi\u00f3n de las Landas muy cerca a la frontera Espa\u00f1ola, creci\u00f3 en una familia pobre, se dedic\u00f3 desde muy peque\u00f1o al campo como pastor, cuando fue joven una persona admiraba sus grandes cualidades y le di\u00f3 la oportunidad de&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=2834"}],"version-history":[{"count":2,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2834\/revisions"}],"predecessor-version":[{"id":2846,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2834\/revisions\/2846"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/2835"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=2834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=2834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=2834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}