{"id":2777,"date":"2023-09-13T19:26:22","date_gmt":"2023-09-14T00:26:22","guid":{"rendered":"https:\/\/devocionario.net\/?p=2777"},"modified":"2023-09-13T19:26:24","modified_gmt":"2023-09-14T00:26:24","slug":"jueves-vigesimo-tercera-semana-del-tiempo-ordinario-ciclo-a-14-septiembre-2023","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2023\/09\/13\/jueves-vigesimo-tercera-semana-del-tiempo-ordinario-ciclo-a-14-septiembre-2023\/","title":{"rendered":"JUEVES, vig\u00e9simo tercera semana del tiempo ordinario (ciclo a) -14 septiembre, 2023"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"550\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/20-junio.jpg\" alt=\"\" class=\"wp-image-2778\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/20-junio.jpg 1000w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/20-junio-300x165.jpg 300w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/20-junio-768x422.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\"><strong>EXALTACI\u00d3N DE LA SANTA CRUZ (Siglo IV)<\/strong><\/p>\n\n\n\n<p>La fiesta de la exaltaci\u00f3n de la santa cruz la iglesia cat\u00f3lica la celebra desde el a\u00f1o 628, es una conmemoraci\u00f3n a la santa cruz donde muri\u00f3 Nuestro Se\u00f1or Jesucristo. La Emperatriz Santa Elena madre de Constantino encontr\u00f3 la Vera Cruz, Santa Elena junto con su hijo construyeron una Bas\u00edlica del Santo Sepulcro donde guardaron la reliquia, a\u00f1os m\u00e1s tarde el Rey Cosroe se la llev\u00f3 para colocarlo bajo su trono como signo de desprecio a los cristianos, pero tiempo despu\u00e9s el emperador Heraclio la recupero y la traslado nuevamente a Jerusal\u00e9n en una solemne procesi\u00f3n la regres\u00f3 y desde aquel entonces esta ceremonia hace parte del calendario lit\u00fargico de la iglesia. La cruz da sentido a nuestra vida, Jesucristo muri\u00f3 en ella para demostrarnos su inmenso amor, y para liberarnos del pecado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Lucas 6,27-38<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, dijo Jes\u00fas a sus disc\u00edpulos: \u00abA los que me escuch\u00e1is os digo: Amad a vuestros enemigos, haced el bien a los que os odian, bendecid a los que os maldicen, orad por los que os injurian. Al que te pegue en una mejilla, pres\u00e9ntale la otra; al que te quite la capa, d\u00e9jale tambi\u00e9n la t\u00fanica. A quien te pide, dale; al que se lleve lo tuyo, no se lo reclames. Tratad a los dem\u00e1s como quer\u00e9is que ellos os traten. Pues, si am\u00e1is s\u00f3lo a los que os aman, \u00bfqu\u00e9 m\u00e9rito ten\u00e9is? Tambi\u00e9n los pecadores aman a los que los aman. Y si hac\u00e9is bien s\u00f3lo a los que os hacen bien, \u00bfqu\u00e9 m\u00e9rito ten\u00e9is? Tambi\u00e9n los pecadores lo hacen. Y si prest\u00e1is s\u00f3lo cuando esper\u00e1is cobrar, \u00bfqu\u00e9 m\u00e9rito ten\u00e9is? Tambi\u00e9n los pecadores prestan a otros pecadores, con intenci\u00f3n de cobr\u00e1rselo. \u00a1No! Amad a vuestros enemigos, haced el bien y prestad sin esperar nada; tendr\u00e9is un gran premio y ser\u00e9is hijos del Alt\u00edsimo, que es bueno con los malvados y desagradecidos. Sed compasivos como vuestro Padre es compasivo; no juzgu\u00e9is, y no ser\u00e9is juzgados; no conden\u00e9is, y no ser\u00e9is condenados; perdonad, y ser\u00e9is perdonados; dad, y se os dar\u00e1: os verter\u00e1n una medida generosa, colmada, remecida, rebosante. La medida que us\u00e9is, la usar\u00e1n con vosotros.\u00bb<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Jesucristo una vez m\u00e1s da a conocer el mandamiento del amor , la ley perfecta que permite amar no solo a los amigos sino a los enemigos, un amor que va m\u00e1s all\u00e1, que trasciende, Jes\u00fas quiere hombres capaces de amar hasta que duela, sabe que es dif\u00edcil para el ser humano demostrar amor a quien ofende, a quien hace el mal , pero invita hacer el bien para aquellos que est\u00e1n desorientados, para aquellos que han perdido el horizonte.<\/li>\n\n\n\n<li>Jes\u00fas invita a que el hombre se despoje de su misma persona para donarse a los hermanos cuando aquellos necesiten, a\u00fan as\u00ed cuando no tienen una forma correcta al obrar, quiere que los cristianos est\u00e9n regidos por el amor, que demuestren misericordia para los considerados d\u00e9biles y faltos del amor de Dios. La ley del tali\u00f3n considerada justa ya no tenia valor ante Jes\u00fas, pues \u00e9l mismo se entregar\u00eda por amor por quienes no cre\u00edan en sus palabras, \u00e9l mismo se don\u00f3 y quiere que la humanidad entera siga sus pasos, amando y perdonando.<\/li>\n\n\n\n<li>En la actualidad el odio reina en los corazones de esta sociedad, vengativa y falta del amor de Dios, cada quien busca desahogarse con la violencia, buscando el mal para quienes les han ofendido, es hora de despertar y seguir las huellas de Jesucristo que nos invita a amar m\u00e1s all\u00e1 de nuestros rencores, a perdonar y ser perdonados, a sembrar en los ni\u00f1os el amor de Dios que sobrepasa cualquier dificultad que es capaz de seguir sin mirar atr\u00e1s y de sembrar m\u00e1s que arrancar, queridos hermanos el odio nos dejar\u00e1 grandes cicatrices, pero si nos disponemos a amar ya perdonar ser\u00e1 una tarea f\u00e1cil para nosotros.<\/li>\n\n\n\n<li>La misericordia nos permite comprender las diferencias de los otros, y a tener presente que Dios nos perdona tambi\u00e9n a pesar de nuestras desobediencias, si pedimos a Dios tenga compasi\u00f3n de nosotros con que cara exigiremos su piedad, si aun hay en nuestro interior odios y rencores que est\u00e1n destruyendo nuestra alma, y estamos alejados de nuestros hermanos, Dios nos manda a la unidad, a desvivirnos por los otros, no podemos ser selectivos y convivir con quienes tenemos afinidad, el merito y la recompensa est\u00e1 en amar a quienes no nos demuestran amor sino necesidad de Dios, porque quien hace mal es porque hay una ausencia tremenda de Dios, entonces nuestro deber  es acercarnos a ellos y no alejarnos como si fu\u00e9ramos jueces, se\u00f1alando y excluyendo, sino al contrario viviendo y ayudando en los desaf\u00edos de cada d\u00eda para que seamos llamados hijos de Dios como no lo dicen las bienaventuranzas pero todo basado en el amor.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">&nbsp;&nbsp;<strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Hoy buscar\u00e9 a quien me ha hecho mal, pedir\u00e9 nos reconciliemos, y sino me atiende seguir orando por \u00e9l. <\/li>\n\n\n\n<li>La exaltaci\u00f3n de la santa cruz me invita a amar a mis enemigos como lo hizo Jes\u00fas, que siendo Dios muere por quienes pecamos y aun lo seguimos crucificando, pero por su inmensa misericordia nos sigue perdonando.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA EXALTACI\u00d3N DE LA SANTA CRUZ (Siglo IV) La fiesta de la exaltaci\u00f3n de la santa cruz la iglesia cat\u00f3lica la celebra desde el a\u00f1o 628, es una conmemoraci\u00f3n a la santa cruz donde muri\u00f3 Nuestro Se\u00f1or Jesucristo. La Emperatriz Santa Elena madre de Constantino encontr\u00f3 la Vera Cruz, Santa Elena junto con &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2023\/09\/13\/jueves-vigesimo-tercera-semana-del-tiempo-ordinario-ciclo-a-14-septiembre-2023\/\"> <span class=\"screen-reader-text\">JUEVES, vig\u00e9simo tercera semana del tiempo ordinario (ciclo a) -14 septiembre, 2023<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":2778,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2777","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/20-junio.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/20-junio.jpg",1000,550,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/20-junio-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/20-junio-300x165.jpg",300,165,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/20-junio-768x422.jpg",768,422,true],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/20-junio.jpg",1000,550,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/20-junio.jpg",1000,550,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/09\/20-junio.jpg",1000,550,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA EXALTACI\u00d3N DE LA SANTA CRUZ (Siglo IV) La fiesta de la exaltaci\u00f3n de la santa cruz la iglesia cat\u00f3lica la celebra desde el a\u00f1o 628, es una conmemoraci\u00f3n a la santa cruz donde muri\u00f3 Nuestro Se\u00f1or Jesucristo. La Emperatriz Santa Elena madre de Constantino encontr\u00f3 la Vera Cruz, Santa Elena junto con&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=2777"}],"version-history":[{"count":1,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2777\/revisions"}],"predecessor-version":[{"id":2779,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2777\/revisions\/2779"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/2778"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=2777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=2777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=2777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}