{"id":2701,"date":"2023-08-23T16:49:52","date_gmt":"2023-08-23T21:49:52","guid":{"rendered":"https:\/\/devocionario.net\/?p=2701"},"modified":"2023-08-23T16:49:54","modified_gmt":"2023-08-23T21:49:54","slug":"domingo-vigesim0-primera-semana-del-tiempo-ordinario-ciclo-a-27-agosto-2023","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2023\/08\/23\/domingo-vigesim0-primera-semana-del-tiempo-ordinario-ciclo-a-27-agosto-2023\/","title":{"rendered":"DOMINGO, vig\u00e9sim0 primera semana del tiempo ordinario (ciclo a) -27 agosto, 2023"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"878\" height=\"1024\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-27-878x1024.jpg\" alt=\"\" class=\"wp-image-2702\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-27-878x1024.jpg 878w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-27-257x300.jpg 257w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-27-768x896.jpg 768w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-27.jpg 1097w\" sizes=\"(max-width: 878px) 100vw, 878px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\"><strong>SANTA MONICA (332-387)<\/strong><\/p>\n\n\n\n<p>Santa M\u00f3nica nacida en \u00c1frica del Norte (Tagaste), su formaci\u00f3n fue bastante estricta, y fue formada en la fe cat\u00f3lica, bautizada grande, ella quer\u00eda dedicarse a la oraci\u00f3n y al silencio, pero sus padres la hicieron casar con Patricio, un hombre de un temperamento fuerte, mujeriego, con \u00e9l tuvo tres hijos entre ellos el gran san Agust\u00edn, ella se manten\u00eda en silencio cuando su esposo estaba de mal genio y as\u00ed evitaba peleas. Santa M\u00f3nica se dedicaba a la caridad y a la oraci\u00f3n su esposo que no era cat\u00f3lico a los treinta a\u00f1os logr\u00f3 que se hiciera bautizar junto con su suegra, tiempo despu\u00e9s Patricio muri\u00f3 y ella qued\u00f3 encargada de su hijo dif\u00edcil. A\u00f1os m\u00e1s tarde llegaban noticias de Agust\u00edn, que la pon\u00edan triste pero ella persisti\u00f3 en la oraci\u00f3n, un d\u00eda cuando lleg\u00f3 su hijo y comenz\u00f3 a renegar de la fe cat\u00f3lica lo corri\u00f3 de la casa. Tiempo despu\u00e9s conoci\u00f3 a San Ambrosio que le ayud\u00f3 mucho como influencia en su hijo, pues san Agust\u00edn admiraba la personalidad de San Ambrosio y se gan\u00f3 su respeto y simpat\u00eda, y en el momento inesperado San Agust\u00edn se hizo instruir y bautizar en la fe Cat\u00f3lica de su Madre, en la Pascua de resurrecci\u00f3n, a\u00f1os despu\u00e9s mientras conversaba con su hijo San Agust\u00edn, tuv\u00f3 una fiebre fuert\u00edsima que le ocasion\u00f3 la muerte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Mateo 16 ,13-20<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, al llegar a la regi\u00f3n de Cesarea de Filipo, Jes\u00fas pregunt\u00f3 a sus disc\u00edpulos:<br>\u00ab\u00bfQui\u00e9n dice la gente que es el Hijo del hombre?\u00bb.<br>Ellos contestaron:<br>\u00abUnos que Juan el Bautista, otros que El\u00edas, otros que Jerem\u00edas o uno de los profetas\u00bb.<br>\u00c9l les pregunt\u00f3:<br>\u00abY vosotros, \u00bfqui\u00e9n dec\u00eds que soy yo?\u00bb.<br>Sim\u00f3n Pedro tom\u00f3 la palabra y dijo:<br>\u00abT\u00fa eres el Mes\u00edas, el Hijo del Dios vivo\u00bb.<br>Jes\u00fas le respondi\u00f3:<br>\u00ab\u00a1Bienaventurado t\u00fa, Sim\u00f3n, hijo de Jon\u00e1s!, porque eso no te lo ha revelado ni la carne ni la sangre, sino mi Padre que est\u00e1 en los cielos.<br>Ahora yo te digo: t\u00fa eres Pedro, y sobre esta piedra edificar\u00e9 mi Iglesia, y el poder del infierno no la derrotar\u00e1.<br>Te dar\u00e9 las llaves del reino de los cielos; lo que ates en la tierra quedar\u00e1 atado en los cielos, y lo que desates en la tierra quedar\u00e1 desatado en los cielos\u00bb.<br>Y les mand\u00f3 a los disc\u00edpulos que no dijesen a nadie que \u00e9l era el Mes\u00edas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En este evangelio Jes\u00fas aprovecha la oportunidad con sus disc\u00edpulos para preguntar la opini\u00f3n de ellos y de las gentes sobre lo que pensaban de \u00e9l, y es que a Jesucristo no le interesaba que concepto bueno o malo ten\u00edan de su persona, solo quer\u00eda dar paso a la respuesta de Sim\u00f3n en quien confiar\u00eda la Iglesia primitiva , el hablar de Pedro en aquel instante no sali\u00f3 de su pensar reflexivo hacia lo que cre\u00eda era Jes\u00fas sino que era la revelaci\u00f3n misma de Dios Padre, un argumento asombroso de un hombre tosco y de car\u00e1cter fuerte, que mostrar\u00eda a Jes\u00fas como \u00a0el verdadero mes\u00edas que salvar\u00eda al pueblo de la esclavitud del pecado .<\/li>\n\n\n\n<li>El nombre de Pedro ten\u00eda un gran significado al momento de ser elegido como ap\u00f3stol, pues Jes\u00fas sabia el encargo que a\u00f1os despu\u00e9s tendr\u00eda que cumplir. Pedro con su contestaci\u00f3n acertada inaugura su misi\u00f3n en esta tierra, pues en aquel momento Jes\u00fas le da la autoridad de permitir y prohibir todo lo que concierne en la Instituci\u00f3n de su Iglesia, Jes\u00fas vi\u00f3 en Sim\u00f3n Pedro la humildad de su vida ordinaria, un simple pescador que dej\u00f3 sus redes por buscar hombres, sabiendo que Dios escoge la sencillez del ser humano y se vale de ella para llevar a cabo su obra&nbsp; salvadora, no dudo en concederle las llaves del Reino de los cielos a Pedro para que guiar\u00e1 sin vacilaci\u00f3n a los creyentes, pero no sin antes prometerle que los poderes del mal jam\u00e1s la destruir\u00edan esta vendr\u00eda siendo una agradable muestra de esperanza para quienes dar\u00edan su vida por la evangelizaci\u00f3n.<\/li>\n\n\n\n<li>Como Cristianos cat\u00f3licos estamos llamados a expandir la Iglesia de Cristo fundada en los ap\u00f3stoles, nuestra obediencia a ella nos permite atender lo que el papa Francisco como sucesor de Pedro nos anuncia, que inspirado por el Esp\u00edritu Santo trabaja por la continuidad de llevar la buena nueva de salvaci\u00f3n a todos los rincones del mundo, debemos ser constantes en la oraci\u00f3n para que las fuerzas del mal no opaquen el mensaje de Jesucristo ante las comunidades cristianas y los no creyentes, y tambi\u00e9n para que Dios fortalezca a quienes anuncian sin cansancio el mensaje de Jes\u00fas, mantenernos en una sola fe que inicio desde la elecci\u00f3n de la primera comunidad de disc\u00edpulos y nosotros en el sacramento del bautismo, nuestro deber sea\u00a0 defenderla en un mundo que resiste a escuchar las palabras de Jes\u00fas contenidas en la santa biblia y la tradici\u00f3n de los ap\u00f3stoles.<\/li>\n\n\n\n<li>Nuestro aporte a la iglesia cat\u00f3lica debe basarse en obras de fidelidad, respeto a las doctrinas que profesamos, el vivir una experiencia con Jes\u00fas y atraer nuestros hermanos para que tambi\u00e9n la tengan, porque recordemos que lo que vivimos y sentimos en nuestras parroquias es lo que reflejamos a los dem\u00e1s,&nbsp; esforzarnos por llegar a la santidad como lo hizo Pedro es una meta por la que debemos trabajar d\u00eda a d\u00eda, y para iniciarla nunca es tarde, \u00a1es hoy!.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">&nbsp;&nbsp;<strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Defender nuestra fe cat\u00f3lica, sabiendo que es la Iglesia de Jesucristo, mantenernos firmes en las doctrinas que obedecemos, no discutir con hermanos separados, s\u00f3lo orar por ellos y convencerlos con nuestro testimonio de vida.<\/li>\n\n\n\n<li>Santa M\u00f3nica nos invita a perseverar en la oraci\u00f3n por la conversi\u00f3n de nuestra vida y la de los dem\u00e1s, tener esperanza y confianza en Dios as\u00ed vengan las pruebas.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SANTA MONICA (332-387) Santa M\u00f3nica nacida en \u00c1frica del Norte (Tagaste), su formaci\u00f3n fue bastante estricta, y fue formada en la fe cat\u00f3lica, bautizada grande, ella quer\u00eda dedicarse a la oraci\u00f3n y al silencio, pero sus padres la hicieron casar con Patricio, un hombre de un temperamento fuerte, mujeriego, con \u00e9l tuvo &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2023\/08\/23\/domingo-vigesim0-primera-semana-del-tiempo-ordinario-ciclo-a-27-agosto-2023\/\"> <span class=\"screen-reader-text\">DOMINGO, vig\u00e9sim0 primera semana del tiempo ordinario (ciclo a) -27 agosto, 2023<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":2702,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2701","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-27.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-27.jpg",1097,1280,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-27-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-27-257x300.jpg",257,300,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-27-768x896.jpg",768,896,true],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-27-878x1024.jpg",878,1024,true],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-27.jpg",1097,1280,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-27.jpg",1097,1280,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SANTA MONICA (332-387) Santa M\u00f3nica nacida en \u00c1frica del Norte (Tagaste), su formaci\u00f3n fue bastante estricta, y fue formada en la fe cat\u00f3lica, bautizada grande, ella quer\u00eda dedicarse a la oraci\u00f3n y al silencio, pero sus padres la hicieron casar con Patricio, un hombre de un temperamento fuerte, mujeriego, con \u00e9l tuvo&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=2701"}],"version-history":[{"count":2,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2701\/revisions"}],"predecessor-version":[{"id":2704,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2701\/revisions\/2704"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/2702"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=2701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=2701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=2701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}