{"id":2680,"date":"2023-08-17T17:49:32","date_gmt":"2023-08-17T22:49:32","guid":{"rendered":"https:\/\/devocionario.net\/?p=2680"},"modified":"2023-08-17T17:49:34","modified_gmt":"2023-08-17T22:49:34","slug":"lunes-vigesima-semana-del-tiempo-ordinario-ciclo-a-21-agosto-2023","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2023\/08\/17\/lunes-vigesima-semana-del-tiempo-ordinario-ciclo-a-21-agosto-2023\/","title":{"rendered":"LUNES, vig\u00e9sima semana del tiempo ordinario (ciclo a) -21 agosto, 2023"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"612\" height=\"408\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-21.jpg\" alt=\"\" class=\"wp-image-2681\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-21.jpg 612w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-21-300x200.jpg 300w\" sizes=\"(max-width: 612px) 100vw, 612px\" \/><figcaption class=\"wp-element-caption\">.<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\"><strong>SAN P\u00cdO X (1835-1914)<\/strong><\/p>\n\n\n\n<p>San P\u00edo naci\u00f3 en Venecia su nombre Giuseppe Melchiorre Sarto,estudi\u00f3 en el Seminario de Padua, se orden\u00f3 sacerdote y comenz\u00f3 a estudiar nuevamente teolog\u00eda basado en Santo Tom\u00e1s, estableci\u00f3 una escuela nocturna para adultos, fue profesor en seminarios, siempre ayudo a los m\u00e1s pobres, se destaco por su ayuda a los enfermos, logr\u00f3 que en las escuelas p\u00fablicas se diera instrucciones religiosas, inculc\u00f3 el canto gregoriano y logro establecer la facultad de derecho can\u00f3nigo en los seminarios. A\u00f1os m\u00e1s tarde muerto Le\u00f3n XIII fue elegido como Papa con 60 votos. Promovi\u00f3 un nuevo catecismo para la Iglesia Cat\u00f3lica, se esmer\u00f3 por la formaci\u00f3n estricta de los seminaristas, para que se acogieran a la disciplina eclesi\u00e1stica y no se convirtieran en amenaza para el Clero. Se destac\u00f3 por velar por los bienes de la iglesia de manera legal. Estando Pio X  como papa la jerarqu\u00eda Cat\u00f3lica aumento de manera significativa, hizo un gran trabajo de restauraci\u00f3n en el vaticano, su Pontificado se bas\u00f3 en conservar las doctrinas y la disciplina cat\u00f3lica, tambi\u00e9n ayudo en las calamidades de pa\u00edses que se enfrentaban a situaciones dolorosas, buscando recolectar dinero para quienes necesitaban.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Mateo 19,16-22<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, se acerc\u00f3 uno a Jes\u00fas y le pregunt\u00f3:<br>\u00abMaestro, \u00bfqu\u00e9 tengo que hacer de bueno para obtener la vida eterna?\u00bb.<\/p>\n\n\n\n<p>Jes\u00fas le contest\u00f3:<br>\u00ab \u00bfPor qu\u00e9 me preguntas qu\u00e9 es bueno? Uno solo es Bueno. Mira, si quieres entrar en la vida, guarda los mandamientos\u00bb.<\/p>\n\n\n\n<p>\u00c9l le pregunt\u00f3:<br>\u00ab\u00bfCu\u00e1les?\u00bb.<\/p>\n\n\n\n<p>Jes\u00fas le contest\u00f3:<br>\u00abNo matar\u00e1s, no cometer\u00e1s adulterio, no robar\u00e1s, no dar\u00e1s falso testimonio, honra a tu padre y a tu madre, y ama a tu pr\u00f3jimo como a ti mismo\u00bb.<\/p>\n\n\n\n<p>El joven le dijo:<br>\u00abTodo eso lo he cumplido. \u00bfQu\u00e9 me falta?\u00bb.<\/p>\n\n\n\n<p>Jes\u00fas le contest\u00f3:<br>\u00abSi quieres ser perfecto, anda, vende tus bienes, da el dinero a los pobres \u2013 as\u00ed tendr\u00e1s un tesoro en el cielo &#8211; y luego ven y s\u00edgueme\u00bb.<\/p>\n\n\n\n<p>Al o\u00edr esto, el joven se fue triste, porque era muy rico.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Palabra del Se\u00f1or<\/h3>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Jes\u00fas da una respuesta sincera al joven rico, no para que se sienta mal sino para que vea la realidad a la que debe enfrentarse, este hombre cre\u00eda haberlo hecho todo por amor a Dios, pero se hab\u00eda olvidado que estaba sujeto a sus riquezas que no le permit\u00edan ser libre para entregarse completamente al Se\u00f1or, hizo una  pregunta a Jes\u00fas que termino cuestionando su vida, quiz\u00e1s no era del todo feliz con lo que hac\u00eda hab\u00eda algo m\u00e1s que lo interpelaba, y era dejarlo todo por aquel que ofrece vida eterna. Como menciona el evangelista San Juan la vida eterna consiste en conocer a Dios Padre y a su enviado Jesucristo, ser participe de esta vida eterna consiste en abandonarse y despojarse de todo aquello que me impide conocer a Jesucristo a profundidad.<\/li>\n\n\n\n<li>Jes\u00fas invita  a la humanidad a trabajar y poner la vida misma al servicio de los dem\u00e1s, cuando las riquezas impiden la cercan\u00eda con Dios, cada cosa que se haga no tendr\u00e1 sentido y solo se experimentar\u00e1 un vac\u00edo que causa tristeza y desolaci\u00f3n, cuando se invierte todo esfuerzo por atesorar bienes terrenales descuidando los bienes celestiales se pone en peligro el cielo, cuando la visi\u00f3n esta puesta en donarnos a los m\u00e1s pobres y vulnerables la vida eterna se convierte en nuestra recompensa final.<\/li>\n\n\n\n<li>Jes\u00fas hoy nos pregunta \u00bf Que nos ata y no nos deja experimentar su amor?\u00bf En donde y en que estoy poniendo mi atenci\u00f3n en este mundo,que me impide a cercarme a \u00e9l? debemos cada d\u00eda examinar si realmente soy feliz y pleno con lo que hago, si solo existo para complacer al mundo o estoy invirtiendo mi vida al servicio de la misi\u00f3n que Jes\u00fas me ha encomendado desde el bautismo, trabajar por Dios implica despojarnos del materialismo y lanzarnos a la aventura de la evangelizaci\u00f3n, pero no quiere decir que renunciemos a trabajar por nuestro sustento, sino que lo esencial en nuestra vida sea vivir por y para Jesucristo, siempre poni\u00e9ndolo en primer lugar. <\/li>\n\n\n\n<li>En esta sociedad el que ama el dinero hace hasta lo imposible por vender hasta la misma alma por conseguirlo, sujeto a la moda, a los lujos, se encierra en la riqueza del orgullo y el ego\u00edsmo que le impiden ver la necesidad del otro, como si cuando muri\u00e9ramos todo no lo llev\u00e1ramos, queridos hermanos no seamos ciegos e ignorantes, si la vida eterna se basa en buenas obras pero hasta darlo todo, hasta el extremo como lo hizo el mismo Jes\u00fas, Hoy este evangelio nos interpela y motiva a seguir a Jes\u00fas sin mirar atr\u00e1s, sin importar cuanto tengamos o que bienes poseemos, nos pide entregarnos sin reservas hasta donar la misma vida en rescate de muchos. \u00a1Sigue a Jesucristo y ya nada m\u00e1s importar\u00e1 porque a sus pies encontraremos la verdadera felicidad!<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>De hoy en adelante ser m\u00e1s generosos con lo que poseemos, no con lo que nos sobra, la caridad nos encamina a la vida eterna.<\/li>\n\n\n\n<li>San Pio X nos ense\u00f1a el valor de la disciplina cristiana, donde no hay orden no esta Dios, mantener las doctrinas y la fe cat\u00f3lica es un signo de unidad que nos motiva a seguir a Cristo.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN P\u00cdO X (1835-1914) San P\u00edo naci\u00f3 en Venecia su nombre Giuseppe Melchiorre Sarto,estudi\u00f3 en el Seminario de Padua, se orden\u00f3 sacerdote y comenz\u00f3 a estudiar nuevamente teolog\u00eda basado en Santo Tom\u00e1s, estableci\u00f3 una escuela nocturna para adultos, fue profesor en seminarios, siempre ayudo a los m\u00e1s pobres, se destaco por su &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2023\/08\/17\/lunes-vigesima-semana-del-tiempo-ordinario-ciclo-a-21-agosto-2023\/\"> <span class=\"screen-reader-text\">LUNES, vig\u00e9sima semana del tiempo ordinario (ciclo a) -21 agosto, 2023<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":2681,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-21.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-21.jpg",612,408,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-21-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-21-300x200.jpg",300,200,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-21.jpg",612,408,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-21.jpg",612,408,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-21.jpg",612,408,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-21.jpg",612,408,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SAN P\u00cdO X (1835-1914) San P\u00edo naci\u00f3 en Venecia su nombre Giuseppe Melchiorre Sarto,estudi\u00f3 en el Seminario de Padua, se orden\u00f3 sacerdote y comenz\u00f3 a estudiar nuevamente teolog\u00eda basado en Santo Tom\u00e1s, estableci\u00f3 una escuela nocturna para adultos, fue profesor en seminarios, siempre ayudo a los m\u00e1s pobres, se destaco por su&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=2680"}],"version-history":[{"count":1,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2680\/revisions"}],"predecessor-version":[{"id":2682,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2680\/revisions\/2682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/2681"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=2680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=2680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=2680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}