{"id":2675,"date":"2023-08-17T16:03:24","date_gmt":"2023-08-17T21:03:24","guid":{"rendered":"https:\/\/devocionario.net\/?p=2675"},"modified":"2023-08-17T16:03:26","modified_gmt":"2023-08-17T21:03:26","slug":"domingo-vigesima-semana-del-tiempo-ordinario-ciclo-a-20-agosto-2023","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2023\/08\/17\/domingo-vigesima-semana-del-tiempo-ordinario-ciclo-a-20-agosto-2023\/","title":{"rendered":"DOMINGO, vig\u00e9sima semana del tiempo ordinario (ciclo a) -20 agosto, 2023"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"443\" height=\"640\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-20.jpg\" alt=\"\" class=\"wp-image-2676\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-20.jpg 443w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-20-208x300.jpg 208w\" sizes=\"(max-width: 443px) 100vw, 443px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\"><strong>SAN BERNARDO TOLOMEI (1272-1348)<\/strong><\/p>\n\n\n\n<p>San Bernardo naci\u00f3 en Siena educado en el Colegio de Santo Domingo de Camporeggio, estudi\u00f3 derecho, tambi\u00e9n atend\u00eda por las noches a los enfermos, y en este tiempo contrajo una ceguera grave, a\u00f1os m\u00e1s tarde siendo adulto decidi\u00f3 la vida de ermita\u00f1o junto con otros compa\u00f1eros, se dedicaron a la oraci\u00f3n, a la lectio divina y al silencio. A\u00f1os m\u00e1s tarde fundo la Congregaci\u00f3n Olivetana basada en la regla de san Benito, su h\u00e1bito era de color blanco para manifestar la veneraci\u00f3n a Mar\u00eda, de ah\u00ed naci\u00f3 el monasterio de Santa Mar\u00eda de Monte Oliveto Maggiore, que hacia alusi\u00f3n al Monte de los Olivos donde Jes\u00fas se retiraba a orar. San Bernardo se convirti\u00f3 en abad de su mismo monasterio por m\u00e1s de veintis\u00e9is a\u00f1os hasta su muerte que resulto del contagio de Peste que por ese entonces asolaba a Siena.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Mateo 15,21-28<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, Jes\u00fas sali\u00f3 y se retir\u00f3 a la regi\u00f3n de Tiro y Sid\u00f3n.<\/p>\n\n\n\n<p>Entonces una mujer cananea, saliendo de uno de aquellos lugares, se puso a gritarle:<br>\u00abTen compasi\u00f3n de m\u00ed, Se\u00f1or Hijo de David. Mi hija tiene un demonio muy malo\u00bb.<\/p>\n\n\n\n<p>\u00c9l no le respondi\u00f3 nada. Entonces los disc\u00edpulos se le acercaron a decirle:<br>\u00abAti\u00e9ndela, que viene detr\u00e1s gritando\u00bb.<\/p>\n\n\n\n<p>\u00c9l les contest\u00f3:<br>\u00abSolo he sido enviado a las ovejas descarriadas de Israel\u00bb.<\/p>\n\n\n\n<p>Ella se acerc\u00f3 y se postr\u00f3 ante \u00e9l diciendo:<br>\u00abSe\u00f1or, ay\u00fadame\u00bb.<\/p>\n\n\n\n<p>\u00c9l le contest\u00f3:<br>\u00abNo est\u00e1 bien tomar el pan de los hijos y ech\u00e1rselo a los perritos\u00bb.<\/p>\n\n\n\n<p>Pero ella repuso:<br>\u00abTienes raz\u00f3n, Se\u00f1or; pero tambi\u00e9n los perritos se comen las migajas que caen de la mesa de los amos\u00bb.<\/p>\n\n\n\n<p>Jes\u00fas le respondi\u00f3:<br>\u00abMujer, qu\u00e9 grande es tu fe: que se cumpla lo que deseas\u00bb.<\/p>\n\n\n\n<p>En aquel momento qued\u00f3 curada su hija.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En este pasaje b\u00edblico Jes\u00fas tiene una postura inflexible frente a la  cananea , pero la persistencia de esta mujer le hace cambiar de posici\u00f3n,  su voz suplicante y llena de fe deja admirado al Maestro, Jesucristo quiere ir a aquellos que hacen parte de su comunidad, su af\u00e1n por convertir las mentes de quienes est\u00e1n equivocados, pero fue tanta la insistencia de aquella pobre mujer que no duda en hacerle el milagro, los disc\u00edpulos solo pueden ver a una persona fastidiosa e inoportuna, pero Jes\u00fas ve m\u00e1s all\u00e1 de este grito de suplica, ve sed de Dios.<\/li>\n\n\n\n<li>La fe que caracteriza a la mujer cananea fue la oportunidad que le permiti\u00f3 ser escuchada por Jes\u00fas, sus argumentos validos expuestos ante Jes\u00fas explican que el poder del Mes\u00edas se da a todos sin importar la raza, ni cultura, ni religi\u00f3n, etc, ella expresaba su necesidad por \u00e9l \u00fanico que pod\u00eda sanar el cuerpo y el alma, reconoce la autoridad mesi\u00e1nica de Jes\u00fas a pesar de ser pagana, y este episodio permite que los ap\u00f3stoles vean y entiendan el verdadero significado de la fe, Jes\u00fas nunca neg\u00f3 la sanaci\u00f3n a aquellos que ten\u00edan fe e invita  a postrarse a sus pies para que \u00e9l actu\u00e9 grandes prodigios en el hombre.<\/li>\n\n\n\n<li>Jes\u00fas nunca deja de escuchar nuestras suplicas y clamores por medio de la oraci\u00f3n, al contrario nos observa y trabaja en nosotros silenciosamente, no tiene en cuenta nuestros pecados porque nos ama y siente compasi\u00f3n , pues sabe cuanto necesitamos de su amor para sanar las heridas de nuestro coraz\u00f3n, como la Cananea atiende siempre nuestros asuntos, as\u00ed creamos que nunca oye lo que le pedimos en secreto, debemos presentarnos ante \u00e9l con fe, sabiendo que lo que deseamos ya se ha cumplido, y si hermanos, la fe es as\u00ed esperar que lo que pedimos ya es un hecho realidad, debemos reconocer el poder de nuestro Dios y saber que har\u00e1 milagros imposibles de creer pero ciertos cuando nos abandonamos y confiamos plenamente en \u00e9l.<\/li>\n\n\n\n<li>La fe se convierte en nuestro ingrediente principal a la hora de orar ante nuestro Dios, si expresamos nuestras necesidades sabiendo que Dios ya las conoce, debemos esperar con paciencia, y no dejar de persistir, siempre y cuando pidamos seg\u00fan la voluntad de Dios. Jes\u00fas nos ense\u00f1a que tenemos un Padre Celestial que siente misericordia y compasi\u00f3n de nosotros sus hijos, s\u00f3lo debemos dejar que nuestra vida gire en torno a \u00e9l, y cada situaci\u00f3n, problema, enfermedad, dificultad presente en nuestra vida llegar\u00e1 a feliz termino porque simplemente le pertenecemos. Para que nuestra oraci\u00f3n sea eficaz debemos ser constantes en ella y ligada a la fe no habr\u00e1 duda que nos invada, \u00bf Crees que Jes\u00fas no te escucha? \u00a1Crees que \u00e9l hace distinci\u00f3n de personas? Jes\u00fas siempre esta amando y observa nuestro andar, y nos habla a menudo siendo nosotros quienes ignoremos su voz que nos invita a seguir sus pasos.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Orar constantemente con fe, acrecentar mi fe mediante la Palabra de Dios, asistir a Misa, y alimentarme del cuerpo y la sangre de Jesucristo.<\/li>\n\n\n\n<li>San Bernardo nos motiva a llevar una vida en oraci\u00f3n y silencio que nos permitir\u00e1 alcanzar las m\u00e1s grandes virtudes con la cu\u00e1l obtendremos la vida eterna.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN BERNARDO TOLOMEI (1272-1348) San Bernardo naci\u00f3 en Siena educado en el Colegio de Santo Domingo de Camporeggio, estudi\u00f3 derecho, tambi\u00e9n atend\u00eda por las noches a los enfermos, y en este tiempo contrajo una ceguera grave, a\u00f1os m\u00e1s tarde siendo adulto decidi\u00f3 la vida de ermita\u00f1o junto con otros compa\u00f1eros, se dedicaron &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2023\/08\/17\/domingo-vigesima-semana-del-tiempo-ordinario-ciclo-a-20-agosto-2023\/\"> <span class=\"screen-reader-text\">DOMINGO, vig\u00e9sima semana del tiempo ordinario (ciclo a) -20 agosto, 2023<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":2676,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2675","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-20.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-20.jpg",443,640,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-20-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-20-208x300.jpg",208,300,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-20.jpg",443,640,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-20.jpg",443,640,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-20.jpg",443,640,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-20.jpg",443,640,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SAN BERNARDO TOLOMEI (1272-1348) San Bernardo naci\u00f3 en Siena educado en el Colegio de Santo Domingo de Camporeggio, estudi\u00f3 derecho, tambi\u00e9n atend\u00eda por las noches a los enfermos, y en este tiempo contrajo una ceguera grave, a\u00f1os m\u00e1s tarde siendo adulto decidi\u00f3 la vida de ermita\u00f1o junto con otros compa\u00f1eros, se dedicaron&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=2675"}],"version-history":[{"count":2,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2675\/revisions"}],"predecessor-version":[{"id":2679,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2675\/revisions\/2679"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/2676"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=2675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=2675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=2675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}