{"id":2669,"date":"2023-08-16T16:34:36","date_gmt":"2023-08-16T21:34:36","guid":{"rendered":"https:\/\/devocionario.net\/?p=2669"},"modified":"2023-08-16T16:34:38","modified_gmt":"2023-08-16T21:34:38","slug":"viernes-decimonovena-semana-del-tiempo-ordinario-ciclo-a-18-agosto-2023","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2023\/08\/16\/viernes-decimonovena-semana-del-tiempo-ordinario-ciclo-a-18-agosto-2023\/","title":{"rendered":"VIERNES, decimonovena semana del tiempo ordinario (ciclo a) -18 agosto, 2023"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"427\" height=\"640\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-17.jpg\" alt=\"\" class=\"wp-image-2670\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-17.jpg 427w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-17-200x300.jpg 200w\" sizes=\"(max-width: 427px) 100vw, 427px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\"><strong>SANTA ELENA  (+329)<\/strong><\/p>\n\n\n\n<p>Santa Elena naci\u00f3 en una familia pagana y pobre, desde su juventud presenci\u00f3 la muerte de muchos cristianos, y no entend\u00eda porque eran torturados y asesinados, era mujer noble de coraz\u00f3n, contrajo matrimonio con Constancio y de ese matrimonio tuvieron un hijo quien tuvo como nombre Cesar de Maximiano, su esposo la repudi\u00f3 para casarse con la hijastra de Maximiano, y su hijo que tomo el nombre de Constantino se fue con su pap\u00e1 a educarse en el palacio, luego a\u00f1os m\u00e1s tarde muriendo su Padre se lleva a su Madre, le da poder para levantar iglesias, y tambi\u00e9n se dejo influenciar por ella en ciertos asuntos que se refer\u00edan a los cristianos. A\u00f1os m\u00e1s tarde Santa Elena viaja a los santos lugares en busca del madero donde fue crucificado el Redentor, su af\u00e1n por encontrar esta important\u00edsima cruz la llev\u00f3 hasta los jud\u00edos que por fin dieron respuesta a su b\u00fasqueda, luego decide enviar una parte de la cruz a Jerusal\u00e9n, otra a Constantinopla y otra a Roma para que fuese venerada, tiempo despu\u00e9s muere cumpliendo con su misi\u00f3n de llevar la cruz de Cristo y darla a conocer para que creyeran en Jesucristo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Mateo 19,3-12<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, se acercaron a Jes\u00fas unos fariseos y le preguntaron, para ponerlo a prueba:<br>\u00ab\u00bfEs l\u00edcito a un hombre repudiar a su mujer por cualquier motivo?\u00bb.<\/p>\n\n\n\n<p>\u00c9l les respondi\u00f3:<br>\u00ab \u00bfNo hab\u00e9is le\u00eddo que el Creador, en el principio, los cre\u00f3 hombre y mujer, y dijo: \u201cPor eso dejar\u00e1 el hombre a su padre y a su madre, y se unir\u00e1 a su mujer, y ser\u00e1n los dos una sola carne\u201d? De modo que ya no son dos, sino una sola carne.<br>Pues lo que Dios ha unido, que no lo separe el hombre\u00bb.<\/p>\n\n\n\n<p>Ellos insistieron:<br>\u00ab \u00bfY por qu\u00e9 mand\u00f3 Mois\u00e9s darle acta de divorcio y repudiarla? \u00bb.<\/p>\n\n\n\n<p>\u00c9l les contest\u00f3:<br>\u00abPor la dureza de vuestro coraz\u00f3n os permiti\u00f3 Mois\u00e9s repudiar a vuestras mujeres; pero, al principio, no era as\u00ed. Pero yo os digo que, si uno repudia a su mujer &#8211; no hablo de uni\u00f3n ileg\u00edtima &#8211; y se casa con otra, comete adulterio\u00bb.<\/p>\n\n\n\n<p>Los disc\u00edpulos le replicaron:<br>\u00abSi esa es la situaci\u00f3n del hombre con la mujer, no trae cuenta casarse\u00bb.<\/p>\n\n\n\n<p>Pero \u00e9l les dijo:<br>\u00abNo todos entienden esto, solo los que han recibido ese don. Hay eunucos que salieron as\u00ed del vientre de su madre, a otros los hicieron los hombres, y hay quienes se hacen eunucos ellos mismos por el reino de los cielos. El que pueda entender, entienda\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Los Fariseos pretend\u00edan que Jes\u00fas ganara enemigos con su respuesta basada en el matrimonio, pero \u00e9l les deja claro que quien contrae una uni\u00f3n conyugal debe permanecer unido a su pareja, pues desde el principio Dios anuncia que se hacen una sola carne, y que una vez recibiendo su bendici\u00f3n no deben retroceder, pues si se es consiente de que convivir con alguien exige compromiso y permanencia, as\u00ed vengan los problemas, el divorcio no es la soluci\u00f3n, pues quien recibe este don de casarse debe  cumplir su misi\u00f3n hasta la muerte, Mois\u00e9s hab\u00eda aceptado el repudi\u00f3 contra la mujer, por lo tercos que eran en esa \u00e9poca, pero al venir Jes\u00fas lo hace todo nuevo, tomando lo antiguo restablece lo actual.<\/li>\n\n\n\n<li>Los disc\u00edpulos se desaniman pensando quien podr\u00e1 vivir toda la vida con el mismo hombre o la misma mujer aceptando sus limitaciones, pero Jes\u00fas les ense\u00f1a que la uni\u00f3n en santo matrimonio es un don que no se da a todos, y quien ha decido escoger este camino debe cumplir con su c\u00f3nyuge, pero Jes\u00fas quiere ir m\u00e1s all\u00e1 ense\u00f1\u00e1ndoles que ellos dejar\u00e1n todo por el anuncio del Reino de los cielos, y es una decisi\u00f3n libre ser casado o no casado, siempre y cuando estando en las dos partes siempre se debe servir y dar testimonio, tanto soltero como casado todo repercute hacer una misi\u00f3n con nuestra vida.<\/li>\n\n\n\n<li>Hoy en d\u00eda muchos matrimonios no se soportan, sino que el camino m\u00e1s f\u00e1cil que toman para solucionar los conflictos es divorciarse como si se tratar\u00e1 de un juego, sin darse cuenta que la convivencia es uno de los compromisos m\u00e1s complicados en una relaci\u00f3n de pareja, pero se olvidan que quien pone en las manos de Dios un matrimonio, todo absolutamente todo se sabr\u00e1 llevar con respeto y sobre todo con amor. Jes\u00fas quiere que el coraz\u00f3n de los hombres este dispuesto a amar, y a soportar con paciencia, pero el maligno siempre pone tropiezos que se vuelven escabrosos y nos impulsan a abandonar nuestra misi\u00f3n de casados, por eso debemos confiar en aquel que es amor, y si resultan problemas en nuestra uni\u00f3n orar juntos nos ayudar\u00e1 a crecer, aprender, y a cambiar por amor al otro al que es considerado mi propia carne.<\/li>\n\n\n\n<li>Quienes se disponen a permanecer en la solter\u00eda, no se considera pecado grave, al contrario su vida estar\u00e1 encaminada a seguir a Jesucristo, pues recordemos que tambi\u00e9n es un don, cada don lo podemos convertir en vocaci\u00f3n independientemente como estemos civilmente hablando, \u00bf Es tu vida dedicada a Jes\u00fas o a los hombres? si decides seguir a Jesucristo el tema del matrimonio pasar\u00e1 a segundo plano, pero si tienes anhelos de casarte, ora para que Dios ponga en tu camino un amor sincero que te valore y sepa ser uno contigo y agradar a Dios siempre, no optando por renunciar a mi compromiso de amor, sino siendo fieles y leales a quien este a mi lado y al mismo Jes\u00fas que camina entre nosotros.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Hoy orar\u00e9 por el matrimonio de mis padres, y por aquellos que han terminado por diferentes circunstancias, para que vuelvan a continuar con su vocaci\u00f3n de casados.<\/li>\n\n\n\n<li>Santa Elena nos ense\u00f1a  que si nuestro matrimonio fracasa, debemos siempre permanecer fieles a Jes\u00fas, respetar mi compromiso de casado (a), y poner al servicio mi vida en torno a la evangelizaci\u00f3n.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SANTA ELENA (+329) Santa Elena naci\u00f3 en una familia pagana y pobre, desde su juventud presenci\u00f3 la muerte de muchos cristianos, y no entend\u00eda porque eran torturados y asesinados, era mujer noble de coraz\u00f3n, contrajo matrimonio con Constancio y de ese matrimonio tuvieron un hijo quien tuvo como nombre Cesar de Maximiano, &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2023\/08\/16\/viernes-decimonovena-semana-del-tiempo-ordinario-ciclo-a-18-agosto-2023\/\"> <span class=\"screen-reader-text\">VIERNES, decimonovena semana del tiempo ordinario (ciclo a) -18 agosto, 2023<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":2670,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2669","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-17.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-17.jpg",427,640,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-17-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-17-200x300.jpg",200,300,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-17.jpg",427,640,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-17.jpg",427,640,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-17.jpg",427,640,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-17.jpg",427,640,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SANTA ELENA (+329) Santa Elena naci\u00f3 en una familia pagana y pobre, desde su juventud presenci\u00f3 la muerte de muchos cristianos, y no entend\u00eda porque eran torturados y asesinados, era mujer noble de coraz\u00f3n, contrajo matrimonio con Constancio y de ese matrimonio tuvieron un hijo quien tuvo como nombre Cesar de Maximiano,&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=2669"}],"version-history":[{"count":1,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2669\/revisions"}],"predecessor-version":[{"id":2671,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2669\/revisions\/2671"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/2670"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=2669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=2669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=2669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}