{"id":2661,"date":"2023-08-15T17:24:50","date_gmt":"2023-08-15T22:24:50","guid":{"rendered":"https:\/\/devocionario.net\/?p=2661"},"modified":"2023-08-15T17:24:52","modified_gmt":"2023-08-15T22:24:52","slug":"miercoles-decimonovena-semana-del-tiempo-ordinario-ciclo-a-16-agosto-2023","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2023\/08\/15\/miercoles-decimonovena-semana-del-tiempo-ordinario-ciclo-a-16-agosto-2023\/","title":{"rendered":"MIERCOLES, decimonovena semana del tiempo ordinario (ciclo a) -16 agosto, 2023"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-16-1024x683.jpg\" alt=\"\" class=\"wp-image-2662\" width=\"651\" height=\"434\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-16-1024x683.jpg 1024w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-16-300x200.jpg 300w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-16-768x512.jpg 768w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-16.jpg 1280w\" sizes=\"(max-width: 651px) 100vw, 651px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\"><strong>SAN ESTEBAN DE HUNGR\u00cdA (975-1038)<\/strong><\/p>\n\n\n\n<p>San Esteban se cas\u00f3 con Gisela hermana de San Enrique, influy\u00f3 mucho en su vida, fue un guerrero excepcional y de orden, venci\u00f3 en muchas batallas contra quienes no quer\u00edan obedecer a la fe cat\u00f3lica, gracias a que \u00e9l defendi\u00f3 a los Obispos, trajo a uno de ellos para que junto con \u00e9l gobernaran a Hungr\u00eda basado en el catolicismo, derroto a muchos que impart\u00edan religiones falsas, idolatr\u00eda y dem\u00e1s, San Esteban fue nombrado Rey de Hungr\u00eda. Su amor a la iglesia cat\u00f3lica era tal, que edifico templos, daba comida y limosna a  los pobres, fund\u00f3 conventos y los dotaba de todo lo necesario, era generoso con los m\u00e1s pobres, pues dec\u00eda que quer\u00eda tratarlos de manera especial pues Jesucristo estaba en ellos. A\u00f1os m\u00e1s tarde educo a su hijo en la humildad, en el respeto a la religi\u00f3n, en la caridad, poniendo sus esperanzas en \u00e9l como sucesor cuando \u00e9l muriera, pero su hijo perdi\u00f3 la vida en un d\u00eda de cacer\u00eda, despu\u00e9s comenz\u00f3 a padecer muchas enfermedades que lo atormentaban, \u00e9l fue el hombre valiente que convirti\u00f3 al catolicismo al pa\u00eds de Hungr\u00eda.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Mateo 18,15-20<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, dijo Jes\u00fas a sus disc\u00edpulos:<br>\u00abSi tu hermano peca contra ti, repr\u00e9ndelo estando los dos a solas. Si te hace caso, has salvado a tu hermano. Si no te hace caso, llama a otro o a otros dos, para que todo el asunto quede confirmado por boca de dos o tres testigos. Si no les hace caso, d\u00edselo a la comunidad, y si no hace caso ni siquiera a la comunidad, consid\u00e9ralo como un pagano o un publicano.<\/p>\n\n\n\n<p>En verdad os digo que todo lo que at\u00e9is en la tierra quedar\u00e1 atado en el cielo, y todo lo que desat\u00e9is en la tierra quedar\u00e1 desatado en los cielos.<\/p>\n\n\n\n<p>Os digo, adem\u00e1s, que si dos de vosotros se ponen de acuerdo en la tierra para pedir algo, se lo dar\u00e1 mi Padre que est\u00e1 en los cielo. Porque donde dos o tres est\u00e1n reunidos en mi nombre, all\u00ed estoy yo en medio de ellos\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Jes\u00fas revela a sus disc\u00edpulos un mecanismo que debe emplearse a la hora de resolver problemas en comunidades,  ense\u00f1a la manera de hacer volver al hermano al camino verdadero, de ayudarlo a entender que esta equivocado, reprenderlo fraternalmente,   ense\u00f1ando una serie de pasos a cumplir a la hora de exhortar a los dem\u00e1s, ,  motivando a cuidar de la vida del pr\u00f3jimo, a sentir y a comprender, a ser compasivos y a lograr recuperar relaciones que han sido truncadas por mal entendidos, odios , rencores y enemistades que causan dolor.<\/li>\n\n\n\n<li>Jes\u00fas  ense\u00f1a que vivir en comunidad es la mejor forma de vencer el mal, la uni\u00f3n hace la fuerza es un dicho que se repite constantemente pero que no solo se da con quienes de cierta manera compaginan sino incluso con quienes no se tiene afinidad, Dios quiere hombres y mujeres comprometidos a impartir uni\u00f3n, para que pensando todos as\u00ed por medio de la oraci\u00f3n se pueda alcanzar grandes cosas en comunidad, Jes\u00fas insiste que siempre se debe procurar buscar el bienestar del que esta a mi lado, pero como sabe que el hombre se complica la vida, y a todo le pone detalle por eso decide que se siga sus consejos para tratar con aquellos problemas que puedan surgir en la convivencia diaria. Recordando que la \u00fanica salida para soportar al otro es el amor.<\/li>\n\n\n\n<li>En esta sociedad tan llena de orgullo es dif\u00edcil solucionar problemas de convivencia, vivir en comunidad se convierte en una tarea complicada, pero no imposible cuando somos conscientes de que siendo hijos de Dios el amor puede ayudarnos a discernir como actuar frente a cada situaci\u00f3n de conflicto, existen personas que insisten en arruinar la vida del otro, porque simplemente les gana el odio, o t\u00e1lves la soberbia que no permite reconocer defectos y aceptar  realidades, siempre estamos bloqueando nuestra mente con el rencor, que no nos permite reconciliarnos con el otro, dejar el pasado atr\u00e1s se nos dificulta y siempre estamos trayendo al presente momentos amargos que nos lastiman, sin caer en cuenta que el hoy es un d\u00eda para iniciar una nueva vida. Nos creemos tan perfectos que empecemos a se\u00f1alar y hasta cuestionamos el accionar del otro, pero queridos hermanos tampoco debemos irnos a los extremos, Jesucristo nos esta dando las pautas para saber llevar aquellos problemas que no podemos solucionar tan f\u00e1cilmente, nos invita al dialogar con quien insiste en hacerme da\u00f1o, y si este no atiende existen otras instancia que debemos hacer para que nuestra conciencia este totalmente tranquila siendo la oraci\u00f3n la \u00faltima esperanza para la conversi\u00f3n de mi hermano.<\/li>\n\n\n\n<li>Distanciarme de aquel que me ha hecho da\u00f1o y lo sigue haciendo es la mejor forma de evitar situaciones dolorosas, pero al decirnos Jes\u00fas que lo tratemos como un pagano cuando ya se ha exhortado alguien, no quiere decir que ah\u00ed termina mi misi\u00f3n, sino que aun no teniendo contacto con esa persona, debemos encomendarla en la oraci\u00f3n que si tiene poder, y en el d\u00eda menos pensado aquello que cre\u00edamos imposible de arreglar se va acomodando seg\u00fan la voluntad de Dios, s\u00f3lo debemos esperar con paciencia y soportar con amor. En la iglesia ocurre mucho estos episodios que nos intranquilizan y hasta nos llevan a desanimarnos y hasta abandonar nuestra vocaci\u00f3n como cristianos cat\u00f3licos, pero hoy el Se\u00f1or nos motiva que cuando las palabras no ayudan las rodillas  que oran si, Jes\u00fas nos da esperanza cuando queremos decaer, nos comprende y nos da la sabidur\u00eda para obrar como \u00e9l lo hizo estando en esta tierra, s\u00f3lo nos queda conservar la calma y actuar siempre en bienestar del otro, as\u00ed \u00e9l quiera hacerme el mal. &#8220;<em>Empieza por hacer lo necesario, luego haz lo posible y de pronto estar\u00e1s logrando lo imposible&#8221;.<\/em> San Francisco de As\u00eds.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Orar en todo momento, por aquella persona con la que no he podido llevar una buena relaci\u00f3n, fomentar la uni\u00f3n en mi parroquia, o en el movimiento al que pertenezca en la iglesia.<\/li>\n\n\n\n<li>San Esteban gan\u00f3 muchas batallas por el bienestar de la iglesia cat\u00f3lica, defendi\u00f3 la fe, como \u00e9l debemos combatir la desuni\u00f3n con la oraci\u00f3n para que seamos testigos fieles del amor de Cristo.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN ESTEBAN DE HUNGR\u00cdA (975-1038) San Esteban se cas\u00f3 con Gisela hermana de San Enrique, influy\u00f3 mucho en su vida, fue un guerrero excepcional y de orden, venci\u00f3 en muchas batallas contra quienes no quer\u00edan obedecer a la fe cat\u00f3lica, gracias a que \u00e9l defendi\u00f3 a los Obispos, trajo a uno de &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2023\/08\/15\/miercoles-decimonovena-semana-del-tiempo-ordinario-ciclo-a-16-agosto-2023\/\"> <span class=\"screen-reader-text\">MIERCOLES, decimonovena semana del tiempo ordinario (ciclo a) -16 agosto, 2023<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":2662,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2661","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-16.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-16.jpg",1280,854,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-16-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-16-300x200.jpg",300,200,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-16-768x512.jpg",768,512,true],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-16-1024x683.jpg",1024,683,true],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-16.jpg",1280,854,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/AGOSTO-16.jpg",1280,854,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SAN ESTEBAN DE HUNGR\u00cdA (975-1038) San Esteban se cas\u00f3 con Gisela hermana de San Enrique, influy\u00f3 mucho en su vida, fue un guerrero excepcional y de orden, venci\u00f3 en muchas batallas contra quienes no quer\u00edan obedecer a la fe cat\u00f3lica, gracias a que \u00e9l defendi\u00f3 a los Obispos, trajo a uno de&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=2661"}],"version-history":[{"count":1,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2661\/revisions"}],"predecessor-version":[{"id":2663,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2661\/revisions\/2663"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/2662"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=2661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=2661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=2661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}