{"id":2656,"date":"2023-08-15T15:09:15","date_gmt":"2023-08-15T20:09:15","guid":{"rendered":"https:\/\/devocionario.net\/?p=2656"},"modified":"2023-08-15T15:09:17","modified_gmt":"2023-08-15T20:09:17","slug":"martes-decimonovena-semana-del-tiempo-ordinario-ciclo-a-15-agosto-2023","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2023\/08\/15\/martes-decimonovena-semana-del-tiempo-ordinario-ciclo-a-15-agosto-2023\/","title":{"rendered":"MARTES, decimonovena semana del tiempo ordinario (ciclo a) -15 agosto, 2023"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-15-1024x682.jpg\" alt=\"\" class=\"wp-image-2657\" width=\"679\" height=\"452\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-15-1024x682.jpg 1024w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-15-300x200.jpg 300w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-15-768x512.jpg 768w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-15.jpg 1280w\" sizes=\"(max-width: 679px) 100vw, 679px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-15.1.jpg\" alt=\"\" class=\"wp-image-2658\" width=\"257\" height=\"257\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-15.1.jpg 225w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-15.1-150x150.jpg 150w\" sizes=\"(max-width: 257px) 100vw, 257px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\"><strong>ASUNCI\u00d3N DE NUESTRA SE\u00d1ORA (1950)<\/strong><\/p>\n\n\n\n<p>Esta solemnidad se proclam\u00f3 por el Papa pio XII en la constituci\u00f3n Munificentisimus Deus, este Dogma de la Iglesia Cat\u00f3lica basado en que Mar\u00eda Madre de Dios, siempre Virgen fue subida al cielo en cuerpo y alma, esta fiesta nos motiva a perseguir la santidad como lo hizo Mar\u00eda que obedeci\u00f3 al Plan Divino, siendo bendita entre las mujeres para ser participe del plan de salvaci\u00f3n, hoy la iglesia nos pide acogernos al amor y misericordia de Dios, logrando llegar a Jesucristo a trav\u00e9s de Mar\u00eda, siguiendo su ejemplo vayamos al cielo.<\/p>\n\n\n\n<p>Hoy en Oca\u00f1a Norte de Santander (Colombia) hace 312 apareci\u00f3 en una Monta\u00f1a de esta regi\u00f3n la advocaci\u00f3n de nuestra Se\u00f1ora de las gracias de Torcoroma que se venera en la ciudad de Oca\u00f1a, perteneciente a esta bell\u00edsima Regi\u00f3n, quiero dar a conocer este inmenso regalo que Dios nos ha dado para proteger a nuestro pueblo, en un peque\u00f1o pedazo de \u00e1rbol se plasmo la imagen de Mar\u00eda, y se revelo a una humilde familia, hoy se encuentra especialmente en un hermoso Santuario, que invito para que conozcan, visiten y se llenen del inmenso amor de Mar\u00eda que se revela a los hombres para acercarnos a su hijo amado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Lucas 1,39-56<\/strong><\/p>\n\n\n\n<p>Por entonces Mar\u00eda tom\u00f3 su decisi\u00f3n y se fue, sin m\u00e1s demora, a una ciudad ubicada en los cerros de Jud\u00e1. Entr\u00f3 en la casa de Zacar\u00edas y salud\u00f3 a Isabel. Al o\u00edr Isabel su saludo, el ni\u00f1o dio saltos en su vientre. Isabel se llen\u00f3 del Esp\u00edritu Santo y exclam\u00f3 en alta voz: &#8220;\u00a1Bendita t\u00fa eres entre las mujeres y bendito el fruto de tu vientre! \u00bfC\u00f3mo he merecido yo que venga a m\u00ed la madre de mi Se\u00f1or? Apenas lleg\u00f3 tu saludo a mis o\u00eddos, el ni\u00f1o salt\u00f3 de alegr\u00eda en mis entra\u00f1as. \u00a1Dichosa t\u00fa por haber cre\u00eddo que se cumplir\u00edan las promesas del Se\u00f1or!&#8221;<\/p>\n\n\n\n<p>Mar\u00eda dijo entonces:<\/p>\n\n\n\n<p>&#8220;Proclama mi alma la grandeza del Se\u00f1or,<\/p>\n\n\n\n<p>y mi esp\u00edritu se alegra en Dios mi Salvador,<\/p>\n\n\n\n<p>porque se fij\u00f3 en su humilde esclava,<\/p>\n\n\n\n<p>y desde ahora todas las generaciones me dir\u00e1n feliz.<\/p>\n\n\n\n<p>El Poderoso ha hecho grandes cosas por m\u00ed: \u00a1Santo es su Nombre!<\/p>\n\n\n\n<p>Muestra su misericordia siglo tras siglo<\/p>\n\n\n\n<p>a todos aquellos que viven en su presencia.<\/p>\n\n\n\n<p>Dio un golpe con todo su poder: deshizo a los soberbios y sus planes.<\/p>\n\n\n\n<p>Derrib\u00f3 a los poderosos de sus tronos, y exalt\u00f3 a los humildes.<\/p>\n\n\n\n<p>Colm\u00f3 de bienes a los hambrientos,<\/p>\n\n\n\n<p>y despidi\u00f3 a los ricos con las manos vac\u00edas.<\/p>\n\n\n\n<p>Socorri\u00f3 a Israel, su siervo; se acord\u00f3 de su misericordia,<\/p>\n\n\n\n<p>como lo hab\u00eda prometido a nuestros padres,<\/p>\n\n\n\n<p>a Abraham y a sus descendientes para siempre&#8221;.<\/p>\n\n\n\n<p>Mar\u00eda se qued\u00f3 unos tres meses con Isabel, y despu\u00e9s volvi\u00f3 a su casa.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En el Evangelio de hoy Mar\u00eda es la protagonista, una mujer humilde y obediente a la invitaci\u00f3n del Dios Alt\u00edsimo, decide visitar a su prima, para cumplir su misi\u00f3n de llenar con el  Espiritu Santo a Juan el Bautista precursor de Jesucristo, Mar\u00eda se destac\u00f3 por su si sincero que dar\u00eda paso al inicio del plan que Dios hab\u00eda trazado para salvar a la humanidad, y fue Mar\u00eda la elegida para cumplir lo dicho por los profetas a\u00f1os antes, ella se convirti\u00f3 en la bienaventurada por acoger la palabra de Dios hecha carne en su vientre.<\/li>\n\n\n\n<li>Mar\u00eda convierte su vida en templo santo para que en ella se engendre el unig\u00e9nito de Dios, es participe de la humanidad de Jesucristo, Dios vio en ella las cualidades perfectas que la llevaron a  convertirse en la Madre de Jes\u00fas, don\u00f3 su vida misma, y sin desobedecer la voluntad de Dios se entrego sin reservas. Una parte de Mar\u00eda se puede contemplar en la Eucarist\u00eda, su misma sangre fue compartida con su hijo amado, lo vi\u00f3 crecer, y lo tuvo durante nueve meses en su vientre, la gracia de Mar\u00eda se refleja en Jes\u00fas hombre. La oraci\u00f3n exclamada por Mar\u00eda es un canto de misericordia que nos motiva a creer en las promesas de Dios para con la raza humana, el Magnifica se convierte en aquella oraci\u00f3n que nos impulsa a seguir a Dios sabiendo que cumple con su palabra y quiere el bien para quienes se abandonan en sus manos.<\/li>\n\n\n\n<li>Hoy Mar\u00eda nos invita a decir si a los mandatos de Dios, nos ense\u00f1a el sentido de la obediencia y la humildad que son fichas claves para caminar en los senderos de la santidad, dejar que Dios haga su proyecto para con nosotros es obedecer a su palabra, \u00e9l es el Dios de antes y de ahora que nos ama y siempre ha estado con nosotros para que le busquemos de coraz\u00f3n y por amor. Es Mar\u00eda la primera disc\u00edpula lleva el mensaje de salvaci\u00f3n a su prima, y nos pide tomemos su ejemplo de misioneros para salvarnos y ayudar a otros a encontrar la salvaci\u00f3n.<\/li>\n\n\n\n<li>Defender la persona de Mar\u00eda es nuestro deber de Cristianos Cat\u00f3licos, existen en esta actualidad muchos hermanos separados de la Iglesia verdadera de Cristo que critican nuestra veneraci\u00f3n a Mar\u00eda Madre, pero no debemos tener miedo en considerarla como una mujer important\u00edsima en la historia divina de salvaci\u00f3n y en nuestra vida, pues ella es el modelo perfecto que como criatura nos ense\u00f1a a obedecer a su hijo el muy amado, nos anima a ser humilde para alcanzar el cielo, y nos ense\u00f1a a confiar en las palabras de Dios. Su intercesi\u00f3n es una manera de acercarnos a Jesucristo, quien no ama a Mar\u00eda no ama a su hijo, \u00bfQui\u00e9n no estima a su Madre en este mundo? as\u00ed mismo Mar\u00eda se convierte en nuestra Madre y como tal nos lleva a Jes\u00fas.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Rezar el Magnifica todos los d\u00edas de nuestra vida, para que junto con Mar\u00eda recordemos cuan grande Dios ha sido con nosotros, y para que tengamos en cuenta que tenemos una Madre celestial que nos ayuda a acercarnos a Jes\u00fas.<\/li>\n\n\n\n<li>La solemnidad de la Asunci\u00f3n de Nuestra Se\u00f1ora, nos motiva a labrar nuestro camino a la conversi\u00f3n y por ende a la santidad, como Mar\u00eda esforc\u00e9monos por obedecer la voluntad de nuestro Padre Celestial.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA ASUNCI\u00d3N DE NUESTRA SE\u00d1ORA (1950) Esta solemnidad se proclam\u00f3 por el Papa pio XII en la constituci\u00f3n Munificentisimus Deus, este Dogma de la Iglesia Cat\u00f3lica basado en que Mar\u00eda Madre de Dios, siempre Virgen fue subida al cielo en cuerpo y alma, esta fiesta nos motiva a perseguir la santidad como lo &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2023\/08\/15\/martes-decimonovena-semana-del-tiempo-ordinario-ciclo-a-15-agosto-2023\/\"> <span class=\"screen-reader-text\">MARTES, decimonovena semana del tiempo ordinario (ciclo a) -15 agosto, 2023<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":2657,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-15.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-15.jpg",1280,853,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-15-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-15-300x200.jpg",300,200,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-15-768x512.jpg",768,512,true],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-15-1024x682.jpg",1024,682,true],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-15.jpg",1280,853,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/08\/agosto-15.jpg",1280,853,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA ASUNCI\u00d3N DE NUESTRA SE\u00d1ORA (1950) Esta solemnidad se proclam\u00f3 por el Papa pio XII en la constituci\u00f3n Munificentisimus Deus, este Dogma de la Iglesia Cat\u00f3lica basado en que Mar\u00eda Madre de Dios, siempre Virgen fue subida al cielo en cuerpo y alma, esta fiesta nos motiva a perseguir la santidad como lo&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=2656"}],"version-history":[{"count":1,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2656\/revisions"}],"predecessor-version":[{"id":2659,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2656\/revisions\/2659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/2657"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=2656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=2656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=2656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}