{"id":2558,"date":"2023-07-24T12:14:43","date_gmt":"2023-07-24T17:14:43","guid":{"rendered":"https:\/\/devocionario.net\/?p=2558"},"modified":"2023-07-24T12:14:44","modified_gmt":"2023-07-24T17:14:44","slug":"miercoles-decimosexta-semana-del-tiempo-ordinario-ciclo-a-26-julio-2023","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2023\/07\/24\/miercoles-decimosexta-semana-del-tiempo-ordinario-ciclo-a-26-julio-2023\/","title":{"rendered":"MIERCOLES, decimosexta semana del tiempo ordinario (ciclo a) -26 julio, 2023"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"480\" height=\"640\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/07\/JULIO-26.jpg\" alt=\"\" class=\"wp-image-2560\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/07\/JULIO-26.jpg 480w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/07\/JULIO-26-225x300.jpg 225w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\"><strong>SAN JOAQUIN Y SANTA ANA <\/strong><\/p>\n\n\n\n<p>Hoy la iglesia celebra a San Joaqu\u00edn y Santa Ana, desde el siglo II inici\u00f3 el culto a estos dos santos , que fueron seg\u00fan los libros ap\u00f3crifos los padres de la sant\u00edsima Virgen Mar\u00eda, con certeza no se tienen datos sobre ellos, pero seg\u00fan la tradici\u00f3n cuenta, que San Joaqu\u00edn fue burlado por sus vecinos al no tener hijos con su esposa Ana, entonces huy\u00f3 al desierto a orar y ponerse en penitencia y tiempo despu\u00e9s, Dios permiti\u00f3 que de Santa Ana naciera la madre del salvador, ellos educaron a Mar\u00eda en las virtudes de humildad y obediencia. Hoy en d\u00eda, san Joaqu\u00edn y santa Ana son considerados los patrones de los abuelos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Mateo 13,1-9<\/strong><\/p>\n\n\n\n<p>Aquel d\u00eda, sali\u00f3 Jes\u00fas de casa y se sent\u00f3 junto al lago. Y acudi\u00f3 a \u00e9l tanta gente que tuvo que subirse a una barca; se sent\u00f3, y la gente se qued\u00f3 de pie en la orilla.<\/p>\n\n\n\n<p>Les habl\u00f3 mucho rato en par\u00e1bolas:<br>\u00abSali\u00f3 el sembrador a sembrar. Al sembrar, una parte cay\u00f3 al borde del camino; vinieron los p\u00e1jaros y se lo comieron.<\/p>\n\n\n\n<p>Otra parte cay\u00f3 en terreno pedregoso, donde apenas ten\u00eda tierra, y, como la tierra no era profunda brot\u00f3 en seguida; pero en cuanto sali\u00f3 el sol, se abras\u00f3 y por falta de ra\u00edz se sec\u00f3.<\/p>\n\n\n\n<p>Otra cay\u00f3 entre abrojos, que crecieron y la ahogaron.<\/p>\n\n\n\n<p>Otra cay\u00f3 en tierra buena y dio fruto: una, ciento; otra sesenta; otra, treinta.<\/p>\n\n\n\n<p>El que tenga o\u00eddos, que oiga\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Jesucristo invita a sus oyentes a que escuchen con los o\u00eddos de su coraz\u00f3n, despierta al hombre a que sea sembrador y sea terreno al mismo tiempo, que anuncie la palabra y tambi\u00e9n la ponga en practica, es decisi\u00f3n de todo cristiano ser terreno f\u00e9rtil o inf\u00e9rtil, quien destina su vida a recibir la palabra y a sembrarla en su interior, su obrar ser\u00e1n luz en este mundo. En todo momento el Maestro  motiva a salir de casa para ir a su encuentro, ser promotores de la Buena de Salvaci\u00f3n es atender al llamado de Jesucristo. Dios no obliga a nadie a seguir sus pasos, y mucho menos a escuchar su palabra que es poder, solo hace su invitaci\u00f3n de amor, a quienes quieran m\u00e1s que verle escucharlo.<\/li>\n\n\n\n<li>&#8220;y dio mucho fruto&#8221; quien toma la semilla del sembrador y la guarda en su interior, la consecuencia de recibir es dar, en este evangelio el buen fruto es en pocas palabras, las buenas obras, son el producto de  permitir que la vida sea trabajada, y esto se logra mediante el crecimiento espiritual que se da por medio de  alimentarnos de la ense\u00f1anzas de Jes\u00fas, recibimos y la respuesta ser\u00e1 obrar el bien, pero Jes\u00fas da unos valores del producido que da cada terreno, y es que todos los seres humanos tienen procesos diferentes y van a diferentes velocidades, entonces la paciencia y la esperanza juegan un papel muy importante en la evangelizaci\u00f3n de este mundo ,para esperar a quienes intentan pero van en el camino correcto, y a quienes siguen definitivamente cumplen la voluntad de Dios.<\/li>\n\n\n\n<li>En la actualidad, nuestras vidas se han convertido en terrenos f\u00e9rtiles para el mal, destinamos nuestro tiempo y espacio a escuchar lo terreno y a trabajar enceguecidos por cosas, que al fin y al cabo quedar\u00e1n en este mundo. La palabra de Dios es escaza para la ni\u00f1ez y la juventud, la atenci\u00f3n de muchos est\u00e1 en seguir patrones para encajar en esta sociedad materialista, seguir a Cristo es una opci\u00f3n y no un deber de Cristianos, cada d\u00eda la fe va decayendo y ponerse a la moda es lo que realmente importa, cuidar el cuerpo m\u00e1s que el interior es el pan de cada d\u00eda, interesados por la apariencia nuestro coraz\u00f3n va siguiendo nuestros propios deseos, generando frutos que ocasionan sufrimientos y muerte a su paso, la biblia es un adorno en  las casas, se quedan all\u00ed sin dar frutos, y lo m\u00e1s ir\u00f3nico es que buscando soluciones a sus vidas fuera de la palabra, sin darse cuenta que es la fuente que da vida misma.<\/li>\n\n\n\n<li>Debemos ser pacientes con los procesos de conversi\u00f3n de nuestros hermanos y los nuestros, cada uno al ser terreno f\u00e9rtil, dependiendo a sus carismas y dones que Dios a proporcionado camina lento o r\u00e1pido, pero siempre con su mirada puesta en Jesucristo. La palabra debe convertirse en nuestra fuente de inspiraci\u00f3n y esperanza para continuar anunciando a nuestro Se\u00f1or Jesucristo con nuestro testimonio de vida, por nuestros frutos nos conocer\u00e1 Dios,  y es por ello que creer en Jesucristo no basta si ese creer no va unido a las obras, cada vez que nos encontramos en diferentes episodios de nuestra vida y que no obtenemos respuesta a nuestros interrogantes, es la palabra misma queda respuesta aquello que inquieta nuestro coraz\u00f3n, ser sembrador es ya la misi\u00f3n que Jes\u00fas nos encomend\u00f3 desde nuestro bautismos de anunciar la Buena de salvaci\u00f3n, de nosotros depende propagar la semilla depositada en nuestro interior no solo generando fruto en nosotros sino en los dem\u00e1s.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Leer la palabra de Dios todos los d\u00edas, y en cada momento que se pueda, llevarla a los dem\u00e1s como verdaderos anunciadores, y ponerla en pr\u00e1ctica en cada momento de mi vida.<\/li>\n\n\n\n<li>San Joaqu\u00edn y Santa Ana sembraron en Mar\u00eda la semilla de Dios, dando como fruto las virtudes de la humildad y obediencia,  las caracter\u00edsticas perfectas que la convertir\u00edan en la Madre de Jes\u00fas. Amar y visitar a nuestros abuelos es signo de agradecimiento por la fe en Dios que ellos nos han inculcado en nuestra vida y que hoy todavia seguimos difundiendo.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN JOAQUIN Y SANTA ANA Hoy la iglesia celebra a San Joaqu\u00edn y Santa Ana, desde el siglo II inici\u00f3 el culto a estos dos santos , que fueron seg\u00fan los libros ap\u00f3crifos los padres de la sant\u00edsima Virgen Mar\u00eda, con certeza no se tienen datos sobre ellos, pero seg\u00fan la tradici\u00f3n &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2023\/07\/24\/miercoles-decimosexta-semana-del-tiempo-ordinario-ciclo-a-26-julio-2023\/\"> <span class=\"screen-reader-text\">MIERCOLES, decimosexta semana del tiempo ordinario (ciclo a) -26 julio, 2023<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":2560,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/07\/JULIO-26.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/07\/JULIO-26.jpg",480,640,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/07\/JULIO-26-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/07\/JULIO-26-225x300.jpg",225,300,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/07\/JULIO-26.jpg",480,640,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/07\/JULIO-26.jpg",480,640,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/07\/JULIO-26.jpg",480,640,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/07\/JULIO-26.jpg",480,640,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SAN JOAQUIN Y SANTA ANA Hoy la iglesia celebra a San Joaqu\u00edn y Santa Ana, desde el siglo II inici\u00f3 el culto a estos dos santos , que fueron seg\u00fan los libros ap\u00f3crifos los padres de la sant\u00edsima Virgen Mar\u00eda, con certeza no se tienen datos sobre ellos, pero seg\u00fan la tradici\u00f3n&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=2558"}],"version-history":[{"count":2,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2558\/revisions"}],"predecessor-version":[{"id":2561,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2558\/revisions\/2561"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/2560"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=2558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=2558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=2558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}