{"id":2468,"date":"2023-07-06T18:02:08","date_gmt":"2023-07-06T23:02:08","guid":{"rendered":"https:\/\/devocionario.net\/?p=2468"},"modified":"2023-07-06T18:02:09","modified_gmt":"2023-07-06T23:02:09","slug":"sabado-decimotercera-semana-del-tiempo-ordinario-ciclo-a-08-julio-2023","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2023\/07\/06\/sabado-decimotercera-semana-del-tiempo-ordinario-ciclo-a-08-julio-2023\/","title":{"rendered":"SABADO, decimotercera semana del tiempo ordinario (ciclo a) -08 julio, 2023"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/07\/julio-8.jpg\" alt=\"\" class=\"wp-image-2469\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/07\/julio-8.jpg 640w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/07\/julio-8-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\"><strong>SAN ADRIANO III (+885)<\/strong><\/p>\n\n\n\n<p>San Adriano en el a\u00f1o 884 fue nombrado papa de la iglesia en un lapso de tiempo muy corto, debido a que muri\u00f3 en M\u00f3dena (Italia) durante un viaje que realiz\u00f3 para encontrase con el emperador Carlos el Gordo para tratar algunos temas, decidi\u00f3 aceptar la invitaci\u00f3n pero no logr\u00f3 llegar, San Adriano dur\u00f3 solo 17 meses en el pontificado, en el momento que estuvo como papa ayudo a muchos necesitados pues en ese tiempo se estaba pasando por una carest\u00eda haciendo todo lo imposible para lograr sobrellevar esta escases que amenazo a muchos en aquella regi\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Mateo 9,14-17<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, se acercaron los disc\u00edpulos de Juan a Jes\u00fas, pregunt\u00e1ndole: \u00ab\u00bfPor qu\u00e9 nosotros y los fariseos ayunamos a menudo y, en cambio, tus disc\u00edpulos no ayunan?\u00bb<br>Jes\u00fas les dijo: \u00ab\u00bfEs que pueden guardar luto los invitados a la boda, mientras el novio est\u00e1 con ellos? Llegar\u00e1 un d\u00eda en que se lleven al novio, y entonces ayunar\u00e1n. Nadie echa un remiendo de pa\u00f1o sin remojar a un manto pasado; porque la pieza tira del manto y deja un roto peor. Tampoco se echa vino nuevo en odres viejos, porque revientan los odres; se derrama el vino, y los odres se estropean; el vino nuevo se echa en odres nuevos, y as\u00ed las dos cosas se conservan.\u00bb<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h4>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color\"><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Jesucristo quiere dar a conocer la nueva creaci\u00f3n que se da mediante su presencia en la tierra, \u00e9l lo hace todo nuevo, pues ofrece una vida basada en la misericordia y el amor, pero los disc\u00edpulos de Juan ven s\u00f3lo lo externo, preocupados por una pr\u00e1ctica piadosa aun no reconocen a Jes\u00fas, no aprovechan la oportunidad de tenerlo en frente, es verdad que el ayuno es necesario para mantenerse firme en la meta que persiguen, pero el Maestro todav\u00eda estaba con ellos y su luz es m\u00e1s que suficiente para mantenerse en pie. Jesucristo no quiere abolir el ayuno sino quiere llevar a la integralidad al ser humano, d\u00e1ndole a entender que se debe estar alegres porque \u00e9l es el centro y culmen de la vida, es \u00e9l quien da la gracia y estando con \u00e9l cada experiencia con Dios cobra valor.<\/li>\n\n\n\n<li>Jes\u00fas quiere dejar el pasado del hombre y hacer de \u00e9l todo nuevo, para que ya no est\u00e9 sometido a ninguna pr\u00e1ctica que prive su libertad, quiere un amor genuino hacia Dios, lo viejo ha muerto, y volver la vista a tras no lleva a nada bueno, pues ser\u00eda en vano anunciar su mensaje salvador si a\u00fan se est\u00e1 bajo la ley que oprime, quiere revelar un Reino instituido e inaugurado para quienes desean entrar en comuni\u00f3n con \u00e9l, de esta manera la fe en Jes\u00fas se conserva y se hace s\u00f3lida.<\/li>\n\n\n\n<li>Jes\u00fas una vez m\u00e1s nos invita a estar alegres, esa es la verdadera caracter\u00edstica de un cristiano autentico, pues como vamos a estar tristes y preocupados si a\u00fan el novio est\u00e1 con nosotros, pero esto se logra mediante la esperanza que debemos conservar en cada uno de nuestros corazones, no debe haber ninguna clase de duelo mientras Jes\u00fas camina con nosotros.<\/li>\n\n\n\n<li>Mediante el bautismo morimos al hombre viejo, la vida nueva ha llegado a nosotros , es por esto que debemos estructurar nuestra persona en una obra de amor, de un amor que nos hace libres de aceptar uno a uno los llamamientos dulces y tiernos que Cristo nos hace, no podemos volver al pasado que nos separa de Jes\u00fas, no podemos mezclar el bien con \u00e9l mal, pues haremos de nuestra existencia un caos, si decidimos estar en la presencia de Jes\u00fas debemos conservar nuestra fe y esperanza en aquel que nos ofrece una nueva creaci\u00f3n que inaugur\u00f3 con su sacrificio de amor y que aun en la actualidad seguimos celebrando para bien de nuestra alma, el ayuno es en cierta manera una experiencia que nos motiva al autocontrol personal, y es sin duda alguna una herramienta eficaz para sacrificarnos, esto dar\u00e1 como resultado pulirnos en la fe, y ser cada d\u00eda agradables a nuestro padre Dios, pero nuestra espiritualidad no debe fundamentarse en lo externo sino trabajar en nuestro interior que permite reflejar lo que realmente somos y a si nuestro servicio hacia quienes nos rodean ser\u00e1 permanente y nuestro amor a Dios ser\u00e1 duradero.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Buscar el catecismo de la Iglesia cat\u00f3lica para cumplir el ayuno en los tiempos correspondientes estipulados por la iglesia, hacerlo de manera que me ayude acercarme a Dios como una experiencia que me motive a seguirlo amando y no como una pr\u00e1ctica externa por obligaci\u00f3n.<\/li>\n\n\n\n<li>San Adriano aprovech\u00f3 al m\u00e1ximo su vocaci\u00f3n de papa para ayudar a quien necesitaba, se desempe\u00f1o en el pontificado por poco tiempo pero logr\u00f3 hacer mucho, como este santo debemos aprovechar cada instante de nuestra vida para hacer el bien y dejar huella, sabiendo que la vida se nos puede ir en cualquier momento.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN ADRIANO III (+885) San Adriano en el a\u00f1o 884 fue nombrado papa de la iglesia en un lapso de tiempo muy corto, debido a que muri\u00f3 en M\u00f3dena (Italia) durante un viaje que realiz\u00f3 para encontrase con el emperador Carlos el Gordo para tratar algunos temas, decidi\u00f3 aceptar la invitaci\u00f3n pero &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2023\/07\/06\/sabado-decimotercera-semana-del-tiempo-ordinario-ciclo-a-08-julio-2023\/\"> <span class=\"screen-reader-text\">SABADO, decimotercera semana del tiempo ordinario (ciclo a) -08 julio, 2023<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":2469,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2468","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/07\/julio-8.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/07\/julio-8.jpg",640,427,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/07\/julio-8-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/07\/julio-8-300x200.jpg",300,200,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/07\/julio-8.jpg",640,427,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/07\/julio-8.jpg",640,427,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/07\/julio-8.jpg",640,427,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/07\/julio-8.jpg",640,427,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SAN ADRIANO III (+885) San Adriano en el a\u00f1o 884 fue nombrado papa de la iglesia en un lapso de tiempo muy corto, debido a que muri\u00f3 en M\u00f3dena (Italia) durante un viaje que realiz\u00f3 para encontrase con el emperador Carlos el Gordo para tratar algunos temas, decidi\u00f3 aceptar la invitaci\u00f3n pero&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=2468"}],"version-history":[{"count":1,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2468\/revisions"}],"predecessor-version":[{"id":2470,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2468\/revisions\/2470"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/2469"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=2468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=2468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=2468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}