{"id":2405,"date":"2023-06-23T09:30:00","date_gmt":"2023-06-23T14:30:00","guid":{"rendered":"https:\/\/devocionario.net\/?p=2405"},"modified":"2023-06-23T09:30:10","modified_gmt":"2023-06-23T14:30:10","slug":"lunes-duodecima-semana-del-tiempo-ordinario-ciclo-a-26-junio-2023","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2023\/06\/23\/lunes-duodecima-semana-del-tiempo-ordinario-ciclo-a-26-junio-2023\/","title":{"rendered":"LUNES, duod\u00e9cima semana del tiempo ordinario (ciclo a) -26 junio, 2023"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"534\" data-id=\"2408\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/26-JUNIO-1.jpg\" alt=\"\" class=\"wp-image-2408\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/26-JUNIO-1.jpg 800w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/26-JUNIO-1-300x200.jpg 300w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/26-JUNIO-1-768x513.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL DIA<\/em><\/strong><strong><em><\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\"><strong>&nbsp;SAN JOSEMARIA ESCRIVA DE BALAGUER&nbsp; (1902-1975)<\/strong><\/p>\n\n\n\n<p>San Josemar\u00eda Escriv\u00e1 de Balaguer naci\u00f3 en Espa\u00f1a, sus padres le dieron la mejor educaci\u00f3n cristiana junto con sus cinco hermanos. Una vez que su padre&nbsp; fracasara con su trabajo de tejidos, viaja a Logro\u00f1o donde despierta su vocaci\u00f3n y decide estudiar,&nbsp; y despu\u00e9s entra al seminario de Zaragoza para continuar sus estudios, por consejos de su padre inicia a estudiar tambi\u00e9n la carrera de derecho. En 1928 viaja a Madrid ya ordenado sacerdote crea la fundaci\u00f3n del Opus Dei, su misi\u00f3n exactamente basada en en el desarrollo espiritual de las personas, insisti\u00f3 en instituir su fundaci\u00f3n en otros pa\u00edses, muere en Roma.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Mateo 7,1-5<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, dijo Jes\u00fas a sus disc\u00edpulos:<\/p>\n\n\n\n<p>\u00abNo juzgu\u00e9is, para que no se\u00e1is juzgados. Porque ser\u00e9is juzgados como juzgu\u00e9is vosotros, y la medida que us\u00e9is, la usar\u00e1n con vosotros.<\/p>\n\n\n\n<p>\u00bfPor qu\u00e9 te fijas en la mota que tiene tu hermano en el ojo y no reparas en la viga que llevas en el tuyo?<\/p>\n\n\n\n<p>\u00bfC\u00f3mo puedes decirle a tu hermano: \u201cD\u00e9jame que te saque la mota del ojo\u201d, teniendo una viga en el tuyo? Hip\u00f3crita; s\u00e1cate primero la viga del ojo; entonces ver\u00e1s claro y podr\u00e1s sacar la mota del ojo de tu hermano\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Una vez m\u00e1s en el evangelio, las revelaciones del Reino de los cielos nos interpelan, Jes\u00fas aprovecha esta oportunidad para hablar de la verdadera justicia que proviene de Dios y nos ense\u00f1a que esta justicia no es despectiva, no denigra a quien ha fallado, pero sabe que la naturaleza del hombre encaminada al mal, tiende a juzgar al pr\u00f3jimo, haci\u00e9ndose juez de lo que no le compete, dej\u00e1ndose llevar por las apariencias y resaltando en el otro no las cualidades sino los defectos, sin percatarse que su vida puede estar en peores condiciones de pecado que a&nbsp; quien critica, en cada momento Jesucristo quiere hacer advertencias con su palabra, dando pautas para saber vivir con quienes se convive, esta vez da a entender que la mirada de las personas debe fijarse en corregir su propia conducta, para que sea un espejo visible para quienes quieran seguir su ejemplo.<\/li>\n\n\n\n<li>La misericordia que Dios ofrece a sus seguidores les permite ver el interior de cada hermano, sus miserias, y el porqu\u00e9 de sus acciones, quien ejerce la misericordia est\u00e1 sujeto a demostrar compasi\u00f3n, a comprender sin denigrar, a amar sin l\u00edmites, a entregarse al otro sin cuestionar, a medida que el acercamiento a los hermanos se haga m\u00e1s profunda, si a Jes\u00fas miramos a quien tengo al frente, no habr\u00e1 raz\u00f3n alguna para culpar sino para ayudar las peque\u00f1eces del otro, y si demostrando conversi\u00f3n en la propia vida se logra exhortar a los dem\u00e1s que lo sea con \u00fanico prop\u00f3sito, hacer volver a Dios a quien se ha perdido. &nbsp;<\/li>\n\n\n\n<li>Olvidamos constantemente que para salvarnos, es necesario tener una buena relaci\u00f3n con \u00e9l que est\u00e1 a mi lado, las imperfecciones que vemos en el otro nos fastidian y escandalizan, &nbsp;nos hacen hablar una y otra vez mal de ellos, nuestra forma de cuestionarle sus actitudes no es la correcta, pues ante los dem\u00e1s da\u00f1amos su imagen, Jes\u00fas nos pide no juzgar, pues tambi\u00e9n hay en nosotros pecados y quiz\u00e1s graves, debemos en lo posible ser prudentes, benignos con quienes no son de cierta manera de nuestro agrado. En la iglesia criticar es ya un h\u00e1bito muy frecuente, creemos que por estar todo el tiempo en el templo tenemos derecho a se\u00f1alar a quien se equivoca, y es lo contrario, cuanto m\u00e1s cercana sea nuestra relaci\u00f3n con Dios m\u00e1s humilde debe ser nuestra persona, mas clemente, \u00bfestamos ense\u00f1ados a creernos superiores, resaltando los peque\u00f1os pecados del otro y no corrigiendo mis grandes desobediencias hacia Dios? \u00bf c\u00f3mo el publicano en el templo reconozco mis flaquezas?.<\/li>\n\n\n\n<li>\u00bfEres misericordioso?\u00bf sabes c\u00f3mo se pr\u00e1ctica la misericordia?, pedimos en nuestras oraciones que Dios tenga piedad de nuestras culpas y no hemos entendido que si aplicamos la compasi\u00f3n primeramente con quien lo necesita nuestro Padre har\u00e1 lo mismo por nosotros.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>De ahora en adelante observar lo bueno y bonito de los dem\u00e1s, guardando silencio de sus defectos y pedir perd\u00f3n a Dios de mis juicios contra mis hermanos.<\/strong><strong><\/strong><\/li>\n\n\n\n<li><strong>&nbsp;San Josemar\u00eda&nbsp; Escriv\u00e1, transformo su vida ordinaria en algo extraordinario, su fundaci\u00f3n de Opus Dei fue el reflejo de su incesante b\u00fasqueda del desarrollo espiritual de sus hermanos y el suyo propio, nos ense\u00f1a que agradar a Dios es preocuparse por la salvaci\u00f3n del otro.<\/strong><strong><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL DIA &nbsp;SAN JOSEMARIA ESCRIVA DE BALAGUER&nbsp; (1902-1975) San Josemar\u00eda Escriv\u00e1 de Balaguer naci\u00f3 en Espa\u00f1a, sus padres le dieron la mejor educaci\u00f3n cristiana junto con sus cinco hermanos. Una vez que su padre&nbsp; fracasara con su trabajo de tejidos, viaja a Logro\u00f1o donde despierta su vocaci\u00f3n y decide estudiar,&nbsp; y despu\u00e9s entra al &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2023\/06\/23\/lunes-duodecima-semana-del-tiempo-ordinario-ciclo-a-26-junio-2023\/\"> <span class=\"screen-reader-text\">LUNES, duod\u00e9cima semana del tiempo ordinario (ciclo a) -26 junio, 2023<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":2407,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-2405","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tiempo-ordinario"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/26-JUNIO.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/26-JUNIO.jpg",800,534,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/26-JUNIO-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/26-JUNIO-300x200.jpg",300,200,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/26-JUNIO-768x513.jpg",768,513,true],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/26-JUNIO.jpg",800,534,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/26-JUNIO.jpg",800,534,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/26-JUNIO.jpg",800,534,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL DIA &nbsp;SAN JOSEMARIA ESCRIVA DE BALAGUER&nbsp; (1902-1975) San Josemar\u00eda Escriv\u00e1 de Balaguer naci\u00f3 en Espa\u00f1a, sus padres le dieron la mejor educaci\u00f3n cristiana junto con sus cinco hermanos. Una vez que su padre&nbsp; fracasara con su trabajo de tejidos, viaja a Logro\u00f1o donde despierta su vocaci\u00f3n y decide estudiar,&nbsp; y despu\u00e9s entra al&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=2405"}],"version-history":[{"count":1,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2405\/revisions"}],"predecessor-version":[{"id":2409,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2405\/revisions\/2409"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/2407"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=2405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=2405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=2405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}