{"id":2392,"date":"2023-06-14T16:56:00","date_gmt":"2023-06-14T21:56:00","guid":{"rendered":"https:\/\/devocionario.net\/?p=2392"},"modified":"2023-06-14T16:56:29","modified_gmt":"2023-06-14T21:56:29","slug":"jueves-undecima-semana-del-tiempo-ordinario-ciclo-a-22-junio-2023","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2023\/06\/14\/jueves-undecima-semana-del-tiempo-ordinario-ciclo-a-22-junio-2023\/","title":{"rendered":"JUEVES, und\u00e9cima semana del tiempo ordinario (ciclo a) -22 junio, 2023"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/22-junio.jpg\" alt=\"\" class=\"wp-image-2393\" width=\"583\" height=\"328\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/22-junio.jpg 412w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/22-junio-300x169.jpg 300w\" sizes=\"(max-width: 583px) 100vw, 583px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL DIA<\/em><\/strong><strong><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\"><strong>SAN PAULINO DE NOLA (353-431)<\/strong><\/p>\n\n\n\n<p>San Paulino de Nola fue un distinguido abogado del Imperio Romano, tuvo una buena educaci\u00f3n y estudi\u00f3 con los mejores maestros de su \u00e9poca debido a que su familia rica le permit\u00eda hacerlo, se cas\u00f3 con una joven llamada Teresa en Espa\u00f1a, con quien tuvo un hijo que muri\u00f3 a los pocos d\u00edas de nacido, por esta raz\u00f3n decidi\u00f3 junto con su esposa vender sus bienes y ponerlos al servicio de los pobres, se fueron a vivir al municipio de Nola, all\u00ed construyeron una casa para dedicarse a la oraci\u00f3n y ayuda de los m\u00e1s necesitados. Por sus buenas obras en aquella regi\u00f3n, la comunidad pidi\u00f3 al obispo de Barcelona de ordenar a Paulino como sacerdote, y a\u00f1os m\u00e1s tarde cuando falleci\u00f3&nbsp; el obispo de Nola el pueblo clam\u00f3 se ordenara a San Paulino como el nuevo obispo, fue un ministro ejemplar hasta su muerte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Mateo 6,7-15<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, dijo Jes\u00fas a sus disc\u00edpulos:<\/p>\n\n\n\n<p>\u00abCuando rec\u00e9is, no us\u00e9is muchas palabras, como los gentiles, que se imaginan que por hablar mucho les har\u00e1n caso. No se\u00e1is como ellos, pues vuestro Padre sabe lo que os hace falta antes de que lo pid\u00e1is. Vosotros orad as\u00ed:<\/p>\n\n\n\n<p>\u201cPadre nuestro que est\u00e1s en el cielo, santificado sea tu nombre, venga a nosotros tu reino, h\u00e1gase tu voluntad en la tierra como en el cielo, danos hoy nuestro pan de cada d\u00eda, perdona nuestras ofensas, como tambi\u00e9n nosotros perdonamos a los que nos han ofenden, no nos dejes caer en la tentaci\u00f3n, y l\u00edbranos del mal\u201d.<\/p>\n\n\n\n<p>Porque si perdon\u00e1is a los hombres sus ofensas, tambi\u00e9n os perdonar\u00e1 vuestro Padre celestial, pero si no perdon\u00e1is a los hombres, tampoco vuestro Padre perdonar\u00e1 vuestras ofensas\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Jesucristo revela a sus disc\u00edpulos una nueva forma de comunicarnos con Dios, y lo hace mediante una cr\u00edtica constructiva, que muestra el verdadero sentido de la oraci\u00f3n, nos es que Jes\u00fas estuviese en contra de rezar como lo hac\u00edan los jud\u00edos, sino que la manera como se hac\u00eda se desviaba del verdadero prop\u00f3sito, que es hablar con Dios cari\u00f1osamente sin palabras premeditadas, sino que expresando con espontaneidad lo que hay en el coraz\u00f3n sean escuchadas con agrado las peticiones y agradecimientos que elevamos a nuestro Padre Celestial.<\/li>\n\n\n\n<li>Jes\u00fas muestra un modelo para orar eficazmente, el Padre nuestro, este se convierte es una oraci\u00f3n integral que abarca en su totalidad todo lo que se quiere decir a Dios, &nbsp;muestra a Dios como &nbsp;un Padre de todos, un confidente, que escucha con atenci\u00f3n las peticiones de sus hijos, manifestando &nbsp;un Dios m\u00e1s cercano a la necesidad del hombre.<\/li>\n\n\n\n<li>Nuestra oraci\u00f3n es mec\u00e1nica en muchos momentos, al iniciar lo primero que hacemos es expresar nuestra lista de peticiones, nos dirigimos a Dios como si \u00e9l necesitar\u00e1 de nosotros, como s\u00ed Dios tuviera la obligaci\u00f3n de concedernos todo cuanto queramos y no solo eso nos basta, sino que decimos a Dios como hacerlo, adem\u00e1s imploramos a Dios se perdonen nuestros pecados, sin darnos cuenta que primero debemos perdonar para obtener el perd\u00f3n de aquel que es todo amor.<\/li>\n\n\n\n<li>Jes\u00fas nos pide hablarle a Dios sinceramente como a nuestro padre, sabiendo que conoce todo de nosotros, nuestras angustias, necesidades y hasta agradecimientos, pues&nbsp; nos cre\u00f3, &nbsp;solo anhela que nuestra comunicaci\u00f3n con \u00e9l sea \u00edntima, necesaria y constante, sabiendo que la acci\u00f3n que se enfoca se potencializa, este buena pr\u00e1ctica de la oraci\u00f3n, debemos hacerla nuestro pan diario, pues nos permite escuchar su voz en nuestro interior dando respuesta a lo que pedimos.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Orar en todo tiempo en especial en los momentos que sintamos la necesidad de hablar con Dios, de contarle nuestros afanes del d\u00eda a d\u00eda, tratar en lo posible que esta oraci\u00f3n sea siempre honesta, Ense\u00f1ar el Padre Nuestro a los m\u00e1s inocentes a quienes no saben orar, al rezar esta hermosa oraci\u00f3n del Cristiano meditemos profundamente como Jes\u00fas quiere que sea nuestra oraci\u00f3n dirigida a Dios. <\/strong><strong><\/strong><\/li>\n\n\n\n<li><strong>San Paulino dedicado a la oraci\u00f3n y a la limosna en la comunidad de Nola, nos motiva a seguir su ejemplo, pues con esta hermos\u00edsima pr\u00e1ctica piadosa ser\u00e1 casi imposible separarnos de Dios.<\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL DIA SAN PAULINO DE NOLA (353-431) San Paulino de Nola fue un distinguido abogado del Imperio Romano, tuvo una buena educaci\u00f3n y estudi\u00f3 con los mejores maestros de su \u00e9poca debido a que su familia rica le permit\u00eda hacerlo, se cas\u00f3 con una joven llamada Teresa en Espa\u00f1a, con quien tuvo un hijo &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2023\/06\/14\/jueves-undecima-semana-del-tiempo-ordinario-ciclo-a-22-junio-2023\/\"> <span class=\"screen-reader-text\">JUEVES, und\u00e9cima semana del tiempo ordinario (ciclo a) -22 junio, 2023<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":2393,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/22-junio.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/22-junio.jpg",412,232,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/22-junio-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/22-junio-300x169.jpg",300,169,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/22-junio.jpg",412,232,false],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/22-junio.jpg",412,232,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/22-junio.jpg",412,232,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/22-junio.jpg",412,232,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL DIA SAN PAULINO DE NOLA (353-431) San Paulino de Nola fue un distinguido abogado del Imperio Romano, tuvo una buena educaci\u00f3n y estudi\u00f3 con los mejores maestros de su \u00e9poca debido a que su familia rica le permit\u00eda hacerlo, se cas\u00f3 con una joven llamada Teresa en Espa\u00f1a, con quien tuvo un hijo&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=2392"}],"version-history":[{"count":1,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2392\/revisions"}],"predecessor-version":[{"id":2394,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2392\/revisions\/2394"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/2393"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=2392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=2392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=2392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}