{"id":2382,"date":"2023-06-14T16:51:00","date_gmt":"2023-06-14T21:51:00","guid":{"rendered":"https:\/\/devocionario.net\/?p=2382"},"modified":"2023-06-14T16:51:26","modified_gmt":"2023-06-14T21:51:26","slug":"lunes-undecima-semana-del-tiempo-ordinario-ciclo-a-19-junio-2023","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2023\/06\/14\/lunes-undecima-semana-del-tiempo-ordinario-ciclo-a-19-junio-2023\/","title":{"rendered":"LUNES, und\u00e9cima semana del tiempo ordinario (ciclo a) -19 junio, 2023"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/19-junio-1024x512.jpg\" alt=\"\" class=\"wp-image-2383\" width=\"773\" height=\"387\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/19-junio-1024x512.jpg 1024w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/19-junio-300x150.jpg 300w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/19-junio-768x384.jpg 768w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/19-junio.jpg 1120w\" sizes=\"(max-width: 773px) 100vw, 773px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\"><strong>SAN ROMUALDO, ABAD (950-1027)<\/strong><\/p>\n\n\n\n<p class=\"has-black-color has-text-color\">San Romualdo fue hijo de unos duques, creci\u00f3 en las pasiones desordenadas de este mundo y cometi\u00f3 muchas faltas en contra de Dios, pero una voz en su interior lo interpelaba indic\u00e1ndole alejarse de esta vida mundana. Un d\u00eda su padre que era bastante vengativo le llevo fuera para que fuera testigo de un pleito que tendr\u00eda con un adversario, esta situaci\u00f3n termino en muerte, de ah\u00ed que San Romualdo decidi\u00f3 huir de aquel lugar y acoger la vida religiosa, ingreso a un&nbsp; &nbsp;monasterio de benedictinos para dedicarse a la oraci\u00f3n y penitencia, pero teniendo conflictos con los monjes se retir\u00f3 a una monta\u00f1a como ermita\u00f1o, en vida fund\u00f3 conventos, para que muchos pecadores acogieran la fe y se convirtieran a Dios, fund\u00f3 a\u00f1os despu\u00e9s una comunidad que anhelaba con su coraz\u00f3n y tomo el nombre de Camaldulenses, m\u00e1s tarde encerrado y dedic\u00e1ndose a lo que lo har\u00eda santo muri\u00f3 en la paz de Cristo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Mateo 5, 38-42<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, dijo Jes\u00fas a sus disc\u00edpulos:<br>\u00abHab\u00e9is o\u00eddo que se dijo: \u201cOjo por ojo, diente por diente\u201d. Pero os digo: no hag\u00e1is frente al que os agravia. Al contrario, si uno te abofetea en la mejilla derecha, pres\u00e9ntale la otra; al que quiera ponerte pleito para quitarte la t\u00fanica, dale tambi\u00e9n el manto; a quien te requiera para caminar una milla, acomp\u00e1\u00f1ale dos; a quien te pide, dale, y al que te pide prestado, no lo reh\u00fayas\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Jes\u00fas no anula la ley de Dios, s\u00f3lo quiere que entendamos cual es el verdadero significado de cumplir los mandamientos, ense\u00f1\u00e1ndonos que la venganza no es el mejor camino para sentirnos mejor y satisfacer nuestra sed de justicia, que el&nbsp; hecho de devolver mal por mal no es un acto de amor que nos har\u00e1 mejores personas, que aunque ofendidos siempre debemos acceder a lo que nos hiere, solo por la iniciativa de amar, pues \u00e9l se someti\u00f3 al sufrimiento por nosotros por una \u00fanica raz\u00f3n, porque nos ama.<\/li>\n\n\n\n<li>&nbsp;Jesucristo nos abre a nuevas posibilidades para pensar distinto, record\u00e1ndonos que no somos perfectos, si las &nbsp;injurias de los dem\u00e1s nos afectan, debemos ser buenos hijos de Dios independientemente de lo que eso nos cueste, nos motiva a practicar la misericordia (la miseria del coraz\u00f3n) con \u00e9l que se equivoca, \u00bfy porque no?, si \u00e9l siendo Dios padeci\u00f3 todo por nosotros, \u201cporque Cristo no busco lo que le agrada, como dice la Escritura: las ofensas de los que te insultaban cayeron sobre mi\u201d Romanos 15,3.<\/li>\n\n\n\n<li>El amor hacia nuestros hermanos es la cualidad de todo cristiano, quien conoce a Dios sabe que es amor, \u00bfqui\u00e9nes somos nosotros para juzgar a quien ha fallado?, sabemos que la palabra de Dios nos recuerda una y otra vez que debemos perdonar siempre, sea cu\u00e1l sea la situaci\u00f3n, pues es este el cumplimiento del verdadero y \u00fanico mandamiento del amor.<\/li>\n\n\n\n<li>Resistir es la clave y el \u00e9xito de nuestro paso por este mundo, comprender las debilidades del otro me hace fuerte en mi fe, conocer a fondo a quienes nos rodea nos facilita aceptar sus defectos y que acepten los nuestros. Cuando una persona atenta contra mi integridad, causarle da\u00f1o no es lo correcto, nos lo que Dios nos dice que hagamos, al contrario es analizar detenidamente su accionar para poder llegar a la ra\u00edz del problema, con el \u00fanico fin de ayudar a quien se ha perdido, levantar a quien ha ca\u00eddo, y aceptarlo en mi vida como a un hermano en Cristo Jes\u00fas.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Perdonar a quien me ha causado da\u00f1o, buscando la manera de hacerle un bien en todo momento y aprender a comprender a&nbsp; quien se equivoca, esta es la identidad de todo cristiano.<\/strong><strong><\/strong><\/li>\n\n\n\n<li><strong>San Romualdo huyo de la venganza que su padre practicaba, y de los placeres que el mundo le ofrec\u00eda, nos ense\u00f1a a dedicarnos a la oraci\u00f3n y penitencia para vencer las tentaciones y ayudar a los pecadores a convertirse a Cristo. <\/strong><strong><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN ROMUALDO, ABAD (950-1027) San Romualdo fue hijo de unos duques, creci\u00f3 en las pasiones desordenadas de este mundo y cometi\u00f3 muchas faltas en contra de Dios, pero una voz en su interior lo interpelaba indic\u00e1ndole alejarse de esta vida mundana. Un d\u00eda su padre que era bastante vengativo le llevo fuera &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2023\/06\/14\/lunes-undecima-semana-del-tiempo-ordinario-ciclo-a-19-junio-2023\/\"> <span class=\"screen-reader-text\">LUNES, und\u00e9cima semana del tiempo ordinario (ciclo a) -19 junio, 2023<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":2383,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2382","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/19-junio.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/19-junio.jpg",1120,560,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/19-junio-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/19-junio-300x150.jpg",300,150,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/19-junio-768x384.jpg",768,384,true],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/19-junio-1024x512.jpg",1024,512,true],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/19-junio.jpg",1120,560,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/19-junio.jpg",1120,560,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"SANTO DEL D\u00cdA SAN ROMUALDO, ABAD (950-1027) San Romualdo fue hijo de unos duques, creci\u00f3 en las pasiones desordenadas de este mundo y cometi\u00f3 muchas faltas en contra de Dios, pero una voz en su interior lo interpelaba indic\u00e1ndole alejarse de esta vida mundana. Un d\u00eda su padre que era bastante vengativo le llevo fuera&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=2382"}],"version-history":[{"count":2,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2382\/revisions"}],"predecessor-version":[{"id":2385,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2382\/revisions\/2385"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/2383"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=2382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=2382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=2382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}