{"id":2357,"date":"2023-06-07T07:02:00","date_gmt":"2023-06-07T12:02:00","guid":{"rendered":"https:\/\/devocionario.net\/?p=2357"},"modified":"2023-06-07T07:02:05","modified_gmt":"2023-06-07T12:02:05","slug":"lunes-decima-semana-del-tiempo-ordinario-ciclo-a-12-junio-2023","status":"publish","type":"post","link":"https:\/\/devocionario.net\/index.php\/2023\/06\/07\/lunes-decima-semana-del-tiempo-ordinario-ciclo-a-12-junio-2023\/","title":{"rendered":"LUNES, d\u00e9cima semana del tiempo ordinario (ciclo a) -12 junio, 2023"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"867\" height=\"577\" src=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/12-junio.jpg\" alt=\"\" class=\"wp-image-2358\" srcset=\"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/12-junio.jpg 867w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/12-junio-300x200.jpg 300w, https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/12-junio-768x511.jpg 768w\" sizes=\"(max-width: 867px) 100vw, 867px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><em>SANTO DEL D\u00cdA<\/em><\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\"><strong>SAN ONOFRE (320-400)<\/strong><\/p>\n\n\n\n<p>San Onofre naci\u00f3 en una familia pudiente, pero al conocer la pobreza lejos del Palacio,&nbsp; en ese mismo instante se convierte a la vida religiosa, se ordena como monje del convento de Abage convivi\u00f3 con 100 monjes, pero su necesidad de tener una experiencia m\u00e1s \u00edntima con Dios decidi\u00f3 irse a vivir al desierto egipcio de Tebaida como ermita\u00f1o cuando ten\u00eda la mayor\u00eda de edad, para estar en constante oraci\u00f3n y alejarse de la vida mundana, mientras se encontraba en la soledad, su \u00e1ngel de la guarda le proporcionaba pan y vino los Domingos, sabiendo que su sufrimiento seria recompensado se mantuvo as\u00ed hasta el d\u00eda de su muerte, seg\u00fan cuenta la tradici\u00f3n San Onofre al morir un coro ang\u00e9lico se escuche en aquella regi\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Evangelio del d\u00eda<\/strong><\/h3>\n\n\n\n<p><strong>San Mateo 5,1-12<\/strong><\/p>\n\n\n\n<p>En aquel tiempo, al ver Jes\u00fas el gent\u00edo, subi\u00f3 al monte, se sent\u00f3, y se acercaron sus disc\u00edpulos; y, abriendo su boca les ense\u00f1aba diciendo:<br>\u00abBienaventurados los pobres de esp\u00edritu, porque de ellos es el Reino de los Cielos.<br>Bienaventurados los mansos, porque ellos heredar\u00e1n la tierra.<br>Bienaventurados los que lloran, porque ellos ser\u00e1n consolados.<br>Bienaventurados los que tienen hambre y sed de la justicia, porque ellos ser\u00e1n saciados.<br>Bienaventurados los misericordiosos, porque ellos alcanzar\u00e1n misericordia.<br>Bienaventurados los limpios de coraz\u00f3n, porque ellos ver\u00e1n a Dios.<br>Bienaventurados los que trabajan por la paz, porque ellos ser\u00e1n llamados hijos de Dios.<br>Bienaventurados los perseguidos por causa de la justicia, porque de ellos es el Reino de los Cielos.<br>Bienaventurados vosotros cuando os insulten y os persigan y os calumnien de cualquier modo por mi causa. Alegraos y regocijaos, porque vuestra recompensa ser\u00e1 grande en el cielo, que de la misma manera persiguieron a los profetas anteriores a vosotros\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palabra del Se\u00f1or<\/strong><\/h3>\n\n\n\n<p><strong>MEDITACI\u00d3N<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Jes\u00fas sube a la monta\u00f1a para anunciar las bienaventuranzas a sus disc\u00edpulos y las gentes, escoge precisamente este lugar porque es el encuentro con Dios es la manifestaci\u00f3n de Dios con \u00e9l hombre, all\u00ed comienza a ense\u00f1ar la clave de la verdadera felicidad, nos dice que cada sufrimiento en esta vida es una bendici\u00f3n cada dificultad es una oportunidad para salvarnos.<\/li>\n\n\n\n<li>Jes\u00fas comprende a quien&nbsp; decide seguirlo, es por eso que sus palabras son motivadoras, tienen esperanza, que aunque las pruebas de esta vida debilitan mi fe, todas estar\u00e1n encaminadas a la santidad siempre y cuando las sobrellevemos junto a \u00e9l.<\/li>\n\n\n\n<li>Jesucristo nos recuerda una y otra vez que sufrir haciendo el bien tendr\u00e1 su recompensa, las bienaventuranzas vendr\u00edan siendo promesas que debemos ansiar para cumplir la voluntad de Dios, el mismo Cristo nos muestra el camino que debemos seguir, nos anima a seguir sin desfallecer siempre con la mirada puesta en la eternidad.<\/li>\n\n\n\n<li>Las bienaventuranzas reconfortan nuestra esperanza sabiendo que cada lucha en esta tierra no es vano, es ah\u00ed donde cada dificultad, enfermedad, angustia, tristeza\u2026etc cobra valor.<\/li>\n\n\n\n<li>\u00bfResuena la voz de Dios en nuestro interior con sus palabras, nos dejamos abrazar por su amor para buscar la felicidad que \u00e9l solo nos ofrece en la otra vida? \u00bfescuchamos su llamado?.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>PR\u00c1CTICA DIARIA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>De hoy en adelante toda dificultad que se presente en mi vida har\u00e9 que sea una oportunidad para crecer espiritualmente y reconfortar mi fe, sabi\u00e9ndola llevar con amor y paciencia de manera que tenga presente las promesas de las bienaventuranzas que Dios me regala como recompensa a mis sufrimientos en esta vida.<\/strong><strong><\/strong><\/li>\n\n\n\n<li><strong>San Onofre nos invita a seguir a Cristo dejando este mundo materialista y dejar que nuestra vida&nbsp; busque una experiencia \u00edntima con Dios.<\/strong><strong><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DEL D\u00cdA SAN ONOFRE (320-400) San Onofre naci\u00f3 en una familia pudiente, pero al conocer la pobreza lejos del Palacio,&nbsp; en ese mismo instante se convierte a la vida religiosa, se ordena como monje del convento de Abage convivi\u00f3 con 100 monjes, pero su necesidad de tener una experiencia m\u00e1s \u00edntima con Dios decidi\u00f3 &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/devocionario.net\/index.php\/2023\/06\/07\/lunes-decima-semana-del-tiempo-ordinario-ciclo-a-12-junio-2023\/\"> <span class=\"screen-reader-text\">LUNES, d\u00e9cima semana del tiempo ordinario (ciclo a) -12 junio, 2023<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":2358,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2357","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_featured_media_url":"https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/12-junio.jpg","uagb_featured_image_src":{"full":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/12-junio.jpg",867,577,false],"thumbnail":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/12-junio-150x150.jpg",150,150,true],"medium":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/12-junio-300x200.jpg",300,200,true],"medium_large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/12-junio-768x511.jpg",768,511,true],"large":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/12-junio.jpg",867,577,false],"1536x1536":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/12-junio.jpg",867,577,false],"2048x2048":["https:\/\/devocionario.net\/wp-content\/uploads\/2023\/05\/12-junio.jpg",867,577,false]},"uagb_author_info":{"display_name":"PEREGRINOS DE LA ESPERANZA","author_link":"https:\/\/devocionario.net\/author\/ancarosa31gmail-com\/"},"uagb_comment_info":2,"uagb_excerpt":"SANTO DEL D\u00cdA SAN ONOFRE (320-400) San Onofre naci\u00f3 en una familia pudiente, pero al conocer la pobreza lejos del Palacio,&nbsp; en ese mismo instante se convierte a la vida religiosa, se ordena como monje del convento de Abage convivi\u00f3 con 100 monjes, pero su necesidad de tener una experiencia m\u00e1s \u00edntima con Dios decidi\u00f3&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/comments?post=2357"}],"version-history":[{"count":1,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2357\/revisions"}],"predecessor-version":[{"id":2359,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts\/2357\/revisions\/2359"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media\/2358"}],"wp:attachment":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/media?parent=2357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories?post=2357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/tags?post=2357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}