{"id":32,"count":1,"description":"","link":"https:\/\/devocionario.net\/index.php\/category\/vigilia-pentecostes\/","name":"Vigilia Pentecost\u00e9s","slug":"vigilia-pentecostes","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories\/32","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/devocionario.net\/index.php\/wp-json\/wp\/v2\/posts?categories=32"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}